{"id":173580,"date":"2025-11-16T16:46:15","date_gmt":"2025-11-16T16:46:15","guid":{"rendered":"https:\/\/arongroups.co\/?p=173580"},"modified":"2026-06-29T15:10:31","modified_gmt":"2026-06-29T15:10:31","slug":"hyperinflation","status":"publish","type":"post","link":"https:\/\/newwp.aronsos.co\/fa\/forex-articles\/hyperinflation\/","title":{"rendered":"\u0686\u06af\u0648\u0646\u0647 \u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u0627\u0642\u062a\u0635\u0627\u062f \u0648 \u0633\u0631\u0645\u0627\u06cc\u0647 \u0627\u0641\u0631\u0627\u062f \u0631\u0627 \u062a\u062d\u062a \u062a\u0623\u062b\u06cc\u0631 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u062f\u0647\u062f\u061f"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"173580\" class=\"elementor elementor-173580\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb8a038 e-flex e-con-boxed e-con e-parent\" data-id=\"eb8a038\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bb9468f elementor-widget elementor-widget-text-editor\" data-id=\"bb9468f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">\u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u062e\u0631\u0628\u200c\u062a\u0631\u06cc\u0646 \u067e\u062f\u06cc\u062f\u0647\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u06cc\u06a9 \u06a9\u0634\u0648\u0631 \u0631\u0627 \u0628\u0647 \u0628\u062d\u0631\u0627\u0646 \u0639\u0645\u06cc\u0642 \u0628\u06a9\u0634\u0627\u0646\u062f \u0648 \u0632\u0646\u062f\u06af\u06cc \u0634\u0647\u0631\u0648\u0646\u062f\u0627\u0646 \u0631\u0627 \u062f\u06af\u0631\u06af\u0648\u0646 \u06a9\u0646\u062f. \u0627\u06cc\u0646 \u067e\u062f\u06cc\u062f\u0647 \u0646\u0647 \u062a\u0646\u0647\u0627 \u0627\u0642\u062a\u0635\u0627\u062f \u0645\u0644\u06cc \u0631\u0627 \u062a\u0636\u0639\u06cc\u0641 \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u0628\u0644\u06a9\u0647 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u0647\u0627\u06cc \u0641\u0631\u062f\u06cc \u0631\u0627 \u0646\u06cc\u0632 \u0646\u0627\u0628\u0648\u062f \u0645\u06cc\u200c\u0633\u0627\u0632\u062f. \u062f\u0631\u06a9 \u0639\u0645\u06cc\u0642 \u0627\u06cc\u0646 \u067e\u062f\u06cc\u062f\u0647 \u0648 \u0631\u0627\u0647\u200c\u0647\u0627\u06cc \u0645\u0642\u0627\u0628\u0644\u0647 \u0628\u0627 \u0622\u0646\u060c \u0628\u0631\u0627\u06cc \u0647\u0631 \u0641\u0631\u062f\u06cc \u06a9\u0647 \u0628\u0647 \u0622\u06cc\u0646\u062f\u0647 \u0645\u0627\u0644\u06cc \u062e\u0648\u062f \u0648 \u06a9\u0634\u0648\u0631\u0634 \u0627\u0647\u0645\u06cc\u062a \u0645\u06cc\u200c\u062f\u0647\u062f\u060c \u0636\u0631\u0648\u0631\u06cc \u0627\u0633\u062a. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0628\u0647 \u0628\u0631\u0631\u0633\u06cc \u062c\u0627\u0645\u0639 \u0627\u0628\u0631\u062a\u0648\u0631\u0645\u060c \u062f\u0644\u0627\u06cc\u0644 \u0628\u0631\u0648\u0632 \u0622\u0646\u060c \u067e\u06cc\u0627\u0645\u062f\u0647\u0627\u06cc \u0645\u062e\u0631\u0628 \u0648 \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u0645\u0642\u0627\u0628\u0644\u0647 \u0628\u0627 \u0627\u06cc\u0646 \u067e\u062f\u06cc\u062f\u0647 \u062e\u0648\u0627\u0647\u06cc\u0645 \u067e\u0631\u062f\u0627\u062e\u062a.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ccf33ad elementor-widget elementor-widget-text-editor\" data-id=\"ccf33ad\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><b>\u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u0686\u06cc\u0633\u062a\u061f<\/b><\/h2>\n<span style=\"font-weight: 400;\">\u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u0628\u0647 \u0648\u0636\u0639\u06cc\u062a \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u06af\u0641\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u062f\u0631 \u0622\u0646 \u0646\u0631\u062e \u062a\u0648\u0631\u0645 \u0628\u0647 \u0634\u062f\u062a \u0627\u0641\u0632\u0627\u06cc\u0634 \u06cc\u0627\u0641\u062a\u0647 \u0648 \u062e\u0627\u0631\u062c \u0627\u0632 \u06a9\u0646\u062a\u0631\u0644 \u0642\u0631\u0627\u0631 \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f. \u0628\u0631 \u0627\u0633\u0627\u0633 \u062a\u0639\u0631\u06cc\u0641 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0627\u0642\u062a\u0635\u0627\u062f\u06cc\u060c \u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u0632\u0645\u0627\u0646\u06cc \u0631\u062e \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 \u0646\u0631\u062e \u062a\u0648\u0631\u0645 \u0645\u0627\u0647\u0627\u0646\u0647 \u0628\u0647 \u0628\u06cc\u0634 \u0627\u0632 \u06f5\u06f0 \u062f\u0631\u0635\u062f \u0628\u0631\u0633\u062f \u06a9\u0647 \u0645\u0639\u0627\u062f\u0644 \u062a\u0648\u0631\u0645 \u0633\u0627\u0644\u0627\u0646\u0647 \u062d\u062f\u0648\u062f \u06f1\u06f2,\u06f8\u06f7\u06f5 \u062f\u0631\u0635\u062f \u0627\u0633\u062a. \u062f\u0631 \u0686\u0646\u06cc\u0646 \u0634\u0631\u0627\u06cc\u0637\u06cc\u060c \u0627\u0631\u0632\u0634 \u067e\u0648\u0644 \u0645\u0644\u06cc \u0628\u0647 \u0633\u0631\u0639\u062a \u06a9\u0627\u0647\u0634 \u06cc\u0627\u0641\u062a\u0647 \u0648 \u0642\u062f\u0631\u062a \u062e\u0631\u06cc\u062f \u0645\u0631\u062f\u0645 \u0628\u0647 \u0634\u062f\u062a \u062a\u0636\u0639\u06cc\u0641 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/span>\n\n<span style=\"font-weight: 400;\">\u0628\u0631 \u0627\u0633\u0627\u0633 \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u062c\u0627\u0645\u0639 <\/span><a style=\"color: #f9c43e;\"href=\"https:\/\/en.wikipedia.org\/wiki\/Hyperinflation\" target=\"_blank\" rel=\"nofollow noopener\"><span style=\"font-weight: 400;\">wikipedia<\/span><\/a><span style=\"font-weight: 400;\">\u060c \u062f\u0631 \u0634\u0631\u0627\u06cc\u0637 \u0627\u0628\u0631\u062a\u0648\u0631\u0645\u060c \u0645\u0631\u062f\u0645 \u062a\u0644\u0627\u0634 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u062a\u0627 \u062d\u062f\u0627\u0642\u0644 \u067e\u0648\u0644 \u0645\u0644\u06cc \u0645\u0645\u06a9\u0646 \u0631\u0627 \u0646\u06af\u0647 \u062f\u0627\u0631\u0646\u062f \u0648 \u0628\u0647 \u0633\u0645\u062a \u0627\u0631\u0632\u0647\u0627\u06cc \u062e\u0627\u0631\u062c\u06cc \u067e\u0627\u06cc\u062f\u0627\u0631\u062a\u0631 \u06cc\u0627 \u062f\u0627\u0631\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc \u0648\u0627\u0642\u0639\u06cc \u0645\u0627\u0646\u0646\u062f \u0637\u0644\u0627 \u0631\u0648\u06cc \u0645\u06cc\u200c\u0622\u0648\u0631\u0646\u062f. \u0627\u06cc\u0646 \u067e\u062f\u06cc\u062f\u0647 \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u0633\u0631\u0639\u062a \u06af\u0631\u062f\u0634 \u067e\u0648\u0644 \u062f\u0631 \u0627\u0642\u062a\u0635\u0627\u062f \u0628\u0647 \u0634\u062f\u062a \u0627\u0641\u0632\u0627\u06cc\u0634 \u06cc\u0627\u0628\u062f \u0648 \u0686\u0631\u062e\u0647 \u0645\u0639\u06cc\u0648\u0628\u06cc \u0627\u0632 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0648 \u06a9\u0627\u0647\u0634 \u0627\u0631\u0632\u0634 \u067e\u0648\u0644 \u0634\u06a9\u0644 \u06af\u06cc\u0631\u062f.<\/span>\n<h2><b>\u0686\u0647 \u0632\u0645\u0627\u0646\u06cc \u062a\u0648\u0631\u0645 \u0628\u0647 \u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u062a\u0628\u062f\u06cc\u0644 \u0645\u06cc\u200c\u0634\u0648\u062f\u061f<\/b><\/h2>\n<a style=\"color: #f9c43e;\"href=\"https:\/\/arongroups.co\/fa\/forex\/inflation-and-inflation-indices\/\"><span style=\"font-weight: 400;\">\u062a\u0648\u0631\u0645<\/span><\/a><span style=\"font-weight: 400;\"> \u0632\u0645\u0627\u0646\u06cc \u0628\u0647 \u00ab\u0627\u0628\u0631\u062a\u0648\u0631\u0645\u00bb \u062a\u063a\u06cc\u06cc\u0631 \u0648\u0636\u0639\u06cc\u062a \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 \u0633\u0631\u0639\u062a \u0631\u0634\u062f \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0622\u0646\u0642\u062f\u0631 \u0632\u06cc\u0627\u062f \u0634\u0648\u062f \u06a9\u0647 \u0627\u0631\u0632\u0634 \u067e\u0648\u0644 \u0645\u0644\u06cc \u0633\u0642\u0648\u0637 \u06a9\u0646\u062f.<\/span>\n\n<span style=\"font-weight: 400;\">\u0628\u0631 \u0627\u0633\u0627\u0633 \u062a\u0639\u0631\u06cc\u0641 \u0645\u0634\u0647\u0648\u0631 \u0641\u06cc\u0644\u06cc\u067e \u06a9\u0627\u06af\u0627\u0646 (\u0627\u0642\u062a\u0635\u0627\u062f\u062f\u0627\u0646)\u060c \u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u0627\u0632 \u0632\u0645\u0627\u0646\u06cc \u0622\u063a\u0627\u0632 \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u0646\u0631\u062e \u062a\u0648\u0631\u0645 \u0645\u0627\u0647\u0627\u0646\u0647 \u0627\u0632 \u06f5\u06f0 \u062f\u0631\u0635\u062f \u0641\u0631\u0627\u062a\u0631 \u0631\u0648\u062f \u0648 \u0632\u0645\u0627\u0646\u06cc \u062e\u0627\u062a\u0645\u0647 \u0645\u06cc\u200c\u06cc\u0627\u0628\u062f \u06a9\u0647 \u0627\u06cc\u0646 \u0646\u0631\u062e \u0628\u0647 \u0632\u06cc\u0631 \u06f5\u06f0 \u062f\u0631\u0635\u062f \u0628\u0627\u0632\u06af\u0634\u062a\u0647 \u0648 \u062f\u0633\u062a \u06a9\u0645 \u0628\u0631\u0627\u06cc \u06cc\u06a9 \u0633\u0627\u0644 \u062f\u0631 \u0647\u0645\u0627\u0646 \u0633\u0637\u062d \u0628\u0627\u0642\u06cc \u0628\u0645\u0627\u0646\u062f.<\/span>\n\n<span style=\"font-weight: 400;\">\u0647\u06cc\u0626\u062a \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u062d\u0633\u0627\u0628\u062f\u0627\u0631\u06cc \u0646\u06cc\u0632\u00a0 \u062f\u0631 <\/span><a style=\"color: #f9c43e;\"href=\"https:\/\/www.ifrs.org\/issued-standards\/list-of-standards\/ias-29-financial-reporting-in-hyperinflationary-economies\/\" target=\"_blank\" rel=\"nofollow noopener\"><span style=\"font-weight: 400;\">IAS 29 \u2013 Financial Reporting in Hyperinflationary Economies, IFRS Foundation<\/span><\/a><span style=\"font-weight: 400;\"> \u0646\u0634\u0627\u0646\u0647\u200c\u0647\u0627\u06cc\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u0645\u062d\u06cc\u0637 \u0627\u0628\u0631\u062a\u0648\u0631\u0645\u06cc \u062a\u0639\u06cc\u06cc\u0646 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a:<\/span>\n<ul>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u06af\u0631\u06cc\u0632 \u0627\u0632 \u067e\u0648\u0644 \u0645\u0644\u06cc:<\/b><span style=\"font-weight: 400;\"> \u0639\u0645\u0648\u0645 \u0645\u0631\u062f\u0645 \u062a\u0631\u062c\u06cc\u062d \u0645\u06cc\u200c\u062f\u0647\u0646\u062f \u062b\u0631\u0648\u062a \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u0634\u06a9\u0644 \u062f\u0627\u0631\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc \u063a\u06cc\u0631\u067e\u0648\u0644\u06cc \u06cc\u0627 \u0627\u0631\u0632\u0647\u0627\u06cc \u062e\u0627\u0631\u062c\u06cc \u0645\u0639\u062a\u0628\u0631 \u0646\u06af\u0647 \u062f\u0627\u0631\u0646\u062f \u0648 \u0628\u0631\u0627\u06cc \u062d\u0641\u0638 \u0642\u062f\u0631\u062a \u062e\u0631\u06cc\u062f\u060c \u0628\u0647 \u0633\u0631\u0639\u062a \u067e\u0648\u0644 \u0646\u0642\u062f \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u062f\u0627\u0631\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc \u062f\u06cc\u06af\u0631 \u062a\u0628\u062f\u06cc\u0644 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f.<\/span><\/li>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u0645\u0628\u0646\u0627 \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0646 \u0627\u0631\u0632 \u062e\u0627\u0631\u062c\u06cc:<\/b><span style=\"font-weight: 400;\"> \u0645\u0631\u062f\u0645 \u0627\u0631\u0632\u0634 \u06a9\u0627\u0644\u0627\u0647\u0627 \u0648 \u062e\u062f\u0645\u0627\u062a \u0631\u0627 \u0628\u0627 \u06cc\u06a9 \u0627\u0631\u0632 \u067e\u0627\u06cc\u062f\u0627\u0631 \u062e\u0627\u0631\u062c\u06cc \u0645\u06cc\u200c\u0633\u0646\u062c\u0646\u062f \u0648 \u062d\u062a\u06cc \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0645\u0633\u062a\u0642\u06cc\u0645\u0627 \u0628\u0627 \u0647\u0645\u0627\u0646 \u0627\u0631\u0632 \u0628\u06cc\u0627\u0646 \u0634\u0648\u0646\u062f.<\/span><\/li>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u0642\u06cc\u0645\u062a\u200c\u06af\u0630\u0627\u0631\u06cc \u062c\u0628\u0631\u0627\u0646\u06cc \u062f\u0631 \u0645\u0639\u0627\u0645\u0644\u0627\u062a \u0627\u0639\u062a\u0628\u0627\u0631\u06cc:<\/b><span style=\"font-weight: 400;\"> \u062f\u0631 \u0645\u0639\u0627\u0645\u0644\u0627\u062a \u0627\u0639\u062a\u0628\u0627\u0631\u06cc\u060c \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0628\u0647 \u06af\u0648\u0646\u0647\u200c\u0627\u06cc \u062a\u0639\u06cc\u06cc\u0646 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f \u06a9\u0647 \u06a9\u0627\u0647\u0634 \u0634\u062f\u06cc\u062f \u0627\u0631\u0632\u0634 \u067e\u0648\u0644 \u062f\u0631 \u0637\u0648\u0644 \u062f\u0648\u0631\u0647 \u0628\u0627\u0632\u067e\u0631\u062f\u0627\u062e\u062a \u062c\u0628\u0631\u0627\u0646 \u0634\u0648\u062f.<\/span><\/li>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u0627\u062a\u0635\u0627\u0644 \u0646\u0631\u062e\u200c\u0647\u0627 \u0628\u0647 \u062a\u0648\u0631\u0645:<\/b><span style=\"font-weight: 400;\"> \u062f\u0633\u062a\u0645\u0632\u062f\u0647\u0627\u060c <\/span><a style=\"color: #f9c43e;\"href=\"https:\/\/arongroups.co\/fa\/forex\/%D9%86%D8%B1%D8%AE-%D8%A8%D9%87%D8%B1%D9%87-%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\/\"><span style=\"font-weight: 400;\">\u0646\u0631\u062e \u0628\u0647\u0631\u0647<\/span><\/a><span style=\"font-weight: 400;\"> \u0648 \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0645\u0633\u062a\u0642\u06cc\u0645\u0627 \u0628\u0647 \u0634\u0627\u062e\u0635 \u0642\u06cc\u0645\u062a (\u062a\u0648\u0631\u0645) \u0645\u062a\u0635\u0644 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f.<\/span><\/li>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u062a\u0648\u0631\u0645 \u0627\u0646\u0628\u0627\u0634\u062a\u0647 \u0628\u0627\u0644\u0627:<\/b><span style=\"font-weight: 400;\"> \u0646\u0631\u062e \u062a\u0648\u0631\u0645 \u062a\u062c\u0645\u0639\u06cc \u062f\u0631 \u06cc\u06a9 \u062f\u0648\u0631\u0647 \u0633\u0647 \u0633\u0627\u0644\u0647 \u0628\u0647 \u062d\u062f\u0648\u062f \u06f1\u06f0\u06f0 \u062f\u0631\u0635\u062f \u06cc\u0627 \u0628\u06cc\u0634\u062a\u0631 \u0645\u06cc\u200c\u0631\u0633\u062f.<\/span><\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53e4d0c elementor-widget elementor-widget-text-editor\" data-id=\"53e4d0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><b>\u062a\u0641\u0627\u0648\u062a \u0645\u06cc\u0627\u0646 \u062a\u0648\u0631\u0645 \u0628\u0627\u0644\u0627\u060c \u062a\u0648\u0631\u0645 \u0645\u0632\u0645\u0646 \u0648 \u0627\u0628\u0631\u062a\u0648\u0631\u0645<\/b><\/h2><p><span style=\"font-weight: 400;\">\u0628\u0631\u0627\u06cc \u062f\u0631\u06a9 \u0628\u0647\u062a\u0631 \u0627\u0628\u0631\u062a\u0648\u0631\u0645\u060c \u0628\u0627\u06cc\u062f \u062a\u0641\u0627\u0648\u062a \u0622\u0646 \u0628\u0627 \u062a\u0648\u0631\u0645 \u0628\u0627\u0644\u0627 \u0648 \u062a\u0648\u0631\u0645 \u0645\u0632\u0645\u0646 \u0631\u0627 \u0634\u0646\u0627\u062e\u062a:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u062a\u0648\u0631\u0645 \u0628\u0627\u0644\u0627: <\/b><span style=\"font-weight: 400;\">\u0645\u0639\u0645\u0648\u0644\u0627 \u0628\u0647 \u0646\u0631\u062e \u062a\u0648\u0631\u0645 \u0633\u0627\u0644\u0627\u0646\u0647 \u0628\u0627\u0644\u0627\u06cc \u06f2\u06f0 \u062f\u0631\u0635\u062f \u06af\u0641\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0634\u0631\u0627\u06cc\u0637\u060c \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0628\u0647 \u0633\u0631\u0639\u062a \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc\u200c\u06cc\u0627\u0628\u0646\u062f\u060c \u0627\u0645\u0627 \u0686\u0648\u0646 \u0647\u0646\u0648\u0632 \u0627\u0642\u062a\u0635\u0627\u062f \u0642\u0627\u062f\u0631 \u0628\u0647 \u0639\u0645\u0644\u06a9\u0631\u062f \u0646\u0633\u0628\u062a\u0627 \u0639\u0627\u062f\u06cc \u0627\u0633\u062a\u060c \u0645\u0631\u062f\u0645 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0628\u0627 \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0631\u06cc\u0632\u06cc \u0646\u0633\u0628\u062a\u0627 \u0628\u0644\u0646\u062f \u0645\u062f\u062a \u062a\u0635\u0645\u06cc\u0645\u0627\u062a \u0645\u0627\u0644\u06cc \u062e\u0648\u062f \u0631\u0627 \u0627\u062a\u062e\u0627\u0630 \u06a9\u0646\u0646\u062f.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u062a\u0648\u0631\u0645 \u0645\u0632\u0645\u0646:<\/b><span style=\"font-weight: 400;\"> \u0628\u0647 \u0648\u0636\u0639\u06cc\u062a\u06cc \u0627\u0637\u0644\u0627\u0642 \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u0646\u0631\u062e \u062a\u0648\u0631\u0645 \u0628\u0631\u0627\u06cc \u0645\u062f\u062a \u0637\u0648\u0644\u0627\u0646\u06cc (\u0645\u0639\u0645\u0648\u0644\u0627 \u0686\u0646\u062f\u06cc\u0646 \u0633\u0627\u0644) \u062f\u0631 \u0633\u0637\u062d \u0628\u0627\u0644\u0627\u06cc\u06cc (\u0645\u062b\u0644\u0627 \u0628\u06cc\u0646 \u06f1\u06f0 \u062a\u0627 \u06f3\u06f0 \u062f\u0631\u0635\u062f \u062f\u0631 \u0633\u0627\u0644) \u0628\u0627\u0642\u06cc \u0628\u0645\u0627\u0646\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0634\u0631\u0627\u06cc\u0637\u060c \u0645\u0631\u062f\u0645 \u0628\u0647 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u062f\u0627\u0648\u0645 \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0639\u0627\u062f\u062a \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u0648 \u0627\u0642\u062a\u0635\u0627\u062f \u0628\u0627 \u0648\u062c\u0648\u062f \u0645\u0634\u06a9\u0644\u0627\u062a\u060c \u0628\u0647 \u06a9\u0627\u0631 \u062e\u0648\u062f \u0627\u062f\u0627\u0645\u0647 \u0645\u06cc\u200c\u062f\u0647\u062f.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u0627\u0628\u0631\u062a\u0648\u0631\u0645:<\/b><span style=\"font-weight: 400;\"> \u062f\u0631 \u0627\u06cc\u0646 \u062d\u0627\u0644\u062a\u060c \u0646\u0631\u062e \u062a\u0648\u0631\u0645 \u0628\u0647 \u062d\u062f\u06cc \u0628\u0627\u0644\u0627 \u0645\u06cc\u200c\u0631\u0648\u062f \u06a9\u0647 \u0627\u0631\u0632\u0634 \u067e\u0648\u0644 \u0645\u0644\u06cc \u0628\u0647 \u0633\u0631\u0639\u062a \u062f\u0631 \u062d\u0627\u0644 \u0646\u0627\u0628\u0648\u062f\u06cc \u0627\u0633\u062a. \u062f\u0631 \u0634\u0631\u0627\u06cc\u0637 \u0627\u0628\u0631\u062a\u0648\u0631\u0645\u060c \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u062f\u0631 \u0637\u0648\u0644 \u06cc\u06a9 \u0631\u0648\u0632 \u0686\u0646\u062f\u06cc\u0646 \u0628\u0631\u0627\u0628\u0631 \u0634\u0648\u0646\u062f \u0648 \u0645\u0631\u062f\u0645 \u062a\u0645\u0627\u06cc\u0644\u06cc \u0628\u0647 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u067e\u0648\u0644 \u0645\u0644\u06cc \u0646\u062f\u0627\u0631\u0646\u062f. \u0627\u0642\u062a\u0635\u0627\u062f \u062f\u0631 \u0627\u06cc\u0646 \u0648\u0636\u0639\u06cc\u062a \u062f\u0686\u0627\u0631 \u0628\u06cc\u200c\u062b\u0628\u0627\u062a\u06cc \u0634\u062f\u06cc\u062f \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u0641\u0639\u0627\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0645\u062e\u062a\u0644 \u0645\u06cc\u200c\u06af\u0631\u062f\u062f.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74dddb3 elementor-widget elementor-widget-text-editor\" data-id=\"74dddb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><b>\u0631\u06cc\u0634\u0647\u200c\u0647\u0627 \u0648 \u062f\u0644\u0627\u06cc\u0644 \u0627\u0635\u0644\u06cc \u0628\u0631\u0648\u0632 \u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u062f\u0631 \u0627\u0642\u062a\u0635\u0627\u062f\u00a0<\/b><\/h2><p><span style=\"font-weight: 400;\">\u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u06cc\u06a9 \u067e\u062f\u06cc\u062f\u0647 \u0648\u06cc\u0631\u0627\u0646\u06af\u0631 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u0639\u0645\u0648\u0644\u0627 \u0646\u0647 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u06cc\u06a9 \u0639\u0627\u0645\u0644 \u0648\u0627\u062d\u062f\u060c \u0628\u0644\u06a9\u0647 \u0628\u0631 \u0627\u062b\u0631 \u062a\u0631\u06a9\u06cc\u0628\u06cc \u0627\u0632 \u0633\u0648\u0621 \u0645\u062f\u06cc\u0631\u06cc\u062a \u0648 \u0641\u0634\u0627\u0631\u0647\u0627\u06cc \u0633\u0627\u062e\u062a\u0627\u0631\u06cc \u0632\u06cc\u0631 \u0631\u062e \u0645\u06cc\u200c\u062f\u0647\u062f:<\/span><\/p><h3><b>\u0633\u06cc\u0627\u0633\u062a\u200c\u0647\u0627\u06cc \u067e\u0648\u0644\u06cc \u0627\u0646\u0628\u0633\u0627\u0637\u06cc \u0648 \u0686\u0627\u067e \u0628\u06cc\u200c\u0631\u0648\u06cc\u0647 \u067e\u0648\u0644<\/b><\/h3><p><span style=\"font-weight: 400;\">\u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u062f\u0648\u0644\u062a \u0628\u0631\u0627\u06cc \u062c\u0628\u0631\u0627\u0646 \u06a9\u0633\u0631\u06cc\u200c\u0647\u0627\u06cc \u062e\u0648\u062f \u0628\u0647 \u0645\u0646\u0627\u0628\u0639 \u0628\u0627\u0646\u06a9 \u0645\u0631\u06a9\u0632\u06cc \u0645\u062a\u0648\u0633\u0644 \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u0633\u0631\u0639\u062a \u062e\u0644\u0642 \u067e\u0648\u0644 \u0627\u0632 \u0631\u0634\u062f \u062a\u0648\u0644\u06cc\u062f \u0633\u0628\u0642\u062a \u0645\u06cc\u200c\u06af\u06cc\u0631\u062f\u060c \u0641\u0634\u0627\u0631 \u0628\u0631 \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0628\u0647 \u0635\u0648\u0631\u062a \u0632\u0646\u062c\u06cc\u0631\u0647\u200c\u0627\u06cc \u0622\u063a\u0627\u0632 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0646\u0638\u0631\u06cc\u0647\u200c\u0647\u0627\u06cc \u067e\u0648\u0644\u200c\u06af\u0631\u0627\u06cc\u0627\u0646\u0647 \u062a\u0648\u0636\u06cc\u062d \u0645\u06cc\u200c\u062f\u0647\u0646\u062f \u06a9\u0647 \u062f\u0631 \u0634\u0631\u0627\u06cc\u0637 \u0628\u06cc\u200c\u0627\u0639\u062a\u0645\u0627\u062f\u06cc\u060c \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062d\u062c\u0645 \u067e\u0648\u0644\u060c \u00ab\u0633\u0631\u0639\u062a \u06af\u0631\u062f\u0634 \u067e\u0648\u0644\u00bb \u0646\u06cc\u0632 \u0628\u0627\u0644\u0627 \u0645\u06cc\u200c\u0631\u0648\u062f\u061b \u06cc\u0639\u0646\u06cc \u0633\u0637\u062d \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u062d\u062a\u06cc \u0633\u0631\u06cc\u0639\u200c\u062a\u0631 \u0627\u0632 \u0686\u0627\u067e \u067e\u0648\u0644 \u0631\u0634\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/span><\/p><h3><b>\u0628\u062f\u0647\u06cc\u200c\u0647\u0627\u06cc \u0633\u0646\u06af\u06cc\u0646 \u062f\u0648\u0644\u062a \u0648 \u06a9\u0633\u0631\u06cc \u0628\u0648\u062f\u062c\u0647 \u0645\u0632\u0645\u0646<\/b><\/h3><p><span style=\"font-weight: 400;\">\u0648\u0642\u062a\u06cc \u062f\u0648\u0644\u062a \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u06a9\u0627\u0641\u06cc \u0628\u0631\u0627\u06cc \u0627\u062e\u0630 \u06a9\u0627\u0631\u0622\u0645\u062f \u0645\u0627\u0644\u06cc\u0627\u062a \u06cc\u0627 \u062f\u0631\u06cc\u0627\u0641\u062a \u0648\u0627\u0645 \u0628\u0627 \u0646\u0631\u062e \u0645\u0639\u0642\u0648\u0644 \u0631\u0627 \u0646\u062f\u0627\u0631\u062f\u060c \u0686\u0627\u067e \u067e\u0648\u0644 (\u067e\u0648\u0644\u06cc\u200c\u0633\u0627\u0632\u06cc \u06a9\u0633\u0631\u06cc \u0628\u0648\u062f\u062c\u0647) \u0628\u0647 \u062f\u0631 \u062f\u0633\u062a\u0631\u0633\u200c\u062a\u0631\u06cc\u0646 \u06af\u0632\u06cc\u0646\u0647 \u062a\u0628\u062f\u06cc\u0644 \u0645\u06cc\u200c\u0634\u0648\u062f. \u0627\u06af\u0631 \u0627\u06cc\u0646 \u0645\u0633\u06cc\u0631 \u0628\u0627 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u0627\u0646\u0639\u0637\u0627\u0641\u200c\u0646\u0627\u067e\u0630\u06cc\u0631\u06cc \u0645\u0627\u0646\u0646\u062f \u062d\u0642\u0648\u0642 \u06a9\u0627\u0631\u0645\u0646\u062f\u0627\u0646\u060c \u06cc\u0627\u0631\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0633\u0646\u06af\u06cc\u0646 \u06cc\u0627 \u0645\u062e\u0627\u0631\u062c \u062c\u0646\u06af \u0647\u0645\u0631\u0627\u0647 \u0634\u0648\u062f\u060c \u0627\u0642\u062a\u0635\u0627\u062f \u0631\u0627 \u06af\u0631\u0641\u062a\u0627\u0631 \u06cc\u06a9 \u062f\u0648\u0631 \u0628\u0627\u0637\u0644 \u062a\u0648\u0631\u0645\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/span><\/p><h3><b>\u0627\u0632 \u0628\u06cc\u0646 \u0631\u0641\u062a\u0646 \u0627\u0639\u062a\u0645\u0627\u062f \u0639\u0645\u0648\u0645\u06cc \u0628\u0647 \u067e\u0648\u0644 \u0645\u0644\u06cc\u00a0<\/b><\/h3><p><span style=\"font-weight: 400;\">\u0628\u0627 \u0639\u0628\u0648\u0631 \u0627\u0632 \u06cc\u06a9 \u0646\u0642\u0637\u0647 \u0628\u062d\u0631\u0627\u0646\u06cc\u060c \u0645\u0631\u062f\u0645 \u062f\u06cc\u06af\u0631 \u062a\u0645\u0627\u06cc\u0644\u06cc \u0628\u0647 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u067e\u0648\u0644 \u0645\u0644\u06cc \u0646\u062f\u0627\u0631\u0646\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0648\u0636\u0639\u06cc\u062a\u060c \u0641\u0631\u0648\u0634\u0646\u062f\u06af\u0627\u0646 \u0628\u0631\u0627\u06cc \u067e\u0630\u06cc\u0631\u0634 \u067e\u0648\u0644 \u062f\u0627\u062e\u0644\u06cc \u00ab\u062d\u0642 \u0631\u06cc\u0633\u06a9\u00bb \u0637\u0644\u0628 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f \u06cc\u0627 \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0631\u0627 \u0644\u062d\u0638\u0647\u200c\u0627\u06cc \u0648 \u0628\u0631 \u0627\u0633\u0627\u0633 \u0627\u0631\u0632\u0647\u0627\u06cc \u062e\u0627\u0631\u062c\u06cc \u0645\u0639\u062a\u0628\u0631 \u062a\u0639\u06cc\u06cc\u0646 \u0645\u06cc\u200c\u06a9\u0646\u0646\u062f. \u0627\u06cc\u0646 \u0641\u0631\u0648\u067e\u0627\u0634\u06cc \u0627\u0639\u062a\u0645\u0627\u062f \u06a9\u0647 \u062f\u0631 \u062a\u062c\u0631\u0628\u0647\u200c\u0647\u0627\u06cc\u06cc \u0645\u0627\u0646\u0646\u062f \u0648\u0646\u0632\u0648\u0626\u0644\u0627 \u0648 \u0632\u06cc\u0645\u0628\u0627\u0628\u0648\u0647 \u062f\u06cc\u062f\u0647 \u0634\u062f\u0647\u060c \u0633\u0631\u0639\u062a \u0633\u0642\u0648\u0637 \u0627\u0631\u0632\u0634 \u067e\u0648\u0644 \u0631\u0627 \u063a\u06cc\u0631\u0642\u0627\u0628\u0644 \u06a9\u0646\u062a\u0631\u0644 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5635ce elementor-widget elementor-widget-text-editor\" data-id=\"d5635ce\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><b>\u062a\u0623\u062b\u06cc\u0631 \u0628\u062d\u0631\u0627\u0646\u200c\u0647\u0627\u06cc \u0633\u06cc\u0627\u0633\u06cc\u060c \u062c\u0646\u06af\u200c\u0647\u0627 \u0648 \u062a\u062d\u0631\u06cc\u0645\u200c\u0647\u0627 \u0628\u0631 \u062a\u0648\u0631\u0645 \u0634\u062f\u06cc\u062f\u00a0<\/b><\/h3><p><span style=\"font-weight: 400;\">\u062c\u0646\u06af \u06cc\u0627 \u0628\u06cc\u200c\u062b\u0628\u0627\u062a\u06cc \u0633\u06cc\u0627\u0633\u06cc\u060c \u0647\u0645\u0632\u0645\u0627\u0646 \u062f\u0631\u0622\u0645\u062f\u0647\u0627\u06cc \u062f\u0648\u0644\u062a (\u0645\u0627\u0646\u0646\u062f \u0645\u0627\u0644\u06cc\u0627\u062a) \u0631\u0627 \u06a9\u0627\u0647\u0634 \u0648 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627 \u0631\u0627 \u0628\u0647 \u0634\u062f\u062a \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f. \u0627\u06cc\u0646 \u0648\u0636\u0639\u06cc\u062a \u0631\u06cc\u0633\u06a9 \u0627\u0639\u062a\u0628\u0627\u0631\u06cc \u062f\u0648\u0644\u062a \u0631\u0627 \u0628\u0627\u0644\u0627 \u0628\u0631\u062f\u0647 \u0648 \u0622\u0646 \u0631\u0627 \u0646\u0627\u0686\u0627\u0631 \u0628\u0647 \u062a\u0623\u0645\u06cc\u0646 \u0645\u0627\u0644\u06cc \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0686\u0627\u067e \u067e\u0648\u0644 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0646\u0645\u0648\u0646\u0647\u200c\u0647\u0627\u06cc \u062a\u0627\u0631\u06cc\u062e\u06cc \u0627\u06cc\u0646 \u0648\u0636\u0639\u06cc\u062a \u062f\u0631 \u0686\u06cc\u0646 (\u062f\u0647\u0647 \u06f4\u06f0)\u060c \u06cc\u0648\u0646\u0627\u0646 (\u062f\u0647\u0647 \u06f4\u06f0) \u0648 \u06cc\u0648\u06af\u0633\u0644\u0627\u0648\u06cc (\u0627\u0648\u0627\u06cc\u0644 \u062f\u0647\u0647 \u06f9\u06f0) \u0645\u0633\u062a\u0646\u062f \u0634\u062f\u0647 \u0627\u0633\u062a.<\/span><\/p><h3><b>\u0646\u0642\u0634 \u0636\u0639\u0641 \u062a\u0648\u0644\u06cc\u062f \u0648 \u0648\u0627\u0628\u0633\u062a\u06af\u06cc \u0628\u0647 \u0648\u0627\u0631\u062f\u0627\u062a \u062f\u0631 \u062a\u0634\u062f\u06cc\u062f \u062a\u0648\u0631\u0645\u00a0<\/b><\/h3><p><span style=\"font-weight: 400;\">\u062f\u0631 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u06a9\u0647 \u0628\u0647 \u0648\u0627\u0631\u062f\u0627\u062a \u0648\u0627\u0628\u0633\u062a\u0647 \u0627\u0633\u062a\u060c \u0647\u0631\u06af\u0648\u0646\u0647 \u0634\u0648\u06a9 \u0645\u0646\u0641\u06cc \u062f\u0631 \u0639\u0631\u0636\u0647 (\u0645\u0627\u0646\u0646\u062f \u06a9\u0627\u0647\u0634 \u062a\u0648\u0644\u06cc\u062f \u062f\u0627\u062e\u0644\u06cc \u06cc\u0627 \u0645\u062d\u062f\u0648\u062f\u06cc\u062a \u062f\u0631 \u0648\u0627\u0631\u062f\u0627\u062a) \u0622\u062a\u0634 \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0631\u0627 \u062a\u0646\u062f\u062a\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06af\u0631 \u0647\u0645\u0632\u0645\u0627\u0646 \u0646\u0631\u062e \u0627\u0631\u0632 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u06a9\u0645\u0628\u0648\u062f \u0645\u0646\u0627\u0628\u0639 \u0627\u0631\u0632\u06cc \u062c\u0647\u0634 \u06a9\u0646\u062f\u060c \u06af\u0631\u0627\u0646\u06cc \u06a9\u0627\u0644\u0627\u0647\u0627\u06cc \u0648\u0627\u0631\u062f\u0627\u062a\u06cc \u0628\u0647 \u0633\u0631\u0639\u062a \u0628\u0647 \u06a9\u0644 \u0627\u0642\u062a\u0635\u0627\u062f \u0633\u0631\u0627\u06cc\u062a \u06a9\u0631\u062f\u0647 (\u0627\u0646\u062a\u0642\u0627\u0644 \u0627\u0631\u0632\u06cc \u0628\u0647 \u0642\u06cc\u0645\u062a\u200c\u0647\u0627) \u0648 \u0645\u0648\u062c \u062a\u0648\u0631\u0645 \u0634\u062f\u06cc\u062f \u0631\u0627 \u0627\u06cc\u062c\u0627\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/span><\/p><h2><b>\u067e\u06cc\u0627\u0645\u062f\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0648 \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0627\u0628\u0631\u062a\u0648\u0631\u0645\u00a0<\/b><\/h2><p><span style=\"font-weight: 400;\">\u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u0641\u0631\u0627\u062a\u0631 \u0627\u0632 \u06cc\u06a9 \u067e\u062f\u06cc\u062f\u0647 \u0635\u0631\u0641\u0627 \u067e\u0648\u0644\u06cc \u0627\u0633\u062a \u0648 \u0628\u0647 \u0633\u0631\u0639\u062a \u0628\u0646\u06cc\u0627\u0646\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f \u0648 \u0633\u0627\u062e\u062a\u0627\u0631\u0647\u0627\u06cc \u0631\u0648\u0627\u0646\u06cc \u062c\u0627\u0645\u0639\u0647 \u0631\u0627 \u062a\u062e\u0631\u06cc\u0628 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e4c7d12 elementor-widget elementor-widget-text-editor\" data-id=\"e4c7d12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><b>\u06a9\u0627\u0647\u0634 \u0627\u0631\u0632\u0634 \u067e\u0648\u0644 \u0648 \u0642\u062f\u0631\u062a \u062e\u0631\u06cc\u062f \u0645\u0631\u062f\u0645\u00a0<\/b><\/h3><p><span style=\"font-weight: 400;\">\u0645\u0633\u062a\u0642\u06cc\u0645\u200c\u062a\u0631\u06cc\u0646 \u067e\u06cc\u0627\u0645\u062f \u0627\u0628\u0631\u062a\u0648\u0631\u0645\u060c \u062a\u0628\u062e\u06cc\u0631 \u0633\u0631\u06cc\u0639 \u0642\u062f\u0631\u062a \u062e\u0631\u06cc\u062f \u0627\u0633\u062a. \u062f\u0631 \u0627\u06cc\u0646 \u0634\u0631\u0627\u06cc\u0637\u060c \u0633\u0631\u0639\u062a \u0631\u0634\u062f \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0628\u0633\u06cc\u0627\u0631 \u0641\u0631\u0627\u062a\u0631 \u0627\u0632 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0633\u062a\u0645\u0632\u062f\u0647\u0627\u06cc \u0627\u0633\u0645\u06cc \u0627\u0633\u062a \u0648 \u00ab\u0639\u0645\u0631 \u0628\u0631\u0686\u0633\u0628\u200c\u0647\u0627\u06cc \u0642\u06cc\u0645\u062a\u06cc\u00bb \u0628\u0647 \u0634\u062f\u062a \u06a9\u0648\u062a\u0627\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f\u060c \u0628\u0647 \u06af\u0648\u0646\u0647\u200c\u0627\u06cc \u06a9\u0647 \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0645\u0645\u06a9\u0646 \u0627\u0633\u062a \u0631\u0648\u0632\u0627\u0646\u0647 \u06cc\u0627 \u062d\u062a\u06cc \u0633\u0627\u0639\u062a\u06cc \u062a\u063a\u06cc\u06cc\u0631 \u06a9\u0646\u0646\u062f.<\/span><\/p><p><span style=\"font-weight: 400;\">\u0646\u0645\u0648\u0646\u0647\u200c\u0647\u0627\u06cc \u062a\u0627\u0631\u06cc\u062e\u06cc \u062b\u0628\u062a \u0634\u062f\u0647 \u0634\u062f\u062a \u0627\u06cc\u0646 \u0641\u0627\u062c\u0639\u0647 \u0631\u0627 \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f: \u062f\u0631 \u0622\u0644\u0645\u0627\u0646 (\u06f1\u06f9\u06f2\u06f3) \u0627\u0631\u0632\u0634 \u067e\u0648\u0644 \u0686\u0646\u0627\u0646 \u0633\u0642\u0648\u0637 \u06a9\u0631\u062f \u06a9\u0647 \u0627\u0632 \u0627\u0633\u06a9\u0646\u0627\u0633 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06a9\u0627\u063a\u0630 \u062f\u06cc\u0648\u0627\u0631\u06cc \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646 \u0637\u0628\u0642 \u0645\u0633\u062a\u0646\u062f\u0627\u062a \u062a\u0627\u0631\u06cc\u062e\u06cc (\u0645\u0627\u0646\u0646\u062f <\/span><a href=\"https:\/\/en.wikipedia.org\/wiki\/Hyperinflation\" target=\"_blank\" rel=\"nofollow noopener\"><span style=\"font-weight: 400;\">\u062f\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u0648\u06cc\u06a9\u06cc\u200c\u067e\u062f\u06cc\u0627<\/span><\/a><span style=\"font-weight: 400;\">)\u060c \u0686\u0627\u067e \u0627\u0633\u06a9\u0646\u0627\u0633\u200c\u0647\u0627\u06cc\u06cc \u0628\u0627 \u0627\u0631\u0642\u0627\u0645 \u0646\u062c\u0648\u0645\u06cc \u062f\u0631 \u0645\u062c\u0627\u0631\u0633\u062a\u0627\u0646 (\u06f1\u06f9\u06f4\u06f6) \u0648 \u0632\u06cc\u0645\u0628\u0627\u0628\u0648\u0647 (\u06f2\u06f0\u06f0\u06f8) \u0646\u0634\u0627\u0646\u200c\u062f\u0647\u0646\u062f\u0647 \u0628\u06cc\u200c\u0627\u0639\u062a\u0628\u0627\u0631\u06cc \u06a9\u0627\u0645\u0644 \u067e\u0648\u0644 \u0645\u0644\u06cc \u062f\u0631 \u0627\u06cc\u0646 \u062f\u0648\u0631\u0647\u200c\u0647\u0627 \u0628\u0648\u062f\u0647 \u0627\u0633\u062a.<\/span><\/p><h3><b>\u0646\u0627\u0628\u0648\u062f\u06cc \u067e\u0633\u200c\u0627\u0646\u062f\u0627\u0632\u0647\u0627 \u0648 \u0641\u0631\u0627\u0631 \u0633\u0631\u0645\u0627\u06cc\u0647 \u0627\u0632 \u06a9\u0634\u0648\u0631\u00a0<\/b><\/h3><p><span style=\"font-weight: 400;\">\u0627\u0628\u0631\u062a\u0648\u0631\u0645\u060c \u067e\u0633\u200c\u0627\u0646\u062f\u0627\u0632\u0647\u0627\u06cc \u0646\u0642\u062f\u06cc \u0631\u0627 \u0628\u06cc\u200c\u0627\u0631\u0632\u0634 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u0639\u0645\u0644\u0627 \u0645\u0627\u0644\u06cc\u0627\u062a\u06cc \u0633\u0646\u06af\u06cc\u0646 \u0628\u0631 \u062f\u0627\u0631\u0646\u062f\u06af\u0627\u0646 \u067e\u0648\u0644 \u0646\u0642\u062f\u060c \u0628\u0647 \u0648\u06cc\u0698\u0647 \u0628\u0627\u0632\u0646\u0634\u0633\u062a\u06af\u0627\u0646 \u0648 \u0627\u0642\u0634\u0627\u0631 \u0628\u0627 \u062f\u0631\u0622\u0645\u062f \u062b\u0627\u0628\u062a\u060c \u062a\u062d\u0645\u06cc\u0644 \u0645\u06cc\u200c\u0646\u0645\u0627\u06cc\u062f. \u062f\u0631 \u0648\u0627\u06a9\u0646\u0634 \u0628\u0647 \u0646\u0631\u062e\u200c\u0647\u0627\u06cc \u0628\u0647\u0631\u0647 \u0648\u0627\u0642\u0639\u06cc \u0645\u0646\u0641\u06cc\u060c \u0645\u0631\u062f\u0645 \u0648 \u0628\u0646\u06af\u0627\u0647\u200c\u0647\u0627 \u0628\u0631\u0627\u06cc \u062d\u0641\u0638 \u0627\u0631\u0632\u0634 \u062f\u0627\u0631\u0627\u06cc\u06cc \u062e\u0648\u062f \u0628\u0647 \u0633\u0645\u062a \u062e\u0631\u06cc\u062f \u062f\u0627\u0631\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc \u0641\u06cc\u0632\u06cc\u06a9\u06cc (\u0645\u0627\u0646\u0646\u062f \u0637\u0644\u0627 \u0648 \u0645\u0644\u06a9) \u06cc\u0627 \u0627\u0631\u0632\u0647\u0627\u06cc \u062e\u0627\u0631\u062c\u06cc \u0647\u062c\u0648\u0645 \u0645\u06cc\u200c\u0622\u0648\u0631\u0646\u062f. \u0627\u06cc\u0646 \u067e\u062f\u06cc\u062f\u0647 \u0645\u0646\u062c\u0631 \u0628\u0647 \u00ab\u0641\u0631\u0627\u0631 \u0633\u0631\u0645\u0627\u06cc\u0647\u00bb \u06af\u0633\u062a\u0631\u062f\u0647 \u0627\u0632 \u06a9\u0634\u0648\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u062e\u0648\u062f\u060c \u0628\u062d\u0631\u0627\u0646 \u06a9\u0645\u0628\u0648\u062f \u0645\u0646\u0627\u0628\u0639 \u0645\u0627\u0644\u06cc \u0631\u0627 \u0639\u0645\u06cc\u0642\u200c\u062a\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f.<\/span><\/p><h3><b>\u0628\u06cc\u200c\u062b\u0628\u0627\u062a\u06cc \u0628\u0627\u0632\u0627\u0631\u0647\u0627 \u0648 \u06a9\u0627\u0647\u0634 \u062a\u0648\u0644\u06cc\u062f \u0645\u0644\u06cc\u00a0<\/b><\/h3><p><span style=\"font-weight: 400;\">\u0646\u0627\u0627\u0637\u0645\u06cc\u0646\u0627\u0646\u06cc \u0634\u062f\u06cc\u062f \u0642\u06cc\u0645\u062a\u06cc\u060c \u0627\u0641\u0642 \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0631\u06cc\u0632\u06cc \u0631\u0627 \u0628\u0631\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f\u06a9\u0646\u0646\u062f\u06af\u0627\u0646 \u062a\u06cc\u0631\u0647 \u0648 \u062a\u0627\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0648\u0642\u062a\u06cc \u0628\u0646\u06af\u0627\u0647\u200c\u0647\u0627 \u0642\u0627\u062f\u0631 \u0628\u0647 \u067e\u06cc\u0634\u200c\u0628\u06cc\u0646\u06cc \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u0622\u062a\u06cc \u0648 \u0642\u06cc\u0645\u062a \u0641\u0631\u0648\u0634 \u0646\u0628\u0627\u0634\u0646\u062f\u060c \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u0645\u062a\u0648\u0642\u0641 \u0634\u062f\u0647 \u0648 \u0645\u062f\u06cc\u0631\u06cc\u062a \u0645\u0648\u062c\u0648\u062f\u06cc \u0627\u0646\u0628\u0627\u0631 \u0645\u062e\u062a\u0644 \u0645\u06cc\u200c\u0634\u0648\u062f.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">\u0646\u062a\u06cc\u062c\u0647 \u0627\u06cc\u0646 \u0648\u0636\u0639\u06cc\u062a\u060c \u0634\u06a9\u0644\u200c\u06af\u06cc\u0631\u06cc \u00ab<\/span><a href=\"https:\/\/arongroups.co\/fa\/forex\/what-is-stagflation\/\"><span style=\"font-weight: 400;\">\u0631\u06a9\u0648\u062f \u062a\u0648\u0631\u0645\u06cc<\/span><\/a><span style=\"font-weight: 400;\">\u00bb \u0627\u0633\u062a\u061b \u0634\u0631\u0627\u06cc\u0637\u06cc \u06a9\u0647 \u062f\u0631 \u0622\u0646 \u0627\u0642\u062a\u0635\u0627\u062f \u0647\u0645\u200c\u0632\u0645\u0627\u0646 \u0628\u0627 \u062a\u0648\u0631\u0645 \u0628\u0627\u0644\u0627\u060c \u062f\u0686\u0627\u0631 \u06a9\u0627\u0647\u0634 \u0634\u062f\u06cc\u062f \u062a\u0648\u0644\u06cc\u062f \u0648 \u0628\u06cc\u06a9\u0627\u0631\u06cc \u0645\u06cc\u200c\u0634\u0648\u062f. \u062a\u062c\u0631\u0628\u0647\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0648\u0646\u0632\u0648\u0626\u0644\u0627 \u0648 \u0632\u06cc\u0645\u0628\u0627\u0628\u0648\u0647 \u0646\u0645\u0648\u0646\u0647\u200c\u0647\u0627\u06cc \u0628\u0627\u0631\u0632\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u0686\u0631\u062e\u0647 \u0645\u062e\u0631\u0628 \u0647\u0633\u062a\u0646\u062f \u06a9\u0647 \u062f\u0631 \u0622\u0646 \u062a\u0648\u0644\u06cc\u062f \u0645\u0644\u06cc \u0642\u0631\u0628\u0627\u0646\u06cc \u0628\u06cc\u200c\u062b\u0628\u0627\u062a\u06cc \u0628\u0627\u0632\u0627\u0631 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/span><\/p><h3><b>\u067e\u06cc\u0627\u0645\u062f\u0647\u0627\u06cc \u0627\u062c\u062a\u0645\u0627\u0639\u06cc \u0648 \u0631\u0648\u0627\u0646\u06cc \u0646\u0627\u0634\u06cc \u0627\u0632 \u0627\u0628\u0631\u062a\u0648\u0631\u0645\u00a0<\/b><\/h3><p><span style=\"font-weight: 400;\">\u0641\u0634\u0627\u0631 \u0645\u062f\u0627\u0648\u0645 \u0628\u0631\u0627\u06cc \u062a\u0623\u0645\u06cc\u0646 \u0646\u06cc\u0627\u0632\u0647\u0627\u06cc \u0627\u0648\u0644\u06cc\u0647\u060c \u062c\u0627\u0645\u0639\u0647 \u0631\u0627 \u062f\u0686\u0627\u0631 \u0627\u0636\u0637\u0631\u0627\u0628 \u0645\u0632\u0645\u0646 \u0648 \u0646\u0627\u0627\u0645\u06cc\u062f\u06cc \u0645\u06cc\u200c\u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0634\u0631\u0627\u06cc\u0637 \u0628\u0647 \u0631\u0641\u062a\u0627\u0631\u0647\u0627\u06cc \u0627\u062d\u062a\u06cc\u0627\u0637\u06cc \u0627\u0641\u0631\u0627\u0637\u06cc \u0645\u0627\u0646\u0646\u062f \u00ab\u0647\u062c\u0648\u0645 \u0628\u0631\u0627\u06cc \u062e\u0631\u06cc\u062f \u06a9\u0627\u0644\u0627\u00bb \u062f\u0627\u0645\u0646 \u0645\u06cc\u200c\u0632\u0646\u062f. \u062f\u0631 \u0633\u0637\u062d \u06a9\u0644\u0627\u0646\u200c\u062a\u0631\u060c \u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u0627\u0639\u062a\u0645\u0627\u062f \u0639\u0645\u0648\u0645\u06cc \u0628\u0647 \u0646\u0647\u0627\u062f\u0647\u0627\u06cc \u062f\u0648\u0644\u062a\u06cc \u0648 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0631\u0627 \u0627\u0632 \u0628\u06cc\u0646 \u0645\u06cc\u200c\u0628\u0631\u062f. \u06a9\u0627\u0647\u0634 \u0633\u0631\u0645\u0627\u06cc\u0647 \u0627\u062c\u062a\u0645\u0627\u0639\u06cc\u060c \u0627\u0641\u0632\u0627\u06cc\u0634 \u0641\u0642\u0631 \u0648 \u0627\u062d\u0633\u0627\u0633 \u0628\u06cc\u200c\u067e\u0646\u0627\u0647\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0632\u0645\u06cc\u0646\u0647\u200c\u0633\u0627\u0632 \u0631\u0634\u062f \u062c\u0631\u0645 \u0648 \u062c\u0646\u0627\u06cc\u062a \u0648 \u062d\u062a\u06cc \u0646\u0627\u0622\u0631\u0627\u0645\u06cc\u200c\u0647\u0627\u06cc \u0645\u062f\u0646\u06cc \u0648 \u0633\u06cc\u0627\u0633\u06cc \u0634\u0648\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-76250ab elementor-widget elementor-widget-text-editor\" data-id=\"76250ab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><b>\u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u0645\u0642\u0627\u0628\u0644\u0647 \u0628\u0627 \u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u062f\u0631 \u0633\u0637\u062d \u06a9\u0644\u0627\u0646 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc <\/b><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e42eed6 elementor-widget elementor-widget-image\" data-id=\"e42eed6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"448\" src=\"https:\/\/newwp.aronsos.co\/wp-content\/uploads\/2025\/11\/hyper-inflation-1-1024x574.jpg\" class=\"attachment-large size-large wp-image-173585\" alt=\"\u0627\u0628\u0631 \u062a\u0648\u0631\u0645\" srcset=\"https:\/\/newwp.aronsos.co\/wp-content\/uploads\/2025\/11\/hyper-inflation-1-1024x574.jpg 1024w, https:\/\/newwp.aronsos.co\/wp-content\/uploads\/2025\/11\/hyper-inflation-1-300x168.jpg 300w, https:\/\/newwp.aronsos.co\/wp-content\/uploads\/2025\/11\/hyper-inflation-1-768x431.jpg 768w, https:\/\/newwp.aronsos.co\/wp-content\/uploads\/2025\/11\/hyper-inflation-1.jpg 1070w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d058966 elementor-widget elementor-widget-text-editor\" data-id=\"d058966\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">\u0645\u0647\u0627\u0631 \u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u0646\u06cc\u0627\u0632\u0645\u0646\u062f \u0627\u062c\u0631\u0627\u06cc \u0647\u0645\u200c\u0632\u0645\u0627\u0646 \u06cc\u06a9 \u0628\u0633\u062a\u0647 \u0633\u06cc\u0627\u0633\u062a\u06cc \u0627\u0646\u0636\u0628\u0627\u0637\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0631\u06cc\u0634\u0647\u200c\u0647\u0627\u06cc \u067e\u0648\u0644\u06cc \u0628\u062d\u0631\u0627\u0646 \u0631\u0627 \u062e\u0634\u06a9\u0627\u0646\u062f\u0647 \u0648 \u0627\u0639\u062a\u0645\u0627\u062f \u0627\u0632 \u062f\u0633\u062a \u0631\u0641\u062a\u0647 \u0631\u0627 \u0628\u0647 \u0641\u0639\u0627\u0644\u0627\u0646 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0628\u0627\u0632\u06af\u0631\u062f\u0627\u0646\u062f.<\/span><\/p><h3><b>\u0627\u0635\u0644\u0627\u062d \u0633\u06cc\u0627\u0633\u062a\u200c\u0647\u0627\u06cc \u067e\u0648\u0644\u06cc \u0648 \u06a9\u0646\u062a\u0631\u0644 \u067e\u0627\u06cc\u0647 \u067e\u0648\u0644\u06cc\u00a0<\/b><\/h3><p><span style=\"font-weight: 400;\">\u0627\u0648\u0644\u06cc\u0646 \u0648 \u062d\u06cc\u0627\u062a\u06cc\u200c\u062a\u0631\u06cc\u0646 \u06af\u0627\u0645\u060c \u062a\u0648\u0642\u0641 \u0641\u0648\u0631\u06cc \u00ab\u067e\u0648\u0644\u06cc\u200c\u0633\u0627\u0632\u06cc \u06a9\u0633\u0631\u06cc \u0628\u0648\u062f\u062c\u0647\u00bb \u0627\u0633\u062a. \u0628\u0647 \u0627\u06cc\u0646 \u0645\u0639\u0646\u0627 \u06a9\u0647 \u062f\u0648\u0644\u062a \u0646\u0628\u0627\u06cc\u062f \u0628\u0631\u0627\u06cc \u062c\u0628\u0631\u0627\u0646 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u062e\u0648\u062f \u0628\u0647 \u0645\u0646\u0627\u0628\u0639 \u0628\u0627\u0646\u06a9 \u0645\u0631\u06a9\u0632\u06cc \u062f\u0633\u062a\u200c\u062f\u0631\u0627\u0632\u06cc \u06a9\u0646\u062f.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">\u0628\u0627\u0632\u06af\u0634\u062a \u0628\u0647 \u0686\u0627\u0631\u0686\u0648\u0628\u200c\u0647\u0627\u06cc \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f \u0645\u0627\u0646\u0646\u062f \u00ab\u0647\u062f\u0641\u200c\u06af\u0630\u0627\u0631\u06cc \u062a\u0648\u0631\u0645\u00bb \u0646\u06cc\u0627\u0632\u0645\u0646\u062f \u0627\u062c\u0631\u0627\u06cc \u0633\u06cc\u0627\u0633\u062a\u200c\u0647\u0627\u06cc \u0627\u0646\u0642\u0628\u0627\u0636\u06cc \u0647\u0648\u0634\u0645\u0646\u062f\u0627\u0646\u0647 (\u0645\u0627\u0646\u0646\u062f \u0627\u0641\u0632\u0627\u06cc\u0634 \u0646\u0631\u062e \u0628\u0647\u0631\u0647 \u0648\u0627\u0642\u0639\u06cc \u0648 \u06a9\u0646\u062a\u0631\u0644 \u0634\u062f\u06cc\u062f \u0631\u0634\u062f <\/span><a href=\"https:\/\/arongroups.co\/fa\/forex\/everything-about-liquidity-provider-and-market-makers-in-forex\/\"><span style=\"font-weight: 400;\">\u0646\u0642\u062f\u06cc\u0646\u06af\u06cc<\/span><\/a><span style=\"font-weight: 400;\">) \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0627\u0642\u062f\u0627\u0645\u0627\u062a \u0627\u06af\u0631\u0686\u0647 \u062f\u0631 \u06a9\u0648\u062a\u0627\u0647 \u0645\u062f\u062a \u062f\u0631\u062f\u0646\u0627\u06a9 \u0647\u0633\u062a\u0646\u062f\u060c \u0627\u0645\u0627 \u0628\u0631\u0627\u06cc \u0634\u06a9\u0633\u062a\u0646 \u0647\u0633\u062a\u0647 \u0633\u062e\u062a \u062a\u0648\u0631\u0645 \u0636\u0631\u0648\u0631\u06cc\u200c\u0627\u0646\u062f.<\/span><\/p><h3><b>\u0627\u0633\u062a\u0642\u0644\u0627\u0644 \u0628\u0627\u0646\u06a9 \u0645\u0631\u06a9\u0632\u06cc \u0648 \u0634\u0641\u0627\u0641\u06cc\u062a \u0645\u0627\u0644\u06cc \u062f\u0648\u0644\u062a\u00a0<\/b><\/h3><p><span style=\"font-weight: 400;\">\u0628\u0627\u0646\u06a9 \u0645\u0631\u06a9\u0632\u06cc \u0628\u0631\u0627\u06cc \u0645\u0642\u0627\u0648\u0645\u062a \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0641\u0634\u0627\u0631\u0647\u0627\u06cc \u0633\u06cc\u0627\u0633\u06cc \u062c\u0647\u062a \u0686\u0627\u067e \u067e\u0648\u0644\u060c \u0646\u06cc\u0627\u0632\u0645\u0646\u062f \u0627\u0633\u062a\u0642\u0644\u0627\u0644 \u0642\u0627\u0646\u0648\u0646\u06cc \u0627\u0633\u062a. \u0627\u06cc\u0646 \u0646\u0647\u0627\u062f \u0628\u0627\u06cc\u062f \u0628\u062a\u0648\u0627\u0646\u062f \u0628\u062f\u0648\u0646 \u062a\u0631\u0633 \u0627\u0632 \u0639\u0648\u0627\u0642\u0628 \u0633\u06cc\u0627\u0633\u06cc\u060c \u0627\u0646\u0636\u0628\u0627\u0637 \u067e\u0648\u0644\u06cc \u0631\u0627 \u0627\u0639\u0645\u0627\u0644 \u06a9\u0646\u062f.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">\u0647\u0645\u200c\u0632\u0645\u0627\u0646\u060c \u062f\u0648\u0644\u062a \u0628\u0627\u06cc\u062f \u0628\u0627 \u0634\u0641\u0627\u0641\u06cc\u062a \u06a9\u0627\u0645\u0644 \u0628\u0648\u062f\u062c\u0647\u200c\u0627\u06cc (\u0634\u0627\u0645\u0644 \u06af\u0632\u0627\u0631\u0634\u200c\u062f\u0647\u06cc \u0645\u0646\u0638\u0645 \u0648 \u0627\u0641\u0634\u0627\u06cc \u0628\u062f\u0647\u06cc\u200c\u0647\u0627\u06cc \u067e\u0646\u0647\u0627\u0646)\u060c \u0627\u0645\u06a9\u0627\u0646 \u0627\u0631\u0632\u06cc\u0627\u0628\u06cc \u0648\u0627\u0642\u0639\u06cc \u0639\u0645\u0644\u06a9\u0631\u062f \u062e\u0648\u062f \u0631\u0627 \u0628\u0631\u0627\u06cc \u0645\u0631\u062f\u0645 \u0648 \u0646\u0647\u0627\u062f\u0647\u0627\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u0641\u0631\u0627\u0647\u0645 \u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0634\u0641\u0627\u0641\u06cc\u062a\u060c \u0633\u06cc\u06af\u0646\u0627\u0644 \u0642\u062f\u0631\u062a\u0645\u0646\u062f\u06cc \u0628\u0631\u0627\u06cc \u0628\u0627\u0632\u0633\u0627\u0632\u06cc \u0627\u0639\u062a\u0628\u0627\u0631 \u0627\u0632 \u062f\u0633\u062a \u0631\u0641\u062a\u0647 \u062f\u0648\u0644\u062a \u0646\u0632\u062f \u06a9\u0627\u0631\u06af\u0632\u0627\u0631\u0627\u0646 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0627\u0633\u062a.<\/span><\/p><h3><b>\u062d\u0645\u0627\u06cc\u062a \u0627\u0632 \u062a\u0648\u0644\u06cc\u062f \u062f\u0627\u062e\u0644\u06cc \u0648 \u06a9\u0627\u0647\u0634 \u0648\u0627\u0628\u0633\u062a\u06af\u06cc \u0628\u0647 \u0627\u0631\u0632 \u062e\u0627\u0631\u062c\u06cc\u00a0<\/b><\/h3><p><span style=\"font-weight: 400;\">\u062d\u0645\u0627\u06cc\u062a \u0627\u0632 \u0633\u0645\u062a \u0639\u0631\u0636\u0647 \u0627\u0642\u062a\u0635\u0627\u062f \u0627\u0632 \u0637\u0631\u06cc\u0642 \u0631\u0641\u0639 \u06af\u0644\u0648\u06af\u0627\u0647\u200c\u0647\u0627\u06cc \u062a\u0648\u0644\u06cc\u062f (\u062a\u0633\u0647\u06cc\u0644 \u062a\u0623\u0645\u06cc\u0646 \u0645\u0648\u0627\u062f \u0627\u0648\u0644\u06cc\u0647 \u0648 \u0627\u0646\u0631\u0698\u06cc) \u0648 \u0628\u0647\u0628\u0648\u062f \u0632\u0646\u062c\u06cc\u0631\u0647\u200c\u0647\u0627\u06cc \u062a\u0623\u0645\u06cc\u0646 \u062f\u0627\u062e\u0644\u06cc\u060c \u0641\u0634\u0627\u0631 \u0628\u0631 \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0631\u0627 \u06a9\u0627\u0647\u0634 \u0645\u06cc\u200c\u062f\u0647\u062f. \u06a9\u0627\u0647\u0634 \u0648\u0627\u0628\u0633\u062a\u06af\u06cc \u0633\u0627\u062e\u062a\u0627\u0631\u06cc \u0628\u0647 \u0648\u0627\u0631\u062f\u0627\u062a\u060c \u0627\u0642\u062a\u0635\u0627\u062f \u0631\u0627 \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u062a\u06a9\u0627\u0646\u0647\u200c\u0647\u0627\u06cc \u0627\u0631\u0632\u06cc \u0645\u0642\u0627\u0648\u0645\u200c\u062a\u0631 \u0645\u06cc\u200c\u06a9\u0646\u062f \u0648 \u0633\u0631\u0639\u062a \u00ab\u0627\u0646\u062a\u0642\u0627\u0644 \u0646\u0631\u062e \u0627\u0631\u0632 \u0628\u0647 \u0642\u06cc\u0645\u062a\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc\u00bb \u0631\u0627 \u06a9\u0627\u0647\u0634 \u0645\u06cc\u200c\u062f\u0647\u062f. \u0647\u062f\u0627\u06cc\u062a \u0645\u0646\u0627\u0628\u0639 \u0628\u0647 \u0633\u0645\u062a \u0628\u062e\u0634\u200c\u0647\u0627\u06cc \u0645\u0648\u0644\u062f \u0628\u0647 \u062c\u0627\u06cc \u0641\u0639\u0627\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc \u062f\u0644\u0627\u0644\u06cc\u060c \u06a9\u0644\u06cc\u062f \u0645\u0648\u0641\u0642\u06cc\u062a \u062f\u0631 \u0627\u06cc\u0646 \u0628\u062e\u0634 \u0627\u0633\u062a.<\/span><\/p><h3><b>\u0628\u0627\u0632\u0633\u0627\u0632\u06cc \u0627\u0639\u062a\u0645\u0627\u062f \u0639\u0645\u0648\u0645\u06cc \u0628\u0647 \u0646\u0638\u0627\u0645 \u067e\u0648\u0644\u06cc\u00a0<\/b><\/h3><p><span style=\"font-weight: 400;\">\u0628\u062f\u0648\u0646 \u0628\u0627\u0632\u06af\u0634\u062a \u0627\u0639\u062a\u0645\u0627\u062f\u060c \u0645\u0631\u062f\u0645 \u0647\u0645\u0686\u0646\u0627\u0646 \u0627\u0632 \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u067e\u0648\u0644 \u0645\u0644\u06cc \u06af\u0631\u06cc\u0632\u0627\u0646 \u062e\u0648\u0627\u0647\u0646\u062f \u0628\u0648\u062f. \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0627\u0628\u0632\u0627\u0631 \u00ab\u0647\u062f\u0627\u06cc\u062a \u0627\u0646\u062a\u0638\u0627\u0631\u0627\u062a\u00bb \u062a\u0648\u0633\u0637 \u0633\u06cc\u0627\u0633\u062a\u200c\u06af\u0630\u0627\u0631\u0627\u0646 \u0648 \u067e\u0631\u0647\u06cc\u0632 \u0627\u0632 \u0648\u0639\u062f\u0647\u200c\u0647\u0627\u06cc \u067e\u0648\u067e\u0648\u0644\u06cc\u0633\u062a\u06cc \u0628\u0631\u0627\u06cc \u0627\u0639\u062a\u0628\u0627\u0631\u0628\u062e\u0634\u06cc \u0645\u062c\u062f\u062f \u0636\u0631\u0648\u0631\u06cc \u0627\u0633\u062a.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">\u062a\u062c\u0631\u0628\u0647\u200c\u0647\u0627\u06cc \u062a\u0627\u0631\u06cc\u062e\u06cc \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u0646\u062f \u06a9\u0647 \u067e\u0633 \u0627\u0632 \u0645\u0647\u0627\u0631 \u0627\u0648\u0644\u06cc\u0647 \u062a\u0648\u0631\u0645\u060c \u0627\u0642\u062f\u0627\u0645\u0627\u062a\u06cc \u0646\u0645\u0627\u062f\u06cc\u0646\u060c \u0627\u0645\u0627 \u0645\u0624\u062b\u0631 \u0645\u0627\u0646\u0646\u062f \u0627\u0635\u0644\u0627\u062d \u0648\u0627\u062d\u062f \u067e\u0648\u0644\u06cc \u06cc\u0627 \u062d\u0630\u0641 \u0635\u0641\u0631 (\u0645\u0634\u0627\u0628\u0647 \u0637\u0631\u062d \u00ab\u0631\u0626\u0627\u0644\u00bb \u0628\u0631\u0632\u06cc\u0644 \u062f\u0631 \u06f1\u06f9\u06f9\u06f4) \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u062a\u062b\u0628\u06cc\u062a \u0631\u0648\u0627\u0646\u06cc \u062c\u0627\u0645\u0639\u0647 \u06a9\u0645\u06a9 \u06a9\u0646\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ed074e8 elementor-widget elementor-widget-text-editor\" data-id=\"ed074e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><b>\u0686\u06af\u0648\u0646\u0647 \u062f\u0631 \u0632\u0645\u0627\u0646 \u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u0627\u0632 \u0633\u0631\u0645\u0627\u06cc\u0647 \u062e\u0648\u062f \u0645\u062d\u0627\u0641\u0638\u062a \u06a9\u0646\u06cc\u0645\u061f<\/b><\/h2>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8407c6e elementor-widget elementor-widget-image\" data-id=\"8407c6e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"759\" height=\"600\" src=\"https:\/\/newwp.aronsos.co\/wp-content\/uploads\/2025\/11\/hyper-inflation-2.jpg\" class=\"attachment-large size-large wp-image-173588\" alt=\"\" srcset=\"https:\/\/newwp.aronsos.co\/wp-content\/uploads\/2025\/11\/hyper-inflation-2.jpg 759w, https:\/\/newwp.aronsos.co\/wp-content\/uploads\/2025\/11\/hyper-inflation-2-300x237.jpg 300w\" sizes=\"(max-width: 759px) 100vw, 759px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7f2316 elementor-widget elementor-widget-text-editor\" data-id=\"d7f2316\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<b>\u062a\u0648\u062c\u0647:<\/b><span style=\"font-weight: 400;\"> \u0627\u06cc\u0646 \u0645\u0637\u0627\u0644\u0628 \u0635\u0631\u0641\u0627 \u062c\u0646\u0628\u0647 \u0622\u0645\u0648\u0632\u0634\u06cc \u062f\u0627\u0631\u062f \u0648 \u062a\u0648\u0635\u06cc\u0647 \u0645\u0627\u0644\u06cc \u06cc\u0627 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u0634\u062e\u0635\u06cc \u0645\u062d\u0633\u0648\u0628 \u0646\u0645\u06cc\u200c\u0634\u0648\u062f.<\/span>\n<ul>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u062a\u0646\u0648\u0639\u200c\u0628\u062e\u0634\u06cc \u0628\u0647 \u0633\u0628\u062f \u062f\u0627\u0631\u0627\u06cc\u06cc:<\/b><span style=\"font-weight: 400;\"> \u0628\u0647 \u062c\u0627\u06cc \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0633\u0631\u0645\u0627\u06cc\u0647 \u0628\u0647 \u06cc\u06a9 \u0634\u06a9\u0644\u060c \u0622\u0646 \u0631\u0627 \u0628\u06cc\u0646 \u0627\u0631\u0632\u0647\u0627\u06cc \u0645\u0639\u062a\u0628\u0631 \u062e\u0627\u0631\u062c\u06cc\u060c \u062f\u0627\u0631\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc \u0648\u0627\u0642\u0639\u06cc (\u0645\u0627\u0646\u0646\u062f \u0645\u0644\u06a9 \u0648 \u06a9\u0627\u0644\u0627\u0647\u0627\u06cc \u0628\u0627\u062f\u0648\u0627\u0645) \u0648 \u062f\u0627\u0631\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc \u062a\u0642\u0633\u06cc\u0645 \u06a9\u0646\u06cc\u062f \u062a\u0627 \u0631\u06cc\u0633\u06a9 \u06a9\u0627\u0647\u0634 \u06cc\u0627\u0628\u062f.<\/span><\/li>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><a style=\"color: #f9c43e;\"href=\"https:\/\/arongroups.co\/fa\/forex\/%D8%B3%D8%B1%D9%85%D8%A7%DB%8C%D9%87-%DA%AF%D8%B0%D8%A7%D8%B1%DB%8C-%D8%AF%D8%B1-%D8%B7%D9%84%D8%A7\/\"><b>\u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u062f\u0631 \u0637\u0644\u0627<\/b><\/a><b>:<\/b><span style=\"font-weight: 400;\"> \u0637\u0644\u0627 \u0628\u0647 \u0637\u0648\u0631 \u062a\u0627\u0631\u06cc\u062e\u06cc \u062f\u0631 \u062f\u0648\u0631\u0647\u200c\u0647\u0627\u06cc \u062a\u0648\u0631\u0645\u06cc \u0646\u0642\u0634 \u00ab\u067e\u0646\u0627\u0647\u06af\u0627\u0647 \u0627\u0645\u0646\u00bb \u0631\u0627 \u062f\u0627\u0634\u062a\u0647 \u0627\u0633\u062a. (\u0627\u0644\u0628\u062a\u0647 \u0647\u0645\u0648\u0627\u0631\u0647 \u0631\u06cc\u0633\u06a9\u200c\u0647\u0627\u06cc \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u0641\u06cc\u0632\u06cc\u06a9\u06cc \u0648 \u0645\u0642\u0631\u0631\u0627\u062a \u062f\u0627\u062e\u0644\u06cc \u0631\u0627 \u062f\u0631 \u0646\u0638\u0631 \u0628\u06af\u06cc\u0631\u06cc\u062f).<\/span><\/li>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u0627\u0646\u062a\u062e\u0627\u0628 \u0633\u0647\u0627\u0645 \u0628\u0627 \u00ab\u0642\u062f\u0631\u062a \u0642\u06cc\u0645\u062a\u200c\u06af\u0630\u0627\u0631\u06cc\u00bb:<\/b><span style=\"font-weight: 400;\"> \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0628\u0648\u0631\u0633\u060c \u0631\u0648\u06cc \u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc\u06cc \u062a\u0645\u0631\u06a9\u0632 \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u0646\u062f \u0647\u0645\u06af\u0627\u0645 \u0628\u0627 \u0631\u0634\u062f \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u060c \u0642\u06cc\u0645\u062a \u0645\u062d\u0635\u0648\u0644\u0627\u062a \u062e\u0648\u062f \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0647\u0646\u062f. \u0628\u0627 \u0627\u06cc\u0646 \u062d\u0627\u0644\u060c \u0645\u0631\u0627\u0642\u0628 \u0646\u0648\u0633\u0627\u0646\u0627\u062a \u0634\u062f\u06cc\u062f \u0648 \u06a9\u0648\u062a\u0627\u0647\u200c \u0645\u062f\u062a \u0628\u0627\u0632\u0627\u0631 \u0633\u0647\u0627\u0645 \u0628\u0627\u0634\u06cc\u062f.<\/span><\/li>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u0627\u0648\u0631\u0627\u0642 \u0645\u062a\u0635\u0644 \u0628\u0647 \u062a\u0648\u0631\u0645:<\/b><span style=\"font-weight: 400;\"> \u062f\u0631 \u0635\u0648\u0631\u062a \u062f\u0633\u062a\u0631\u0633\u06cc (\u0645\u0627\u0646\u0646\u062f \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u06cc \u062c\u0647\u0627\u0646\u06cc)\u060c \u0628\u062e\u0634\u06cc \u0627\u0632 \u0633\u0631\u0645\u0627\u06cc\u0647 \u0631\u0627 \u0628\u0647 \u0627\u0648\u0631\u0627\u0642\u06cc \u0627\u062e\u062a\u0635\u0627\u0635 \u062f\u0647\u06cc\u062f \u06a9\u0647 \u0628\u0627\u0632\u062f\u0647\u06cc \u0622\u0646\u0647\u0627 \u0628\u0647 \u0637\u0648\u0631 \u062e\u0648\u062f\u06a9\u0627\u0631 \u0628\u0627 \u0646\u0631\u062e \u062a\u0648\u0631\u0645 \u062a\u0639\u062f\u06cc\u0644 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/span><\/li>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u0645\u062f\u06cc\u0631\u06cc\u062a \u0647\u0648\u0634\u0645\u0646\u062f \u0627\u0645\u0644\u0627\u06a9:<\/b><span style=\"font-weight: 400;\"> \u062f\u0631 \u0642\u0631\u0627\u0631\u062f\u0627\u062f\u0647\u0627\u06cc \u0627\u062c\u0627\u0631\u0647\u060c \u0628\u0646\u062f\u0647\u0627\u06cc\u06cc \u0628\u0631\u0627\u06cc \u062a\u0639\u062f\u06cc\u0644 \u062f\u0648\u0631\u0647\u200c\u0627\u06cc \u0645\u0628\u0627\u0644\u063a \u0628\u0631 \u0627\u0633\u0627\u0633 \u0634\u0627\u062e\u0635\u200c\u0647\u0627\u06cc \u0645\u0639\u062a\u0628\u0631 \u062a\u0648\u0631\u0645\u06cc \u0628\u06af\u0646\u062c\u0627\u0646\u06cc\u062f \u062a\u0627 \u0627\u0631\u0632\u0634 \u0648\u0627\u0642\u0639\u06cc \u062f\u0631\u0622\u0645\u062f \u0627\u062c\u0627\u0631\u0647 \u062d\u0641\u0638 \u0634\u0648\u062f.<\/span><\/li>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u062d\u0641\u0638 \u0646\u0642\u062f\u06cc\u0646\u06af\u06cc \u0627\u0636\u0637\u0631\u0627\u0631\u06cc:<\/b><span style=\"font-weight: 400;\"> \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u0636\u0631\u0648\u0631\u06cc \u06f3 \u062a\u0627 \u06f6 \u0645\u0627\u0647 \u0622\u06cc\u0646\u062f\u0647 \u0631\u0627 \u0628\u0647 \u0634\u06a9\u0644\u06cc (\u0645\u0627\u0646\u0646\u062f \u0627\u0631\u0632\u0647\u0627\u06cc \u0645\u0639\u062a\u0628\u0631) \u0646\u06af\u0647\u062f\u0627\u0631\u06cc \u06a9\u0646\u06cc\u062f \u06a9\u0647 \u0647\u0645 \u0627\u0631\u0632\u0634 \u0622\u0646 \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0634\u0648\u06a9\u200c\u0647\u0627\u06cc \u0642\u06cc\u0645\u062a\u06cc \u062d\u0641\u0638 \u0634\u0648\u062f \u0648 \u0647\u0645 \u0628\u0647 \u0633\u0631\u0639\u062a \u0642\u0627\u0628\u0644 \u0646\u0642\u062f \u0634\u062f\u0646 \u0628\u0627\u0634\u062f.<\/span><\/li>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u0645\u062f\u06cc\u0631\u06cc\u062a \u0628\u062f\u0647\u06cc\u200c\u0647\u0627:<\/b><span style=\"font-weight: 400;\"> \u062f\u0631 \u0627\u0628\u0631\u062a\u0648\u0631\u0645\u060c \u0627\u0631\u0632\u0634 \u0648\u0627\u0642\u0639\u06cc \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u0628\u0627 \u0646\u0631\u062e \u0628\u0647\u0631\u0647 \u062b\u0627\u0628\u062a \u06a9\u0627\u0647\u0634 \u0645\u06cc\u200c\u06cc\u0627\u0628\u062f (\u0628\u0647 \u0646\u0641\u0639 \u0648\u0627\u0645\u200c\u06af\u06cc\u0631\u0646\u062f\u0647)\u060c \u0627\u0645\u0627 \u0646\u0628\u0627\u06cc\u062f \u0631\u06cc\u0633\u06a9\u200c\u0647\u0627\u06cc \u062a\u063a\u06cc\u06cc\u0631 \u0646\u0631\u062e \u0628\u0647\u0631\u0647 \u062a\u0648\u0633\u0637 \u0628\u0627\u0646\u06a9\u200c\u0647\u0627 \u0648 \u06a9\u0627\u0647\u0634 \u062a\u0648\u0627\u0646 \u0628\u0627\u0632\u067e\u0631\u062f\u0627\u062e\u062a \u062e\u0648\u062f \u0631\u0627 \u0646\u0627\u062f\u06cc\u062f\u0647 \u0628\u06af\u06cc\u0631\u06cc\u062f.<\/span><\/li>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u0628\u0648\u062f\u062c\u0647\u200c\u0631\u06cc\u0632\u06cc \u06a9\u0648\u062a\u0627\u0647\u200c \u0645\u062f\u062a:<\/b><span style=\"font-weight: 400;\"> \u062f\u0631 \u0634\u0631\u0627\u06cc\u0637 \u062a\u063a\u06cc\u06cc\u0631 \u0633\u0631\u06cc\u0639 \u0642\u06cc\u0645\u062a\u200c\u0647\u0627\u060c \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc \u0633\u0627\u0644\u0627\u0646\u0647 \u06a9\u0627\u0631\u0627\u06cc\u06cc \u0646\u062f\u0627\u0631\u0646\u062f. \u0628\u0648\u062f\u062c\u0647 \u062e\u0648\u062f \u0631\u0627 \u0628\u0647 \u0635\u0648\u0631\u062a \u0645\u0627\u0647\u0627\u0646\u0647 \u06cc\u0627 \u0641\u0635\u0644\u06cc \u0628\u0627\u0632\u0628\u06cc\u0646\u06cc \u0648 \u0628\u0627 \u0642\u06cc\u0645\u062a\u200c\u0647\u0627\u06cc \u0631\u0648\u0632 \u062a\u0646\u0638\u06cc\u0645 \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u0628\u0647\u200c\u0631\u0648\u0632\u0631\u0633\u0627\u0646\u06cc \u0628\u06cc\u0645\u0647\u200c\u0647\u0627:<\/b><span style=\"font-weight: 400;\"> \u0628\u0627 \u062a\u0648\u062c\u0647 \u0628\u0647 \u062c\u0647\u0634 \u0642\u06cc\u0645\u062a\u200c\u0647\u0627\u060c \u0633\u0642\u0641 \u062a\u0639\u0647\u062f\u0627\u062a \u0628\u06cc\u0645\u0647\u200c\u0646\u0627\u0645\u0647\u200c\u0647\u0627\u06cc \u062e\u0648\u062f (\u0645\u0627\u0646\u0646\u062f \u0628\u06cc\u0645\u0647 \u0627\u0645\u0648\u0627\u0644 \u06cc\u0627 \u0639\u0645\u0631) \u0631\u0627 \u0645\u0631\u062a\u0628\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0647\u06cc\u062f \u062a\u0627 \u062f\u0631 \u0635\u0648\u0631\u062a \u0648\u0642\u0648\u0639 \u062d\u0627\u062f\u062b\u0647\u060c \u062e\u0633\u0627\u0631\u062a \u0628\u0647 \u0627\u0631\u0632\u0634 \u0648\u0627\u0642\u0639\u06cc \u0631\u0648\u0632 \u062c\u0628\u0631\u0627\u0646 \u0634\u0648\u062f.<\/span><\/li>\n \t<li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u0627\u0646\u0636\u0628\u0627\u0637 \u0627\u0637\u0644\u0627\u0639\u0627\u062a\u06cc:<\/b><span style=\"font-weight: 400;\"> \u0628\u0631\u0627\u06cc \u062a\u0635\u0645\u06cc\u0645\u200c\u06af\u06cc\u0631\u06cc\u060c \u0628\u0647 \u062c\u0627\u06cc \u0634\u0627\u06cc\u0639\u0627\u062a\u060c \u0631\u0648\u0646\u062f\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0631\u0627 \u0627\u0632 \u0645\u0646\u0627\u0628\u0639 \u0645\u0639\u062a\u0628\u0631 \u0648 \u062f\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u0631\u0633\u0645\u06cc (\u0645\u0627\u0646\u0646\u062f \u06af\u0632\u0627\u0631\u0634\u200c\u0647\u0627\u06cc \u0646\u0647\u0627\u062f\u0647\u0627\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc) \u062f\u0646\u0628\u0627\u0644 \u06a9\u0646\u06cc\u062f.<\/span><\/li>\n<\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3652c6 elementor-widget elementor-widget-text-editor\" data-id=\"c3652c6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><b>\u062a\u062c\u0631\u0628\u0647 \u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u062f\u0631 \u0627\u06cc\u0631\u0627\u0646\u061b \u0648\u0627\u0642\u0639\u06cc\u062a \u06cc\u0627 \u062a\u0647\u062f\u06cc\u062f \u0628\u0627\u0644\u0642\u0648\u0647\u061f<\/b><\/h2><p><span style=\"font-weight: 400;\">\u062f\u0631 \u062d\u0627\u0644 \u062d\u0627\u0636\u0631\u060c \u0627\u0642\u062a\u0635\u0627\u062f \u0627\u06cc\u0631\u0627\u0646 \u0628\u0627 \u062a\u0648\u0631\u0645 \u0628\u0627\u0644\u0627 \u0648 \u0645\u0632\u0645\u0646 \u0631\u0648\u0628\u0647\u200c\u0631\u0648 \u0627\u0633\u062a\u060c \u0646\u0647 \u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u06a9\u0627\u0645\u0644. \u0628\u0631\u0627\u0633\u0627\u0633 <\/span><a href=\"https:\/\/www.amar.org.ir\/\" target=\"_blank\" rel=\"nofollow noopener\"><span style=\"font-weight: 400;\">\u0645\u0631\u06a9\u0632 \u0622\u0645\u0627\u0631 \u0627\u06cc\u0631\u0627\u0646<\/span><\/a><span style=\"font-weight: 400;\">\u060c \u0646\u0631\u062e \u062a\u0648\u0631\u0645 \u0633\u0627\u0644\u0627\u0646\u0647 \u062a\u0627 \u0633\u067e\u062a\u0627\u0645\u0628\u0631 \u06f2\u06f0\u06f2\u06f5 \u0628\u0647 \u06f4\u06f5.\u06f3 \u062f\u0631\u0635\u062f \u0631\u0633\u06cc\u062f\u0647 \u0648 \u062a\u0648\u0631\u0645 \u0645\u0627\u0647\u0627\u0646\u0647 \u0646\u06cc\u0632 \u0628\u0647 \u06f3.\u06f8 \u062f\u0631\u0635\u062f \u0627\u0641\u0632\u0627\u06cc\u0634 \u06cc\u0627\u0641\u062a\u0647 \u0627\u0633\u062a\u061b \u0627\u0631\u0642\u0627\u0645\u06cc \u06a9\u0647 \u0646\u0634\u0627\u0646 \u0627\u0632 \u0641\u0634\u0627\u0631 \u0634\u062f\u06cc\u062f \u0628\u0631 \u0645\u0639\u06cc\u0634\u062a \u0645\u0631\u062f\u0645 \u0648 \u06a9\u0627\u0647\u0634 \u0645\u062f\u0627\u0648\u0645 \u0642\u062f\u0631\u062a \u062e\u0631\u06cc\u062f \u062f\u0627\u0631\u0646\u062f. \u0628\u0627 \u0627\u06cc\u0646\u200c \u062d\u0627\u0644\u060c \u0637\u0628\u0642 \u062a\u0639\u0631\u06cc\u0641 \u0641\u06cc\u0644\u067e \u06a9\u0627\u06af\u0627\u0646\u060c \u062a\u0627 \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u062a\u0648\u0631\u0645 \u0645\u0627\u0647\u0627\u0646\u0647 \u0627\u0632 \u06f5\u06f0 \u062f\u0631\u0635\u062f \u0641\u0631\u0627\u062a\u0631 \u0646\u0631\u0648\u062f \u0648 \u0627\u0639\u062a\u0645\u0627\u062f \u0639\u0645\u0648\u0645\u06cc \u0628\u0647 \u067e\u0648\u0644 \u0645\u0644\u06cc \u0628\u0647 \u0635\u0648\u0631\u062a \u06af\u0633\u062a\u0631\u062f\u0647 \u0641\u0631\u0648 \u0646\u067e\u0627\u0634\u062f\u060c \u0646\u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0648\u0636\u0639\u06cc\u062a \u0641\u0639\u0644\u06cc \u0631\u0627 \u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u062f\u0627\u0646\u0633\u062a.<\/span><\/p><p><b>\u0628\u0646\u0627\u0628\u0631\u0627\u06cc\u0646\u060c \u0627\u06cc\u0631\u0627\u0646 \u062f\u0631 \u0645\u0631\u0632 \u0647\u0634\u062f\u0627\u0631 \u0642\u0631\u0627\u0631 \u062f\u0627\u0631\u062f. <\/b><span style=\"font-weight: 400;\">\u0634\u0631\u0627\u06cc\u0637\u06cc \u06a9\u0647 \u0627\u06af\u0631 \u0627\u0635\u0644\u0627\u062d \u0633\u06cc\u0627\u0633\u062a\u200c\u0647\u0627\u06cc \u067e\u0648\u0644\u06cc\u060c \u06a9\u0646\u062a\u0631\u0644 \u0646\u0642\u062f\u06cc\u0646\u06af\u06cc \u0648 \u062a\u0631\u0645\u06cc\u0645 \u0627\u0639\u062a\u0645\u0627\u062f \u0639\u0645\u0648\u0645\u06cc \u0628\u0647 \u062a\u0639\u0648\u06cc\u0642 \u0628\u06cc\u0641\u062a\u062f\u060c \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0628\u0647 \u0633\u0631\u0639\u062a \u0628\u0647 \u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u0648\u0627\u0642\u0639\u06cc \u0645\u0646\u062c\u0631 \u0634\u0648\u062f. \u062f\u0631 \u0686\u0646\u06cc\u0646 \u0641\u0636\u0627\u06cc\u06cc\u060c \u0645\u062f\u06cc\u0631\u06cc\u062a \u0627\u0646\u062a\u0638\u0627\u0631\u0627\u062a \u062a\u0648\u0631\u0645\u06cc \u0648 \u062a\u0642\u0648\u06cc\u062a \u062a\u0648\u0644\u06cc\u062f \u062f\u0627\u062e\u0644\u06cc\u060c \u062d\u06cc\u0627\u062a\u06cc\u200c\u062a\u0631\u06cc\u0646 \u0627\u0628\u0632\u0627\u0631\u0647\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0633\u0642\u0648\u0637 \u0627\u0631\u0632\u0634 \u067e\u0648\u0644 \u0648 \u0628\u06cc\u200c\u062b\u0628\u0627\u062a\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0645\u062d\u0633\u0648\u0628 \u0645\u06cc\u200c\u0634\u0648\u0646\u062f.<\/span><\/p><h2><b>\u0646\u0645\u0648\u0646\u0647\u200c\u0647\u0627\u06cc \u062c\u0647\u0627\u0646\u06cc \u0627\u0628\u0631\u062a\u0648\u0631\u0645<\/b><\/h2><p><span style=\"font-weight: 400;\">\u062f\u0631 \u0627\u06cc\u0646\u062c\u0627 \u0644\u06cc\u0633\u062a\u06cc \u0627\u0632 \u0628\u0631\u062e\u06cc \u0627\u0632 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u0648 \u0645\u0639\u0631\u0648\u0641\u200c\u062a\u0631\u06cc\u0646 \u0646\u0645\u0648\u0646\u0647\u200c\u0647\u0627\u06cc \u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u062f\u0631 \u062a\u0627\u0631\u06cc\u062e \u062c\u0647\u0627\u0646 \u0628\u0647 \u0647\u0645\u0631\u0627\u0647 \u062a\u0648\u0636\u06cc\u062d\u06cc \u0645\u062e\u062a\u0635\u0631 \u0628\u0631\u0627\u06cc \u0647\u0631 \u06a9\u062f\u0627\u0645 \u0622\u0645\u062f\u0647 \u0627\u0633\u062a:<\/span><\/p><h3><b>\u0622\u0644\u0645\u0627\u0646 (\u062c\u0645\u0647\u0648\u0631\u06cc \u0648\u0627\u06cc\u0645\u0627\u0631) &#8211; \u06f1\u06f9\u06f2\u06f3<\/b><\/h3><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u062f\u0648\u0631\u0647 \u0632\u0645\u0627\u0646\u06cc:<\/b><span style=\"font-weight: 400;\"> \u06f1\u06f9\u06f2\u06f1 \u062a\u0627 \u06f1\u06f9\u06f2\u06f3<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u0646\u0642\u0637\u0647 \u0627\u0648\u062c:<\/b><span style=\"font-weight: 400;\"> \u0646\u0648\u0627\u0645\u0628\u0631 \u06f1\u06f9\u06f2\u06f3<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">\u067e\u0633 \u0627\u0632 \u062c\u0646\u06af \u062c\u0647\u0627\u0646\u06cc \u0627\u0648\u0644\u060c \u0622\u0644\u0645\u0627\u0646 \u0628\u0631\u0627\u06cc \u067e\u0631\u062f\u0627\u062e\u062a \u063a\u0631\u0627\u0645\u062a\u200c\u0647\u0627\u06cc \u0633\u0646\u06af\u06cc\u0646 \u062c\u0646\u06af\u06cc \u0634\u0631\u0648\u0639 \u0628\u0647 \u0686\u0627\u067e \u0628\u06cc\u200c\u0631\u0648\u06cc\u0647 \u067e\u0648\u0644 \u06a9\u0631\u062f. \u0627\u06cc\u0646 \u06a9\u0627\u0631 \u0645\u0646\u062c\u0631 \u0628\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0634\u0647\u0648\u0631\u062a\u0631\u06cc\u0646 \u0627\u0628\u0631\u062a\u0648\u0631\u0645\u200c\u0647\u0627\u06cc \u062a\u0627\u0631\u06cc\u062e \u0634\u062f. \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0628\u0647 \u0642\u062f\u0631\u06cc \u0633\u0631\u06cc\u0639 \u0628\u0627\u0644\u0627 \u0645\u06cc\u200c\u0631\u0641\u062a\u0646\u062f \u06a9\u0647 \u0645\u0631\u062f\u0645 \u062d\u0642\u0648\u0642 \u062e\u0648\u062f \u0631\u0627 \u0628\u0627 \u0686\u0645\u062f\u0627\u0646 \u06cc\u0627 \u0641\u0631\u063a\u0648\u0646 \u062d\u0645\u0644 \u0645\u06cc\u200c\u06a9\u0631\u062f\u0646\u062f \u0648 \u0628\u0644\u0627\u0641\u0627\u0635\u0644\u0647 \u0622\u0646 \u0631\u0627 \u062e\u0631\u062c \u0645\u06cc\u200c\u06a9\u0631\u062f\u0646\u062f. \u062f\u0631 \u0627\u0648\u062c \u0628\u062d\u0631\u0627\u0646\u060c \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0647\u0631 \u0686\u0646\u062f \u0631\u0648\u0632 \u06cc\u06a9 \u0628\u0627\u0631 \u062f\u0648 \u0628\u0631\u0627\u0628\u0631 \u0645\u06cc\u200c\u0634\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1df283f elementor-widget elementor-widget-text-editor\" data-id=\"1df283f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><b>\u0645\u062c\u0627\u0631\u0633\u062a\u0627\u0646 &#8211; \u06f1\u06f9\u06f4\u06f5-\u06f1\u06f9\u06f4\u06f6<\/b><\/h3><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u062f\u0648\u0631\u0647 \u0632\u0645\u0627\u0646\u06cc:<\/b><span style=\"font-weight: 400;\"> \u06f1\u06f9\u06f4\u06f5 \u062a\u0627 \u06f1\u06f9\u06f4\u06f6<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u0646\u0642\u0637\u0647 \u0627\u0648\u062c:<\/b><span style=\"font-weight: 400;\"> \u0698\u0648\u0626\u06cc\u0647 \u06f1\u06f9\u06f4\u06f6<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">\u0645\u062c\u0627\u0631\u0633\u062a\u0627\u0646 \u067e\u0633 \u0627\u0632 \u062c\u0646\u06af \u062c\u0647\u0627\u0646\u06cc \u062f\u0648\u0645 \u0628\u062f\u062a\u0631\u06cc\u0646 \u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u062b\u0628\u062a \u0634\u062f\u0647 \u062f\u0631 \u062a\u0627\u0631\u06cc\u062e \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0631\u062f. \u062c\u0646\u06af\u060c \u0646\u0627\u0628\u0648\u062f\u06cc \u0632\u06cc\u0631\u0633\u0627\u062e\u062a\u200c\u0647\u0627 \u0648 \u067e\u0631\u062f\u0627\u062e\u062a \u063a\u0631\u0627\u0645\u062a \u0628\u0647 \u0634\u0648\u0631\u0648\u06cc \u0627\u0642\u062a\u0635\u0627\u062f \u0631\u0627 \u0641\u0644\u062c \u06a9\u0631\u062f\u0647 \u0628\u0648\u062f. \u062f\u0631 \u0627\u0648\u062c \u062a\u0648\u0631\u0645\u060c \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0647\u0631 \u06f1\u06f5 \u0633\u0627\u0639\u062a \u062f\u0648 \u0628\u0631\u0627\u0628\u0631 \u0645\u06cc\u200c\u0634\u062f. \u062f\u0648\u0644\u062a \u0627\u0633\u06a9\u0646\u0627\u0633\u200c\u0647\u0627\u06cc\u06cc \u0628\u0627 \u0627\u0631\u0642\u0627\u0645 \u0646\u062c\u0648\u0645\u06cc (\u0645\u0627\u0646\u0646\u062f \u06f1\u06f0\u06f0 \u06a9\u0648\u06cc\u0646\u062a\u06cc\u0644\u06cc\u0648\u0646 \u067e\u0646\u06af\u0648) \u0686\u0627\u067e \u06a9\u0631\u062f \u062a\u0627 \u0627\u06cc\u0646\u06a9\u0647 \u062f\u0631 \u0646\u0647\u0627\u06cc\u062a \u067e\u0648\u0644 \u062c\u062f\u06cc\u062f (\u0641\u0648\u0631\u06cc\u0646\u062a) \u062c\u0627\u06cc\u06af\u0632\u06cc\u0646 \u0634\u062f.<\/span><\/p><h3><b>\u0632\u06cc\u0645\u0628\u0627\u0628\u0648\u0647 &#8211; \u0627\u0648\u0627\u062e\u0631 \u062f\u0647\u0647 \u06f2\u06f0\u06f0\u06f0<\/b><\/h3><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u062f\u0648\u0631\u0647 \u0632\u0645\u0627\u0646\u06cc:<\/b><span style=\"font-weight: 400;\"> \u062d\u062f\u0648\u062f \u06f2\u06f0\u06f0\u06f7 \u062a\u0627 \u06f2\u06f0\u06f0\u06f8<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u0646\u0642\u0637\u0647 \u0627\u0648\u062c:<\/b><span style=\"font-weight: 400;\"> \u0646\u0648\u0627\u0645\u0628\u0631 \u06f2\u06f0\u06f0\u06f8<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">\u0633\u06cc\u0627\u0633\u062a\u200c\u0647\u0627\u06cc \u063a\u0644\u0637 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc\u060c \u0627\u0635\u0644\u0627\u062d\u0627\u062a \u0627\u0631\u0636\u06cc \u0646\u0627\u0645\u0648\u0641\u0642 \u0648 \u0686\u0627\u067e \u0628\u06cc\u200c\u0631\u0648\u06cc\u0647 \u067e\u0648\u0644 \u062a\u0648\u0633\u0637 \u062f\u0648\u0644\u062a \u0645\u0648\u06af\u0627\u0628\u0647 \u0645\u0646\u062c\u0631 \u0628\u0647 \u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u0634\u062f\u06cc\u062f\u06cc \u0634\u062f. \u0646\u0631\u062e \u062a\u0648\u0631\u0645 \u0628\u0647 \u0642\u062f\u0631\u06cc \u0628\u0627\u0644\u0627 \u0631\u0641\u062a \u06a9\u0647 \u0627\u0633\u06a9\u0646\u0627\u0633 \u06f1\u06f0\u06f0 \u062a\u0631\u06cc\u0644\u06cc\u0648\u0646 \u062f\u0644\u0627\u0631\u06cc \u0686\u0627\u067e \u0634\u062f \u06a9\u0647 \u0639\u0645\u0644\u0627 \u0627\u0631\u0632\u0634\u06cc \u0646\u062f\u0627\u0634\u062a. \u062f\u0631 \u0646\u0647\u0627\u06cc\u062a\u060c \u0632\u06cc\u0645\u0628\u0627\u0628\u0648\u0647 \u067e\u0648\u0644 \u0645\u0644\u06cc \u062e\u0648\u062f \u0631\u0627 \u0631\u0647\u0627 \u06a9\u0631\u062f \u0648 \u0627\u0632 \u0627\u0631\u0632\u0647\u0627\u06cc \u062e\u0627\u0631\u062c\u06cc \u0645\u0627\u0646\u0646\u062f \u062f\u0644\u0627\u0631 \u0622\u0645\u0631\u06cc\u06a9\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0646\u0645\u0648\u062f.<\/span><\/p><h3><b>\u00a0\u06cc\u0648\u06af\u0633\u0644\u0627\u0648\u06cc &#8211; \u0627\u0648\u0627\u06cc\u0644 \u062f\u0647\u0647 \u06f1\u06f9\u06f9\u06f0<\/b><\/h3><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u062f\u0648\u0631\u0647 \u0632\u0645\u0627\u0646\u06cc:<\/b><span style=\"font-weight: 400;\"> \u06f1\u06f9\u06f9\u06f2 \u062a\u0627 \u06f1\u06f9\u06f9\u06f4<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u0646\u0642\u0637\u0647 \u0627\u0648\u062c:<\/b><span style=\"font-weight: 400;\"> \u0698\u0627\u0646\u0648\u06cc\u0647 \u06f1\u06f9\u06f9\u06f4<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">\u0641\u0631\u0648\u067e\u0627\u0634\u06cc \u06cc\u0648\u06af\u0633\u0644\u0627\u0648\u06cc\u060c \u062c\u0646\u06af\u200c\u0647\u0627\u06cc \u062f\u0627\u062e\u0644\u06cc\u060c \u062a\u062d\u0631\u06cc\u0645\u200c\u0647\u0627\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u0648 \u0633\u0648\u0621 \u0645\u062f\u06cc\u0631\u06cc\u062a \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0628\u0627\u0639\u062b \u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u0634\u062f\u06cc\u062f \u062f\u0631 \u062c\u0645\u0647\u0648\u0631\u06cc \u0641\u062f\u0631\u0627\u0644 \u06cc\u0648\u06af\u0633\u0644\u0627\u0648\u06cc (\u0635\u0631\u0628\u0633\u062a\u0627\u0646 \u0648 \u0645\u0648\u0646\u062a\u0647\u200c\u0646\u06af\u0631\u0648) \u0634\u062f. \u062f\u0648\u0644\u062a \u0628\u0631\u0627\u06cc \u062a\u0623\u0645\u06cc\u0646 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u062c\u0646\u06af \u0648 \u06a9\u0633\u0631\u06cc \u0628\u0648\u062f\u062c\u0647 \u0628\u0647 \u0686\u0627\u067e \u067e\u0648\u0644 \u0631\u0648\u06cc \u0622\u0648\u0631\u062f. \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0631\u0648\u0632\u0627\u0646\u0647 \u0628\u0647 \u0634\u062f\u062a \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u06cc\u200c\u06cc\u0627\u0641\u062a\u0646\u062f.<\/span><\/p><h3><b>\u00a0\u0648\u0646\u0632\u0648\u0626\u0644\u0627 &#8211; \u0627\u0632 \u06f2\u06f0\u06f1\u06f6 \u062a\u0627\u06a9\u0646\u0648\u0646<\/b><\/h3><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u062f\u0648\u0631\u0647 \u0632\u0645\u0627\u0646\u06cc:<\/b><span style=\"font-weight: 400;\"> \u0627\u0632 \u062d\u062f\u0648\u062f \u06f2\u06f0\u06f1\u06f6 \u0622\u063a\u0627\u0632 \u0634\u062f\u0647 \u0648 \u0647\u0645\u0686\u0646\u0627\u0646 \u0627\u062f\u0627\u0645\u0647 \u062f\u0627\u0631\u062f (\u0628\u0627 \u0646\u0648\u0633\u0627\u0646).<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">\u06a9\u0627\u0647\u0634 \u0634\u062f\u06cc\u062f \u0642\u06cc\u0645\u062a \u0646\u0641\u062a (\u0645\u0646\u0628\u0639 \u0627\u0635\u0644\u06cc \u062f\u0631\u0622\u0645\u062f \u06a9\u0634\u0648\u0631)\u060c \u0633\u0648\u0621 \u0645\u062f\u06cc\u0631\u06cc\u062a \u0627\u0642\u062a\u0635\u0627\u062f\u06cc\u060c \u0641\u0633\u0627\u062f \u0648 \u062a\u062d\u0631\u06cc\u0645\u200c\u0647\u0627 \u0645\u0646\u062c\u0631 \u0628\u0647 \u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u062f\u0631 \u0648\u0646\u0632\u0648\u0626\u0644\u0627 \u0634\u062f\u0647 \u0627\u0633\u062a. \u0627\u0631\u0632\u0634 \u067e\u0648\u0644 \u0645\u0644\u06cc (\u0628\u0648\u0644\u06cc\u0648\u0627\u0631) \u0628\u0647 \u0634\u062f\u062a \u0633\u0642\u0648\u0637 \u06a9\u0631\u062f\u0647 \u0648 \u0645\u0631\u062f\u0645 \u0628\u0627 \u06a9\u0645\u0628\u0648\u062f \u0634\u062f\u06cc\u062f \u0645\u0648\u0627\u062f \u063a\u0630\u0627\u06cc\u06cc \u0648 \u062f\u0627\u0631\u0648\u06cc\u06cc \u0645\u0648\u0627\u062c\u0647 \u0647\u0633\u062a\u0646\u062f. \u062f\u0648\u0644\u062a \u0628\u0627\u0631\u0647\u0627 \u0627\u0642\u062f\u0627\u0645 \u0628\u0647 \u062d\u0630\u0641 \u0635\u0641\u0631 \u0627\u0632 \u067e\u0648\u0644 \u0645\u0644\u06cc \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a.<\/span><\/p><h3><b>\u0622\u0631\u0698\u0627\u0646\u062a\u06cc\u0646 &#8211; \u062f\u0648\u0631\u0647\u200c\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641<\/b><\/h3><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u062f\u0648\u0631\u0647 \u0632\u0645\u0627\u0646\u06cc:<\/b><span style=\"font-weight: 400;\"> \u0622\u0631\u0698\u0627\u0646\u062a\u06cc\u0646 \u0686\u0646\u062f\u06cc\u0646 \u062f\u0648\u0631\u0647 \u062a\u0648\u0631\u0645 \u0628\u0633\u06cc\u0627\u0631 \u0628\u0627\u0644\u0627 \u0648 \u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u0631\u0627 \u062a\u062c\u0631\u0628\u0647 \u06a9\u0631\u062f\u0647 \u0627\u0633\u062a\u060c \u0627\u0632 \u062c\u0645\u0644\u0647 \u062f\u0631 \u0627\u0648\u0627\u062e\u0631 \u062f\u0647\u0647 \u06f1\u06f9\u06f8\u06f0 \u0648 \u0628\u062d\u0631\u0627\u0646\u200c\u0647\u0627\u06cc \u0627\u062e\u06cc\u0631.<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">\u062a\u0631\u06a9\u06cc\u0628\u06cc \u0627\u0632 \u0628\u062f\u0647\u06cc\u200c\u0647\u0627\u06cc \u062e\u0627\u0631\u062c\u06cc \u0633\u0646\u06af\u06cc\u0646\u060c \u06a9\u0633\u0631\u06cc \u0628\u0648\u062f\u062c\u0647 \u0645\u0632\u0645\u0646\u060c \u0628\u06cc\u200c\u062b\u0628\u0627\u062a\u06cc \u0633\u06cc\u0627\u0633\u06cc \u0648 \u0639\u062f\u0645 \u0627\u0639\u062a\u0645\u0627\u062f \u0628\u0647 \u067e\u0648\u0644 \u0645\u0644\u06cc \u0628\u0627\u0639\u062b \u0634\u062f\u0647 \u0622\u0631\u0698\u0627\u0646\u062a\u06cc\u0646 \u0628\u0627\u0631\u0647\u0627 \u062f\u0686\u0627\u0631 \u0628\u062d\u0631\u0627\u0646\u200c\u0647\u0627\u06cc \u062a\u0648\u0631\u0645\u06cc \u0634\u0648\u062f. \u062f\u0631 \u0633\u0627\u0644\u200c\u0647\u0627\u06cc \u0627\u062e\u06cc\u0631 \u0646\u06cc\u0632 \u0646\u0631\u062e \u062a\u0648\u0631\u0645 \u0633\u0627\u0644\u0627\u0646\u0647 \u0628\u0633\u06cc\u0627\u0631 \u0628\u0627\u0644\u0627 (\u0628\u06cc\u0634 \u0627\u0632 \u06f1\u06f0\u06f0 \u062f\u0631\u0635\u062f) \u0628\u0648\u062f\u0647 \u0627\u0633\u062a.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee439e6 elementor-widget elementor-widget-text-editor\" data-id=\"ee439e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><b>\u0633\u0627\u06cc\u0631 \u0646\u0645\u0648\u0646\u0647\u200c\u0647\u0627\u06cc \u0642\u0627\u0628\u0644 \u062a\u0648\u062c\u0647:<\/b><\/h3><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u0686\u06cc\u0646 (\u06f1\u06f9\u06f4\u06f8-\u06f1\u06f9\u06f4\u06f9):<\/b><span style=\"font-weight: 400;\"> \u062f\u0631 \u062f\u0648\u0631\u0627\u0646 \u062c\u0646\u06af \u062f\u0627\u062e\u0644\u06cc\u060c \u062f\u0648\u0644\u062a \u0645\u0644\u06cc\u200c\u06af\u0631\u0627 \u0628\u0631\u0627\u06cc \u062a\u0623\u0645\u06cc\u0646 \u0647\u0632\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u062c\u0646\u06af \u0627\u0642\u062f\u0627\u0645 \u0628\u0647 \u0686\u0627\u067e \u067e\u0648\u0644 \u06a9\u0631\u062f \u06a9\u0647 \u0645\u0646\u062c\u0631 \u0628\u0647 \u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u0648 \u062f\u0631 \u0646\u0647\u0627\u06cc\u062a \u0641\u0631\u0648\u067e\u0627\u0634\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0648 \u067e\u06cc\u0631\u0648\u0632\u06cc \u06a9\u0645\u0648\u0646\u06cc\u0633\u062a\u200c\u0647\u0627 \u0634\u062f.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u0628\u0648\u0644\u06cc\u0648\u06cc (\u06f1\u06f9\u06f8\u06f4-\u06f1\u06f9\u06f8\u06f5):<\/b><span style=\"font-weight: 400;\"> \u0628\u062d\u0631\u0627\u0646 \u0628\u062f\u0647\u06cc \u0648 \u06a9\u0633\u0631\u06cc \u0628\u0648\u062f\u062c\u0647 \u0645\u0646\u062c\u0631 \u0628\u0647 \u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u0634\u062f \u06a9\u0647 \u0628\u0627 \u0627\u0635\u0644\u0627\u062d\u0627\u062a \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0634\u062f\u06cc\u062f \u0645\u0647\u0627\u0631 \u06af\u0631\u062f\u06cc\u062f.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u06cc\u0648\u0646\u0627\u0646 (\u06f1\u06f9\u06f4\u06f1-\u06f1\u06f9\u06f4\u06f4):<\/b><span style=\"font-weight: 400;\"> \u062f\u0631 \u062f\u0648\u0631\u0627\u0646 \u0627\u0634\u063a\u0627\u0644 \u062a\u0648\u0633\u0637 \u0622\u0644\u0645\u0627\u0646 \u0646\u0627\u0632\u06cc\u060c \u063a\u0627\u0631\u062a \u0645\u0646\u0627\u0628\u0639 \u0648 \u0686\u0627\u067e \u067e\u0648\u0644 \u062a\u0648\u0633\u0637 \u0627\u0634\u063a\u0627\u0644\u06af\u0631\u0627\u0646 \u0645\u0646\u062c\u0631 \u0628\u0647 \u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u0634\u062f\u06cc\u062f \u0634\u062f.<\/span><\/li><\/ul><h2><b>\u0646\u062a\u06cc\u062c\u0647\u200c\u06af\u06cc\u0631\u06cc<\/b><\/h2><p><span style=\"font-weight: 400;\">\u0627\u0628\u0631\u062a\u0648\u0631\u0645\u060c \u067e\u062f\u06cc\u062f\u0647\u200c\u0627\u06cc \u0648\u06cc\u0631\u0627\u0646\u06af\u0631 \u0627\u0633\u062a \u06a9\u0647 \u0628\u0647 \u0633\u0631\u0639\u062a \u0631\u0641\u0627\u0647 \u062c\u0627\u0645\u0639\u0647 \u0631\u0627 \u0627\u0632 \u0628\u06cc\u0646 \u0645\u06cc\u200c\u0628\u0631\u062f \u0648 \u0627\u0639\u062a\u0645\u0627\u062f \u0639\u0645\u0648\u0645\u06cc \u0631\u0627 \u0646\u0627\u0628\u0648\u062f \u0645\u06cc\u200c\u06a9\u0646\u062f. \u062e\u0637 \u0645\u0642\u062f\u0645 \u0645\u0628\u0627\u0631\u0632\u0647 \u0628\u0627 \u0627\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646\u060c \u0628\u0631\u0642\u0631\u0627\u0631\u06cc \u0627\u0646\u0636\u0628\u0627\u0637 \u0645\u0627\u0644\u06cc \u0648 \u067e\u0648\u0644\u06cc\u060c \u062a\u0636\u0645\u06cc\u0646 \u0627\u0633\u062a\u0642\u0644\u0627\u0644 \u0628\u0627\u0646\u06a9 \u0645\u0631\u06a9\u0632\u06cc \u0648 \u062a\u0644\u0627\u0634 \u0628\u0631\u0627\u06cc \u0628\u0627\u0632\u0633\u0627\u0632\u06cc \u0627\u0639\u062a\u0645\u0627\u062f \u0627\u0632 \u062f\u0633\u062a \u0631\u0641\u062a\u0647 \u0627\u0633\u062a.<\/span><\/p><p><span style=\"font-weight: 400;\">\u0628\u0631\u0627\u06cc \u062d\u0641\u0638 \u0633\u0631\u0645\u0627\u06cc\u0647 \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0627\u06cc\u0646 \u062a\u0648\u0641\u0627\u0646 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc\u060c \u062e\u0627\u0646\u0648\u0627\u0631\u0647\u0627 \u0648 \u06a9\u0633\u0628\u200c\u0648\u06a9\u0627\u0631\u0647\u0627 \u0628\u0627\u06cc\u062f \u0628\u0647 \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u0639\u0645\u0644\u06cc \u0645\u0627\u0646\u0646\u062f <\/span><a href=\"https:\/\/arongroups.co\/fa\/technical\/diversification-strategy\/\"><span style=\"font-weight: 400;\">\u062a\u0646\u0648\u0639\u200c\u0628\u062e\u0634\u06cc \u0628\u0647 \u0633\u0628\u062f \u062f\u0627\u0631\u0627\u06cc\u06cc<\/span><\/a><span style=\"font-weight: 400;\"> (\u0634\u0627\u0645\u0644 \u0627\u0631\u0632 \u0648 \u062f\u0627\u0631\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc \u0641\u06cc\u0632\u06cc\u06a9\u06cc)\u060c \u062a\u0646\u0638\u06cc\u0645 \u0642\u0631\u0627\u0631\u062f\u0627\u062f\u0647\u0627 \u0628\u0631 \u0627\u0633\u0627\u0633 \u0634\u0627\u062e\u0635\u200c\u0647\u0627\u06cc \u062a\u0648\u0631\u0645\u06cc \u0648 \u0628\u0648\u062f\u062c\u0647\u200c\u0631\u06cc\u0632\u06cc \u06a9\u0648\u062a\u0627\u0647\u200c\u0645\u062f\u062a \u0631\u0648\u06cc \u0622\u0648\u0631\u0646\u062f.<\/span><\/p><p><span style=\"font-weight: 400;\">\u062a\u062c\u0631\u0628\u0647 \u062a\u0627\u0631\u06cc\u062e\u06cc \u0646\u0634\u0627\u0646 \u0645\u06cc\u200c\u062f\u0647\u062f \u06a9\u0647 \u0645\u0647\u0627\u0631 \u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u0627\u0645\u06a9\u0627\u0646\u200c\u067e\u0630\u06cc\u0631 \u0627\u0633\u062a\u060c \u0627\u0645\u0627 \u0627\u06cc\u0646 \u0645\u0647\u0645 \u0628\u062f\u0648\u0646 \u062f\u0633\u062a\u0631\u0633\u06cc \u0628\u0647 \u062f\u0627\u062f\u0647\u200c\u0647\u0627\u06cc \u0645\u0639\u062a\u0628\u0631\u060c \u0634\u0641\u0627\u0641\u06cc\u062a \u062f\u0631 \u0633\u06cc\u0627\u0633\u062a\u200c\u06af\u0630\u0627\u0631\u06cc \u0648 \u0627\u0646\u062c\u0627\u0645 \u0627\u0635\u0644\u0627\u062d\u0627\u062a \u0633\u0627\u062e\u062a\u0627\u0631\u06cc \u0639\u0645\u06cc\u0642\u060c \u062f\u0633\u062a\u200c\u06cc\u0627\u0641\u062a\u0646\u06cc \u0646\u062e\u0648\u0627\u0647\u062f \u0628\u0648\u062f.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0627\u0628\u0631\u062a\u0648\u0631\u0645 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u062e\u0631\u0628\u200c\u062a\u0631\u06cc\u0646 \u067e\u062f\u06cc\u062f\u0647\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0627\u0633\u062a \u06a9\u0647 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u06cc\u06a9 \u06a9\u0634\u0648\u0631 \u0631\u0627 \u0628\u0647 \u0628\u062d\u0631\u0627\u0646 \u0639\u0645\u06cc\u0642 \u0628\u06a9\u0634\u0627\u0646\u062f \u0648 \u0632\u0646\u062f\u06af\u06cc \u0634\u0647\u0631\u0648\u0646\u062f\u0627\u0646 \u0631\u0627 \u062f\u06af\u0631\u06af\u0648\u0646 \u06a9\u0646\u062f. \u0627\u06cc\u0646 \u067e\u062f\u06cc\u062f\u0647 \u0646\u0647 \u062a\u0646\u0647\u0627 \u0627\u0642\u062a\u0635\u0627\u062f \u0645\u0644\u06cc \u0631\u0627 \u062a\u0636\u0639\u06cc\u0641 \u0645\u06cc\u200c\u06a9\u0646\u062f\u060c \u0628\u0644\u06a9\u0647 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u0647\u0627\u06cc \u0641\u0631\u062f\u06cc \u0631\u0627 \u0646\u06cc\u0632 \u0646\u0627\u0628\u0648\u062f \u0645\u06cc\u200c\u0633\u0627\u0632\u062f. \u062f\u0631\u06a9 \u0639\u0645\u06cc\u0642 \u0627\u06cc\u0646 \u067e\u062f\u06cc\u062f\u0647 \u0648 \u0631\u0627\u0647\u200c\u0647\u0627\u06cc \u0645\u0642\u0627\u0628\u0644\u0647 \u0628\u0627 \u0622\u0646\u060c \u0628\u0631\u0627\u06cc \u0647\u0631 \u0641\u0631\u062f\u06cc \u06a9\u0647 \u0628\u0647 \u0622\u06cc\u0646\u062f\u0647 \u0645\u0627\u0644\u06cc \u062e\u0648\u062f [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":174212,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[74],"tags":[63,66],"class_list":["post-173580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forex-articles","tag-forex-market","tag-economic-concepts"],"_links":{"self":[{"href":"https:\/\/newwp.aronsos.co\/fa\/wp-json\/wp\/v2\/posts\/173580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newwp.aronsos.co\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newwp.aronsos.co\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newwp.aronsos.co\/fa\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/newwp.aronsos.co\/fa\/wp-json\/wp\/v2\/comments?post=173580"}],"version-history":[{"count":1,"href":"https:\/\/newwp.aronsos.co\/fa\/wp-json\/wp\/v2\/posts\/173580\/revisions"}],"predecessor-version":[{"id":193385,"href":"https:\/\/newwp.aronsos.co\/fa\/wp-json\/wp\/v2\/posts\/173580\/revisions\/193385"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newwp.aronsos.co\/fa\/wp-json\/wp\/v2\/media\/174212"}],"wp:attachment":[{"href":"https:\/\/newwp.aronsos.co\/fa\/wp-json\/wp\/v2\/media?parent=173580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newwp.aronsos.co\/fa\/wp-json\/wp\/v2\/categories?post=173580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newwp.aronsos.co\/fa\/wp-json\/wp\/v2\/tags?post=173580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}