{"id":175154,"date":"2025-11-29T16:33:30","date_gmt":"2025-11-29T16:33:30","guid":{"rendered":"https:\/\/arongroups.co\/?p=175154"},"modified":"2026-06-29T15:15:31","modified_gmt":"2026-06-29T15:15:31","slug":"2008-financial-crisis","status":"publish","type":"post","link":"https:\/\/newwp.aronsos.co\/fa\/forex-articles\/2008-financial-crisis\/","title":{"rendered":"\u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8 \u0627\u0632 \u0646\u06af\u0627\u0647 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc\u061b \u0686\u06af\u0648\u0646\u0647 \u062c\u0647\u0627\u0646 \u062f\u0631 \u0622\u0633\u062a\u0627\u0646\u0647 \u0641\u0631\u0648\u067e\u0627\u0634\u06cc \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u061f"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"175154\" class=\"elementor elementor-175154\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-00e4797 e-flex e-con-boxed e-con e-parent\" data-id=\"00e4797\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-439444e elementor-widget elementor-widget-text-editor\" data-id=\"439444e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">\u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u0648 \u067e\u06cc\u0686\u06cc\u062f\u0647\u200c\u062a\u0631\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u062a\u0627\u0631\u06cc\u062e \u0628\u0648\u062f \u06a9\u0647 \u062a\u0623\u062b\u06cc\u0631\u0627\u062a \u0622\u0646 \u062a\u0627 \u0633\u0627\u0644\u200c\u0647\u0627 \u0627\u062d\u0633\u0627\u0633 \u0634\u062f. \u0627\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646 \u0646\u0627\u0634\u06cc \u0627\u0632 \u06cc\u06a9 \u0633\u0631\u06cc \u0627\u0634\u062a\u0628\u0627\u0647\u0627\u062a \u0633\u06cc\u0633\u062a\u0645\u0627\u062a\u06cc\u06a9 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0645\u0633\u06a9\u0646 \u0622\u0645\u0631\u06cc\u06a9\u0627 \u0628\u0648\u062f. \u0632\u06cc\u0631\u0627\u00a0 \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u0631\u0647\u0646\u06cc \u067e\u0631\u0631\u06cc\u0633\u06a9 \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0628\u06cc\u200c\u0631\u0648\u06cc\u0647 \u0642\u06cc\u0645\u062a \u062e\u0627\u0646\u0647\u200c\u0647\u0627\u060c \u062d\u0628\u0627\u0628\u06cc \u0628\u0632\u0631\u06af \u0627\u06cc\u062c\u0627\u062f \u06a9\u0631\u062f\u0646\u062f.<\/span><\/p><p><span style=\"font-weight: 400;\">\u00a0\u0628\u0627 \u0622\u063a\u0627\u0632 \u0633\u0642\u0648\u0637 \u0642\u06cc\u0645\u062a \u0645\u0633\u06a9\u0646\u060c \u0633\u06cc\u0633\u062a\u0645 \u0645\u0627\u0644\u06cc \u062f\u0631 \u0645\u0639\u0631\u0636 \u0628\u062d\u0631\u0627\u0646\u200c\u0647\u0627\u06cc \u062c\u062f\u06cc \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a \u0648 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0628\u0627\u0646\u06a9\u200c\u0647\u0627 \u0648\u0631\u0634\u06a9\u0633\u062a\u0647 \u0634\u062f\u0646\u062f. \u0627\u06cc\u0646 \u0631\u062e\u062f\u0627\u062f \u0646\u0647 \u062a\u0646\u0647\u0627 \u0628\u0647 \u0631\u06a9\u0648\u062f \u0628\u0632\u0631\u06af \u062c\u0647\u0627\u0646\u06cc \u0645\u0646\u062c\u0631 \u0634\u062f\u061b \u0628\u0644\u06a9\u0647 \u0628\u0627\u0639\u062b \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u0639\u0645\u062f\u0647 \u062f\u0631 \u0646\u062d\u0648\u0647 \u0646\u0638\u0627\u0631\u062a \u0628\u0631 \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc \u0634\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0645\u0642\u0627\u0644\u0647 \u0628\u0647 \u0628\u0631\u0631\u0633\u06cc \u062f\u0644\u0627\u06cc\u0644 \u0648 \u0622\u062b\u0627\u0631 \u0627\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646 \u062e\u0648\u0627\u0647\u06cc\u0645 \u067e\u0631\u062f\u0627\u062e\u062a \u0648 \u062f\u0631\u0633\u200c\u0647\u0627\u06cc\u06cc \u06a9\u0647 \u0627\u0632 \u0622\u0646 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u06af\u0631\u0641\u062a \u0631\u0627 \u0628\u0631\u0631\u0633\u06cc \u0645\u06cc\u200c\u06a9\u0646\u06cc\u0645.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f18f33 elementor-widget elementor-widget-text-editor\" data-id=\"1f18f33\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><b>\u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8 \u0686\u0647 \u0628\u0648\u062f \u0648 \u0686\u0631\u0627 \u0627\u0647\u0645\u06cc\u062a \u062f\u0627\u0631\u062f\u061f<\/b><\/h2><p><span style=\"font-weight: 400;\">\u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8 \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0632\u0631\u06af\u200c\u062a\u0631\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u062a\u0627\u0631\u06cc\u062e \u0628\u0648\u062f \u06a9\u0647 \u062a\u0623\u062b\u06cc\u0631\u0627\u062a \u0622\u0646 \u062a\u0627 \u0645\u062f\u062a\u200c\u0647\u0627 \u0628\u0631 \u0627\u0642\u062a\u0635\u0627\u062f \u062c\u0647\u0627\u0646\u06cc \u0628\u0627\u0642\u06cc \u0645\u0627\u0646\u062f.<\/span><\/p><p><span style=\"font-weight: 400;\">\u00a0\u0627\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646 \u0632\u0645\u0627\u0646\u06cc \u0622\u063a\u0627\u0632 \u0634\u062f \u06a9\u0647 \u0633\u06cc\u0633\u062a\u0645 \u0645\u0627\u0644\u06cc \u0622\u0645\u0631\u06cc\u06a9\u0627 \u0628\u0627 \u0645\u0634\u06a9\u0644\u0627\u062a \u062c\u062f\u06cc \u0645\u0648\u0627\u062c\u0647 \u0634\u062f \u0648 \u0627\u0631\u0632\u0634 \u062f\u0627\u0631\u0627\u06cc\u06cc\u200c\u0647\u0627 \u0628\u0647 \u0633\u0631\u0639\u062a \u06a9\u0627\u0647\u0634 \u067e\u06cc\u062f\u0627 \u06a9\u0631\u062f.<\/span><\/p><p><span style=\"font-weight: 400;\">\u06cc\u06a9\u06cc \u0627\u0632 \u0639\u0648\u0627\u0645\u0644 \u0627\u0635\u0644\u06cc \u0627\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646\u060c \u0627\u0641\u0632\u0627\u06cc\u0634 \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u0631\u0647\u0646\u06cc \u067e\u0631\u0631\u06cc\u0633\u06a9 \u0628\u0648\u062f \u06a9\u0647 \u0628\u0627\u0639\u062b \u0634\u062f \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0628\u0627\u0646\u06a9\u200c\u0647\u0627 \u0648 \u0645\u0624\u0633\u0633\u0627\u062a \u0645\u0627\u0644\u06cc \u0628\u0627 \u0645\u0634\u06a9\u0644 \u0645\u0648\u0627\u062c\u0647 \u0634\u0648\u0646\u062f.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">\u0648\u0642\u062a\u06cc \u0642\u06cc\u0645\u062a \u0645\u0633\u06a9\u0646 \u06a9\u0627\u0647\u0634 \u06cc\u0627\u0641\u062a\u060c \u0645\u0634\u06a9\u0644\u0627\u062a \u0632\u06cc\u0627\u062f\u06cc \u0628\u0631\u0627\u06cc \u0633\u06cc\u0633\u062a\u0645 \u0645\u0627\u0644\u06cc \u067e\u06cc\u0634 \u0622\u0645\u062f \u0648 \u0628\u0647 \u062a\u062f\u0631\u06cc\u062c \u0627\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646 \u0628\u0647 \u0633\u0627\u06cc\u0631 \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u06cc \u062c\u0647\u0627\u0646\u06cc \u06af\u0633\u062a\u0631\u0634 \u06cc\u0627\u0641\u062a.<\/span><\/p><p><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646 \u0646\u0647 \u062a\u0646\u0647\u0627 \u0628\u0627\u0639\u062b \u0631\u06a9\u0648\u062f \u0628\u0632\u0631\u06af \u06f2\u06f0\u06f0\u06f8 \u0634\u062f \u0628\u0644\u06a9\u0647 \u0628\u0627\u0639\u062b \u062a\u063a\u06cc\u06cc\u0631\u0627\u062a \u0639\u0645\u062f\u0647 \u062f\u0631 \u0646\u062d\u0648\u0647 \u0645\u062f\u06cc\u0631\u06cc\u062a \u0648 \u0646\u0638\u0627\u0631\u062a \u0628\u0631 \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc \u06af\u0631\u062f\u06cc\u062f.<\/span><\/p><p><span style=\"font-weight: 400;\">\u00a0\u0628\u0647 \u0647\u0645\u06cc\u0646 \u062f\u0644\u06cc\u0644\u060c \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8 \u0628\u0647 \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0632\u0631\u06af\u200c\u062a\u0631\u06cc\u0646 \u0648 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646\u200c\u0647\u0627 \u067e\u0633 \u0627\u0632 \u0631\u06a9\u0648\u062f \u0628\u0632\u0631\u06af \u062f\u0647\u0647 \u06f1\u06f9\u06f3\u06f0 \u0634\u0646\u0627\u062e\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f \u0648 \u067e\u06cc\u0627\u0645\u062f\u0647\u0627\u06cc \u0622\u0646 \u0647\u0645\u0686\u0646\u0627\u0646 \u0628\u0631 \u0633\u06cc\u0627\u0633\u062a\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u062a\u0627\u062b\u06cc\u0631 \u062f\u0627\u0631\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17d7055 elementor-widget elementor-widget-text-editor\" data-id=\"17d7055\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><b>\u0634\u0628\u0627\u0647\u062a\u200c\u0647\u0627 \u0648 \u062a\u0641\u0627\u0648\u062a\u200c\u0647\u0627\u06cc \u0631\u06a9\u0648\u062f \u0628\u0632\u0631\u06af \u06f2\u06f0\u06f0\u06f8 \u0628\u0627 \u0631\u06a9\u0648\u062f \u0628\u0632\u0631\u06af \u062f\u0647\u0647 \u06f1\u06f9\u06f3\u06f0<\/b><\/h2><p><span style=\"font-weight: 400;\">\u062f\u0631 \u0645\u0642\u0627\u06cc\u0633\u0647 \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8 \u0648 \u0631\u06a9\u0648\u062f \u0628\u0632\u0631\u06af \u062f\u0647\u0647 \u06f1\u06f9\u06f3\u06f0\u060c \u0634\u0628\u0627\u0647\u062a\u200c\u0647\u0627 \u0648 \u062a\u0641\u0627\u0648\u062a\u200c\u0647\u0627\u06cc \u0632\u06cc\u0627\u062f\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f. \u0647\u0631 \u062f\u0648 \u0628\u062d\u0631\u0627\u0646 \u0628\u0627 \u0641\u0631\u0648\u067e\u0627\u0634\u06cc \u0627\u0639\u062a\u0645\u0627\u062f \u0628\u0627\u0646\u06a9\u06cc\u060c \u0633\u0642\u0648\u0637 \u0628\u0627\u0632\u0627\u0631\u0647\u0627 \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0628\u06cc\u06a9\u0627\u0631\u06cc \u0634\u0631\u0648\u0639 \u0634\u062f\u0646\u062f. \u062f\u0631 \u0647\u0631 \u062f\u0648 \u0628\u062d\u0631\u0627\u0646\u060c \u0633\u06cc\u0633\u062a\u0645 \u0645\u0627\u0644\u06cc \u062a\u062d\u062a \u0641\u0634\u0627\u0631 \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a \u0648 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0627\u0641\u0631\u0627\u062f \u0648 \u0634\u0631\u06a9\u062a\u200c\u0647\u0627 \u0636\u0631\u0631 \u06a9\u0631\u062f\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u062f\u0631 \u0647\u0631 \u062f\u0648 \u0628\u062d\u0631\u0627\u0646\u060c \u0628\u0627\u0632\u0627\u0631\u0647\u0627 \u0628\u0647 \u0634\u062f\u062a \u062f\u0686\u0627\u0631 \u0631\u06a9\u0648\u062f \u0634\u062f\u0646\u062f \u0648 \u0627\u0639\u062a\u0645\u0627\u062f \u0645\u0631\u062f\u0645 \u0628\u0647 \u0633\u06cc\u0633\u062a\u0645 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u06a9\u0627\u0647\u0634 \u06cc\u0627\u0641\u062a.<\/span><\/p><p><span style=\"font-weight: 400;\">\u0628\u0627 \u0627\u06cc\u0646 \u062d\u0627\u0644\u060c \u062a\u0641\u0627\u0648\u062a\u200c\u0647\u0627\u06cc \u0642\u0627\u0628\u0644\u200c \u062a\u0648\u062c\u0647\u06cc \u0646\u06cc\u0632 \u0628\u06cc\u0646 \u0627\u06cc\u0646 \u062f\u0648 \u0628\u062d\u0631\u0627\u0646 \u0648\u062c\u0648\u062f \u062f\u0627\u0631\u062f. \u0628\u0631\u0627\u06cc \u0645\u062b\u0627\u0644\u060c \u062f\u0631 \u0631\u06a9\u0648\u062f \u0628\u0632\u0631\u06af \u062f\u0647\u0647 \u06f1\u06f9\u06f3\u06f0\u060c \u0634\u062f\u062a \u0628\u062d\u0631\u0627\u0646 \u0628\u0633\u06cc\u0627\u0631 \u0628\u06cc\u0634\u062a\u0631 \u0628\u0648\u062f \u0648 \u0628\u06cc\u06a9\u0627\u0631\u06cc \u0628\u0647 \u0628\u06cc\u0634 \u0627\u0632 \u06f2\u06f5 \u062f\u0631\u0635\u062f \u0631\u0633\u06cc\u062f. \u0627\u0645\u0627 \u062f\u0631 \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8\u060c \u0647\u0631\u0686\u0646\u062f \u062a\u0623\u062b\u06cc\u0631\u0627\u062a \u0634\u062f\u06cc\u062f \u0628\u0648\u062f\u060c <\/span><a href=\"https:\/\/arongroups.co\/fa\/forex\/%D8%B4%D8%A7%D8%AE%D8%B5-%D9%86%D8%B1%D8%AE-%D8%A8%DB%8C%DA%A9%D8%A7%D8%B1%DB%8C-%D9%88-%D8%AA%D8%A7%D8%AB%DB%8C%D8%B1-%D8%A2%D9%86-%D8%A8%D8%B1-%D9%81%D8%A7%D8%B1%DA%A9%D8%B3\/\"><span style=\"font-weight: 400;\">\u0646\u0631\u062e \u0628\u06cc\u06a9\u0627\u0631\u06cc<\/span><\/a><span style=\"font-weight: 400;\"> \u0628\u0647 \u0627\u0646\u062f\u0627\u0632\u0647 \u0628\u062d\u0631\u0627\u0646 \u062f\u0647\u0647 \u06f3\u06f0 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0646\u06cc\u0627\u0641\u062a.<\/span><\/p><p><span style=\"font-weight: 400;\">\u06cc\u06a9\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u062a\u0641\u0627\u0648\u062a\u200c\u0647\u0627 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u062f\u0631 \u0628\u062d\u0631\u0627\u0646 \u06f2\u06f0\u06f0\u06f8\u060c \u0627\u0628\u0632\u0627\u0631\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc \u067e\u06cc\u0686\u06cc\u062f\u0647\u200c\u062a\u0631\u06cc \u0645\u0627\u0646\u0646\u062f \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u0631\u0647\u0646\u06cc \u067e\u0631\u0631\u06cc\u0633\u06a9 \u0648 \u0627\u0648\u0631\u0627\u0642 \u0628\u0647\u0627\u062f\u0627\u0631 \u0645\u0627\u0644\u06cc \u0648\u062c\u0648\u062f \u062f\u0627\u0634\u062a \u06a9\u0647 \u0628\u0627\u0639\u062b \u0634\u062f \u0628\u062d\u0631\u0627\u0646 \u062c\u0647\u0627\u0646\u06cc\u200c\u062a\u0631 \u0648 \u0633\u0631\u06cc\u0639\u200c\u062a\u0631 \u06af\u0633\u062a\u0631\u0634 \u06cc\u0627\u0628\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0633\u06cc\u0627\u0633\u062a\u200c\u0647\u0627\u06cc \u062f\u0648\u0644\u062a\u200c\u0647\u0627 \u062f\u0631 \u0628\u062d\u0631\u0627\u0646 \u06f2\u06f0\u06f0\u06f8 \u0628\u0633\u06cc\u0627\u0631 \u0633\u0631\u06cc\u0639\u200c\u062a\u0631 \u0648 \u06af\u0633\u062a\u0631\u062f\u0647\u200c\u062a\u0631 \u0628\u0648\u062f\u0646\u062f\u060c \u0628\u0647\u200c \u0637\u0648\u0631\u06cc\u200c\u06a9\u0647 \u062f\u0648\u0644\u062a\u200c\u0647\u0627 \u0648 \u0628\u0627\u0646\u06a9\u200c\u0647\u0627\u06cc \u0645\u0631\u06a9\u0632\u06cc \u0628\u0633\u062a\u0647\u200c\u0647\u0627\u06cc \u062d\u0645\u0627\u06cc\u062a\u06cc \u0648 \u062a\u0632\u0631\u06cc\u0642 <\/span><a href=\"https:\/\/arongroups.co\/fa\/forex\/everything-about-liquidity-provider-and-market-makers-in-forex\/\"><span style=\"font-weight: 400;\">\u0646\u0642\u062f\u06cc\u0646\u06af\u06cc<\/span><\/a><span style=\"font-weight: 400;\"> \u0632\u06cc\u0627\u062f\u06cc \u0631\u0627 \u0628\u0647 \u0628\u0627\u0632\u0627\u0631 \u0648\u0627\u0631\u062f \u06a9\u0631\u062f\u0646\u062f.<\/span><\/p><p><span style=\"font-weight: 400;\">\u062f\u0631 \u0646\u0647\u0627\u06cc\u062a\u060c \u0631\u06a9\u0648\u062f \u0628\u0632\u0631\u06af \u06f2\u06f0\u06f0\u06f8 \u0628\u0647\u200c \u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9 \u0628\u062d\u0631\u0627\u0646 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0645\u0647\u0645 \u062f\u0631 \u062a\u0627\u0631\u06cc\u062e \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u062c\u0647\u0627\u0646 \u0634\u0646\u0627\u062e\u062a\u0647 \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u062f\u0631 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u062c\u0646\u0628\u0647\u200c\u0647\u0627 \u0645\u0634\u0627\u0628\u0647 \u0648 \u062f\u0631 \u0628\u0631\u062e\u06cc \u0645\u0648\u0627\u0631\u062f \u0645\u062a\u0641\u0627\u0648\u062a \u0627\u0632 \u0631\u06a9\u0648\u062f \u0628\u0632\u0631\u06af \u062f\u0647\u0647 \u06f1\u06f9\u06f3\u06f0 \u0628\u0648\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba0a066 elementor-widget elementor-widget-text-editor\" data-id=\"ba0a066\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><b>\u0632\u0645\u06cc\u0646\u0647\u200c\u0647\u0627\u06cc \u0634\u06a9\u0644\u200c\u06af\u06cc\u0631\u06cc \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8<\/b><\/h2><p><span style=\"font-weight: 400;\">\u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8 \u0646\u062a\u06cc\u062c\u0647 \u0645\u062c\u0645\u0648\u0639\u0647\u200c\u0627\u06cc \u0627\u0632 \u0639\u0648\u0627\u0645\u0644 \u0628\u0648\u062f \u06a9\u0647 \u062f\u0631 \u06a9\u0646\u0627\u0631 \u06cc\u06a9\u062f\u06cc\u06af\u0631 \u0628\u0647 \u06cc\u06a9 \u0628\u062d\u0631\u0627\u0646 \u06af\u0633\u062a\u0631\u062f\u0647 \u0645\u0646\u062c\u0631 \u0634\u062f\u0646\u062f. \u0627\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646 \u0628\u0647 \u0648\u06cc\u0698\u0647 \u062a\u062d\u062a \u062a\u0623\u062b\u06cc\u0631 \u0628\u0627\u0632\u0627\u0631 \u0645\u0633\u06a9\u0646 \u0622\u0645\u0631\u06cc\u06a9\u0627\u060c <\/span><a href=\"https:\/\/arongroups.co\/fa\/forex\/%D8%B3%DB%8C%D8%A7%D8%B3%D8%AA-%D8%AA%D8%B3%D9%87%DB%8C%D9%84-%D9%BE%D9%88%D9%84%DB%8C\/\"><span style=\"font-weight: 400;\">\u0633\u06cc\u0627\u0633\u062a\u200c\u0647\u0627\u06cc \u067e\u0648\u0644\u06cc<\/span><\/a><span style=\"font-weight: 400;\"> \u0641\u062f\u0631\u0627\u0644 \u0631\u0632\u0631\u0648 \u0648 \u06af\u0633\u062a\u0631\u0634 \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u0631\u0647\u0646\u06cc \u067e\u0631\u0631\u06cc\u0633\u06a9 \u0642\u0631\u0627\u0631 \u062f\u0627\u0634\u062a. \u062f\u0631 \u0627\u06cc\u0646 \u0628\u062e\u0634\u060c \u0628\u0647 \u0628\u0631\u0631\u0633\u06cc \u0627\u06cc\u0646 \u0639\u0648\u0627\u0645\u0644 \u0648 \u0686\u06af\u0648\u0646\u06af\u06cc \u062a\u0623\u062b\u06cc\u0631 \u0622\u0646\u200c\u0647\u0627 \u062f\u0631 \u0627\u06cc\u062c\u0627\u062f \u0628\u062d\u0631\u0627\u0646 \u0645\u0633\u06a9\u0646 \u0622\u0645\u0631\u06cc\u06a9\u0627 \u0648 \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8 \u062e\u0648\u0627\u0647\u06cc\u0645 \u067e\u0631\u062f\u0627\u062e\u062a.<\/span><\/p><h3><b>\u0631\u0648\u0646\u0642 \u063a\u06cc\u0631\u0645\u0646\u0637\u0642\u06cc \u0628\u0627\u0632\u0627\u0631 \u0645\u0633\u06a9\u0646 \u062f\u0631 \u0622\u0645\u0631\u06cc\u06a9\u0627<\/b><\/h3><p><span style=\"font-weight: 400;\">\u062f\u0631 \u0633\u0627\u0644\u200c\u0647\u0627\u06cc \u0642\u0628\u0644 \u0627\u0632 \u0628\u062d\u0631\u0627\u0646\u060c \u0628\u0627\u0632\u0627\u0631 \u0645\u0633\u06a9\u0646 \u062f\u0631 \u0622\u0645\u0631\u06cc\u06a9\u0627 \u0634\u0627\u0647\u062f \u0631\u0634\u062f \u0634\u062f\u06cc\u062f \u0648 \u063a\u06cc\u0631 \u0648\u0627\u0642\u0639\u06cc \u0628\u0648\u062f. \u0642\u06cc\u0645\u062a \u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u0628\u0647 \u0633\u0631\u0639\u062a \u0627\u0641\u0632\u0627\u06cc\u0634 \u06cc\u0627\u0641\u062a\u060c \u0628\u062f\u0648\u0646 \u0627\u06cc\u0646\u06a9\u0647 \u0627\u06cc\u0646 \u0631\u0634\u062f \u0628\u0627 \u0634\u0631\u0627\u06cc\u0637 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0648 \u062f\u0631\u0622\u0645\u062f \u0645\u0631\u062f\u0645 \u0647\u0645\u062e\u0648\u0627\u0646\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u062f. \u0627\u06cc\u0646 \u0631\u0634\u062f \u0628\u06cc\u200c\u0631\u0648\u06cc\u0647 \u0631\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646 \u0628\u0647\u200c\u0639\u0646\u0648\u0627\u0646 \u06cc\u06a9<\/span><a href=\"https:\/\/arongroups.co\/fa\/forex\/%DA%86%DA%AF%D9%88%D9%86%D9%87-%D9%88%D9%82%D9%88%D8%B9-%D8%AD%D8%A8%D8%A7%D8%A8-%D8%A7%D9%82%D8%AA%D8%B5%D8%A7%D8%AF%DB%8C-%D8%B1%D8%A7-%D9%BE%DB%8C%D8%B4-%D8%A8%DB%8C%D9%86%DB%8C-%DA%A9%D9%86%DB%8C\/\"> <span style=\"font-weight: 400;\">\u062d\u0628\u0627\u0628 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc<\/span><\/a><span style=\"font-weight: 400;\"> \u062f\u0631 \u0646\u0638\u0631 \u06af\u0631\u0641\u062a \u06a9\u0647 \u0628\u0647 \u0633\u0631\u0639\u062a \u062a\u0631\u06a9\u06cc\u062f. \u0627\u0641\u0632\u0627\u06cc\u0634 \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0628\u0627\u0639\u062b \u0634\u062f \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0645\u0631\u062f\u0645 \u0628\u0647 \u062e\u0631\u06cc\u062f \u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u0631\u0648\u06cc \u0622\u0648\u0631\u0646\u062f \u0648 \u0627\u06cc\u0646 \u0631\u0648\u0646\u062f \u062a\u0642\u0627\u0636\u0627 \u0631\u0627 \u0628\u0627\u0644\u0627 \u0628\u0631\u062f\u060c \u0627\u0645\u0627 \u0627\u06cc\u0646 \u0648\u0636\u0639\u06cc\u062a \u067e\u0627\u06cc\u062f\u0627\u0631 \u0646\u0628\u0648\u062f \u0648 \u0645\u0646\u062c\u0631 \u0628\u0647 \u0633\u0642\u0648\u0637 \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0634\u062f.<\/span><\/p><h3><b>\u0646\u0642\u0634 \u0633\u06cc\u0627\u0633\u062a\u200c\u0647\u0627\u06cc \u067e\u0648\u0644\u06cc \u0641\u062f\u0631\u0627\u0644 \u0631\u0632\u0631\u0648 \u067e\u0633 \u0627\u0632 \u062d\u0645\u0644\u0627\u062a \u06f1\u06f1 \u0633\u067e\u062a\u0627\u0645\u0628\u0631<\/b><\/h3><p><span style=\"font-weight: 400;\">\u067e\u0633 \u0627\u0632 \u062d\u0645\u0644\u0627\u062a \u06f1\u06f1 \u0633\u067e\u062a\u0627\u0645\u0628\u0631 \u06f2\u06f0\u06f0\u06f1\u060c \u0641\u062f\u0631\u0627\u0644 \u0631\u0632\u0631\u0648 \u062a\u0635\u0645\u06cc\u0645 \u06af\u0631\u0641\u062a \u06a9\u0647 <\/span><a href=\"https:\/\/arongroups.co\/fa\/forex\/%D9%86%D8%B1%D8%AE-%D8%A8%D9%87%D8%B1%D9%87-%DA%86%DB%8C%D8%B3%D8%AA%D8%9F\/\"><span style=\"font-weight: 400;\">\u0646\u0631\u062e \u0628\u0647\u0631\u0647<\/span><\/a><span style=\"font-weight: 400;\"> \u0631\u0627 \u06a9\u0627\u0647\u0634 \u062f\u0647\u062f \u062a\u0627 \u0628\u0647 \u0627\u0642\u062a\u0635\u0627\u062f \u06a9\u0645\u06a9 \u06a9\u0646\u062f. \u0627\u06cc\u0646 \u0633\u06cc\u0627\u0633\u062a \u0628\u0627\u0639\u062b \u0634\u062f \u06a9\u0647 \u0648\u0627\u0645\u200c\u06af\u06cc\u0631\u06cc \u0622\u0633\u0627\u0646\u200c\u062a\u0631 \u0634\u0648\u062f \u0648 \u0646\u0642\u062f\u06cc\u0646\u06af\u06cc \u0632\u06cc\u0627\u062f\u06cc \u0648\u0627\u0631\u062f \u0628\u0627\u0632\u0627\u0631 \u0634\u0648\u062f. \u0628\u0627 \u06a9\u0627\u0647\u0634 \u0646\u0631\u062e \u0628\u0647\u0631\u0647\u060c \u0645\u0631\u062f\u0645 \u0631\u0627\u062d\u062a\u200c\u062a\u0631 \u062e\u0627\u0646\u0647 \u062e\u0631\u06cc\u062f\u0646\u062f \u0648 \u0627\u06cc\u0646 \u0627\u0645\u0631 \u0628\u0647 \u0631\u0634\u062f \u0628\u06cc\u200c\u0631\u0648\u06cc\u0647 \u0628\u0627\u0632\u0627\u0631 \u0645\u0633\u06a9\u0646 \u06a9\u0645\u06a9 \u06a9\u0631\u062f. \u0627\u0645\u0627 \u0627\u06cc\u0646 \u0634\u0631\u0627\u06cc\u0637\u060c \u0631\u06cc\u0633\u06a9\u200c\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc \u0632\u06cc\u0627\u062f\u06cc \u0627\u06cc\u062c\u0627\u062f \u06a9\u0631\u062f \u0648 \u062f\u0631 \u0646\u0647\u0627\u06cc\u062a \u0628\u0627\u0639\u062b \u0634\u062f \u06a9\u0647 \u0628\u062d\u0631\u0627\u0646 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u062f\u0631 \u0633\u0627\u0644 \u06f2\u06f0\u06f0\u06f8 \u0634\u06a9\u0644 \u0628\u06af\u06cc\u0631\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f5c998 elementor-widget elementor-widget-text-editor\" data-id=\"6f5c998\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><b>\u06af\u0633\u062a\u0631\u0634 \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u0631\u0647\u0646\u06cc \u067e\u0631\u0631\u06cc\u0633\u06a9 (Subprime Mortgages)<\/b><\/h3><p><span style=\"font-weight: 400;\">\u06cc\u06a9\u06cc \u0627\u0632 \u0639\u0648\u0627\u0645\u0644 \u06a9\u0644\u06cc\u062f\u06cc \u062f\u0631 \u0634\u06a9\u0644\u200c\u06af\u06cc\u0631\u06cc \u0628\u062d\u0631\u0627\u0646 \u0645\u0633\u06a9\u0646 \u0622\u0645\u0631\u06cc\u06a9\u0627\u060c \u06af\u0633\u062a\u0631\u0634 \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u0631\u0647\u0646\u06cc \u067e\u0631\u0631\u06cc\u0633\u06a9 \u0628\u0648\u062f. \u0627\u06cc\u0646 \u0648\u0627\u0645\u200c\u0647\u0627 \u0628\u0647 \u0627\u0641\u0631\u0627\u062f\u06cc \u0628\u0627 \u0627\u0639\u062a\u0628\u0627\u0631 \u067e\u0627\u06cc\u06cc\u0646 \u062f\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u062f \u06a9\u0647 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u0628\u0627\u0632\u067e\u0631\u062f\u0627\u062e\u062a \u06a9\u0627\u0645\u0644 \u0622\u0646\u200c\u0647\u0627 \u0631\u0627 \u0646\u062f\u0627\u0634\u062a\u0646\u062f. \u0627\u06cc\u0646 \u0646\u0648\u0639 \u0648\u0627\u0645\u200c\u0647\u0627 \u0628\u0647 \u0628\u062e\u0634 \u0628\u0632\u0631\u06af\u06cc \u0627\u0632 \u062c\u0645\u0639\u06cc\u062a \u0622\u0645\u0631\u06cc\u06a9\u0627 \u062f\u0627\u062f\u0647 \u0634\u062f \u0648 \u062f\u0631 \u0646\u0647\u0627\u06cc\u062a \u0628\u0627\u0639\u062b \u0634\u062f \u06a9\u0647 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0627\u0641\u0631\u0627\u062f \u0646\u062a\u0648\u0627\u0646\u0646\u062f \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u062e\u0648\u062f \u0631\u0627 \u0628\u0627\u0632\u067e\u0631\u062f\u0627\u062e\u062a \u06a9\u0646\u0646\u062f.<\/span><\/p><p><span style=\"font-weight: 400;\">\u0648\u0642\u062a\u06cc \u0642\u06cc\u0645\u062a \u0645\u0633\u06a9\u0646 \u0633\u0642\u0648\u0637 \u06a9\u0631\u062f\u060c \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0627\u06cc\u0646 \u0627\u0641\u0631\u0627\u062f \u062f\u06cc\u06af\u0631 \u0642\u0627\u062f\u0631 \u0628\u0647 \u067e\u0631\u062f\u0627\u062e\u062a \u0627\u0642\u0633\u0627\u0637 \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u062e\u0648\u062f \u0646\u0628\u0648\u062f\u0646\u062f \u0648 \u0627\u06cc\u0646 \u0648\u0636\u0639\u06cc\u062a \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u062c\u0647\u0627\u0646\u06cc \u0631\u0627 \u0622\u063a\u0627\u0632 \u06a9\u0631\u062f. \u0627\u06cc\u0646 \u0648\u0627\u0645\u200c\u0647\u0627 \u0628\u0627 \u0627\u0628\u0632\u0627\u0631\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc \u067e\u06cc\u0686\u06cc\u062f\u0647 \u062a\u0631\u06a9\u06cc\u0628 \u0634\u062f\u0646\u062f \u0648 \u0631\u06cc\u0633\u06a9 \u0632\u06cc\u0627\u062f\u06cc \u0631\u0627 \u062f\u0631 \u0633\u06cc\u0633\u062a\u0645 \u0645\u0627\u0644\u06cc \u0627\u06cc\u062c\u0627\u062f \u06a9\u0631\u062f\u0646\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-39154bd elementor-widget elementor-widget-image\" data-id=\"39154bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"780\" height=\"438\" src=\"https:\/\/newwp.aronsos.co\/wp-content\/uploads\/2025\/11\/2008-financial-crisis-3.jpg\" class=\"attachment-large size-large wp-image-175162\" alt=\"\u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc 2008\" srcset=\"https:\/\/newwp.aronsos.co\/wp-content\/uploads\/2025\/11\/2008-financial-crisis-3.jpg 780w, https:\/\/newwp.aronsos.co\/wp-content\/uploads\/2025\/11\/2008-financial-crisis-3-300x168.jpg 300w, https:\/\/newwp.aronsos.co\/wp-content\/uploads\/2025\/11\/2008-financial-crisis-3-768x431.jpg 768w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5865d7 elementor-widget elementor-widget-text-editor\" data-id=\"a5865d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u0633\u0647 \u0639\u0627\u0645\u0644 \u0628\u0647\u200c\u0637\u0648\u0631 \u0645\u0634\u062a\u0631\u06a9 \u0628\u0627\u0639\u062b \u0634\u06a9\u0644\u200c\u06af\u06cc\u0631\u06cc \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8 \u0634\u062f\u0646\u062f \u0648 \u0628\u0647 \u0633\u0631\u0639\u062a \u0627\u0632 \u0628\u0627\u0632\u0627\u0631 \u0645\u0633\u06a9\u0646 \u0628\u0647 \u0633\u0627\u06cc\u0631 \u0628\u062e\u0634\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u06af\u0633\u062a\u0631\u0634 \u06cc\u0627\u0641\u062a\u0646\u062f.<\/span><\/p><h2><b>\u062d\u0628\u0627\u0628 \u0645\u0633\u06a9\u0646 \u0622\u0645\u0631\u06cc\u06a9\u0627 \u0648 \u0622\u063a\u0627\u0632 \u0632\u0646\u062c\u06cc\u0631\u0647 \u0628\u062d\u0631\u0627\u0646<\/b><\/h2><p><span style=\"font-weight: 400;\">\u0647\u0645\u0627\u0646\u06af\u0648\u0646\u0647 \u06a9\u0647 \u062f\u0631 \u0628\u062e\u0634\u200c\u0647\u0627\u06cc \u0642\u0628\u0644 \u0628\u06cc\u0627\u0646 \u06a9\u0631\u062f\u06cc\u0645\u060c \u06cc\u06a9\u06cc \u0627\u0632 \u0639\u0648\u0627\u0645\u0644 \u0627\u0635\u0644\u06cc \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8\u060c \u0634\u06a9\u0644\u200c\u06af\u06cc\u0631\u06cc \u062d\u0628\u0627\u0628 \u0645\u0633\u06a9\u0646 \u062f\u0631 \u0622\u0645\u0631\u06cc\u06a9\u0627 \u0628\u0648\u062f \u06a9\u0647 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u0627\u0641\u0632\u0627\u06cc\u0634 \u063a\u06cc\u0631\u0645\u0646\u0637\u0642\u06cc \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0648 \u0633\u0627\u062e\u062a\u0627\u0631\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc \u067e\u06cc\u0686\u06cc\u062f\u0647\u060c \u0628\u0647 \u0633\u0642\u0648\u0637 \u0628\u0627\u0632\u0627\u0631 \u0645\u0633\u06a9\u0646 \u0648 \u062f\u0631 \u067e\u06cc \u0622\u0646 \u0628\u0647 \u0628\u062d\u0631\u0627\u0646 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u062c\u0647\u0627\u0646\u06cc \u0645\u0646\u062c\u0631 \u0634\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0628\u062e\u0634\u060c \u0628\u0647 \u0628\u0631\u0631\u0633\u06cc \u0639\u0648\u0627\u0645\u0644\u06cc \u0645\u06cc\u200c\u067e\u0631\u062f\u0627\u0632\u06cc\u0645 \u06a9\u0647 \u0628\u0627\u0639\u062b \u0627\u06cc\u062c\u0627\u062f \u0627\u06cc\u0646 \u062d\u0628\u0627\u0628 \u0648 \u0622\u063a\u0627\u0632 \u0632\u0646\u062c\u06cc\u0631\u0647 \u0628\u062d\u0631\u0627\u0646 \u0634\u062f\u0646\u062f.<\/span><\/p><h3><b>\u0686\u0631\u0627 \u0642\u06cc\u0645\u062a \u0645\u0633\u06a9\u0646 \u0628\u0647\u200c \u0637\u0648\u0631 \u063a\u06cc\u0631\u0648\u0627\u0642\u0639\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u06cc\u0627\u0641\u062a\u061f<\/b><\/h3><p><span style=\"font-weight: 400;\">\u062f\u0631 \u0633\u0627\u0644\u200c\u0647\u0627\u06cc \u067e\u06cc\u0634 \u0627\u0632 \u0628\u062d\u0631\u0627\u0646\u060c \u0642\u06cc\u0645\u062a \u0645\u0633\u06a9\u0646 \u062f\u0631 \u0622\u0645\u0631\u06cc\u06a9\u0627 \u0628\u0647\u200c\u0637\u0648\u0631 \u0686\u0634\u0645\u06af\u06cc\u0631\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u06cc\u0627\u0641\u062a. \u0627\u06cc\u0646 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0646\u062a\u06cc\u062c\u0647 \u0639\u0648\u0627\u0645\u0644 \u0645\u062e\u062a\u0644\u0641\u06cc \u0627\u0632 \u062c\u0645\u0644\u0647: \u0646\u0631\u062e \u067e\u0627\u06cc\u06cc\u0646 \u0628\u0647\u0631\u0647\u060c \u062f\u0633\u062a\u0631\u0633\u06cc \u0622\u0633\u0627\u0646 \u0628\u0647 \u0648\u0627\u0645 \u0648 \u0627\u0646\u062a\u0638\u0627\u0631\u0627\u062a \u062a\u0648\u0631\u0645\u06cc \u0628\u0648\u062f. \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0648\u0627\u0645\u200c\u0647\u0627 \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u062f\u0631 \u0627\u062e\u062a\u06cc\u0627\u0631 \u0645\u0631\u062f\u0645 \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u060c \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0627\u0641\u0631\u0627\u062f \u0628\u0627 \u062e\u0631\u06cc\u062f \u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u0648\u0627\u0631\u062f \u0628\u0627\u0632\u0627\u0631 \u0634\u062f\u0646\u062f.<\/span><\/p><p><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u0634\u0631\u0627\u06cc\u0637 \u0628\u0627\u0639\u062b \u0634\u062f \u06a9\u0647 \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0628\u0647\u200c\u0637\u0648\u0631 \u063a\u06cc\u0631\u0648\u0627\u0642\u0639\u06cc \u0628\u0627\u0644\u0627 \u0628\u0631\u0648\u0646\u062f \u0648 \u062d\u0628\u0627\u0628\u06cc \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0645\u0633\u06a9\u0646 \u0634\u06a9\u0644 \u06af\u06cc\u0631\u062f. \u0648\u0642\u062a\u06cc \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0633\u0642\u0648\u0637 \u06a9\u0631\u062f\u0646\u062f\u060c \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u062e\u0631\u06cc\u062f\u0627\u0631\u0627\u0646 \u062f\u06cc\u06af\u0631 \u0642\u0627\u062f\u0631 \u0628\u0647 \u0628\u0627\u0632\u067e\u0631\u062f\u0627\u062e\u062a \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u062f\u0631\u06cc\u0627\u0641\u062a\u06cc \u062e\u0648\u062f \u0646\u0628\u0648\u062f\u0646\u062f \u0648 \u0627\u06cc\u0646 \u0648\u0636\u0639\u06cc\u062a \u06cc\u06a9\u06cc \u0627\u0632 \u0639\u0648\u0627\u0645\u0644 \u0627\u0635\u0644\u06cc \u0627\u06cc\u062c\u0627\u062f \u0628\u062d\u0631\u0627\u0646 \u0645\u0633\u06a9\u0646 \u0622\u0645\u0631\u06cc\u06a9\u0627 \u0634\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2932dc8 elementor-widget elementor-widget-text-editor\" data-id=\"2932dc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><b>\u062a\u0628\u062f\u06cc\u0644 \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u0628\u06cc\u200c\u067e\u0634\u062a\u0648\u0627\u0646\u0647 \u0628\u0647 \u0627\u0648\u0631\u0627\u0642 \u0628\u0647\u0627\u062f\u0627\u0631 \u0645\u0627\u0644\u06cc (MBS)<\/b><\/h3><p><span style=\"font-weight: 400;\">\u06cc\u06a9\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u0639\u0648\u0627\u0645\u0644\u06cc \u06a9\u0647 \u0628\u0647 \u062a\u0634\u062f\u06cc\u062f \u0628\u062d\u0631\u0627\u0646 \u06a9\u0645\u06a9 \u06a9\u0631\u062f\u060c \u062a\u0628\u062f\u06cc\u0644 \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u0633\u0627\u0628\u200c\u067e\u0631\u0627\u06cc\u0645 (\u0628\u0627 \u0646\u0631\u062e \u0628\u0647\u0631\u0647 \u0628\u0627\u0644\u0627 \u0648 \u0628\u062f\u0648\u0646 \u067e\u0634\u062a\u0648\u0627\u0646\u0647) \u0628\u0647 \u0627\u0648\u0631\u0627\u0642 \u0628\u0647\u0627\u062f\u0627\u0631 \u0645\u0627\u0644\u06cc \u0628\u0648\u062f. \u0627\u06cc\u0646 \u0648\u0627\u0645\u200c\u0647\u0627 \u06a9\u0647 \u0628\u0647 \u0627\u0641\u0631\u0627\u062f\u06cc \u0628\u0627 \u0627\u0639\u062a\u0628\u0627\u0631 \u067e\u0627\u06cc\u06cc\u0646 \u062f\u0627\u062f\u0647 \u0645\u06cc\u200c\u0634\u062f\u060c \u062a\u0648\u0633\u0637 \u0628\u0627\u0646\u06a9\u200c\u0647\u0627 \u0628\u0647 \u0627\u0648\u0631\u0627\u0642 \u0628\u0647\u0627\u062f\u0627\u0631 \u062a\u0628\u062f\u06cc\u0644 \u0648 \u0628\u0647 \u0641\u0631\u0648\u0634 \u0631\u0633\u06cc\u062f. \u0627\u06cc\u0646 \u0627\u0648\u0631\u0627\u0642 \u0628\u0647\u200c\u0637\u0648\u0631 \u06af\u0633\u062a\u0631\u062f\u0647 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc \u0645\u0639\u0627\u0645\u0644\u0647 \u0634\u062f\u0646\u062f \u0648 \u0628\u0627\u0639\u062b \u067e\u062e\u0634 \u0634\u062f\u0646 \u0631\u06cc\u0633\u06a9 \u062f\u0631 \u0633\u06cc\u0633\u062a\u0645 \u0645\u0627\u0644\u06cc \u062c\u0647\u0627\u0646\u06cc \u0634\u062f\u0646\u062f. \u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0628\u0627\u0632\u0627\u0631 \u0645\u0633\u06a9\u0646 \u0633\u0642\u0648\u0637 \u06a9\u0631\u062f\u060c \u0627\u06cc\u0646 \u0627\u0648\u0631\u0627\u0642 \u0628\u06cc\u200c\u0627\u0631\u0632\u0634 \u0634\u062f\u0646\u062f \u0648 \u0628\u0627\u0639\u062b \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8 \u0634\u062f\u0646\u062f.<\/span><\/p><h3><b>\u0646\u0642\u0634 \u0645\u0624\u0633\u0633\u0627\u062a \u0631\u062a\u0628\u0647\u200c\u0628\u0646\u062f\u06cc \u062f\u0631 \u062a\u0642\u0648\u06cc\u062a \u062d\u0628\u0627\u0628 \u0648 \u067e\u0646\u0647\u0627\u0646\u200c\u0633\u0627\u0632\u06cc \u0631\u06cc\u0633\u06a9<\/b><\/h3><p><span style=\"font-weight: 400;\">\u0645\u0624\u0633\u0633\u0627\u062a \u0631\u062a\u0628\u0647\u200c\u0628\u0646\u062f\u06cc \u0645\u0627\u0646\u0646\u062f <\/span><a href=\"https:\/\/arongroups.co\/fa\/forex\/%d9%81%db%8c%da%86-%d8%b1%db%8c%d8%aa%db%8c%d9%86%da%af%d8%b2-%da%86%db%8c%d8%b3%d8%aa-%d8%9f\/\"><span style=\"font-weight: 400;\">\u0641\u06cc\u0686 \u0631\u06cc\u062a\u06cc\u0646\u06af\u0632<\/span><\/a><span style=\"font-weight: 400;\">\u060c Standard &amp; Poor\u2019s \u0648 \u0645\u0648\u062f\u06cc\u0632 (Moody\u2019s) \u0646\u0642\u0634\u06cc \u0645\u0647\u0645 \u062f\u0631 \u0634\u06a9\u0644\u200c\u06af\u06cc\u0631\u06cc \u0628\u062d\u0631\u0627\u0646 \u062f\u0627\u0634\u062a\u0646\u062f. \u0627\u06cc\u0646 \u0645\u0624\u0633\u0633\u0627\u062a \u0628\u0647 \u0627\u0648\u0631\u0627\u0642 \u0645\u0627\u0644\u06cc \u0645\u0628\u062a\u0646\u06cc \u0628\u0631 \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u067e\u0631\u0631\u06cc\u0633\u06a9\u060c \u0631\u062a\u0628\u0647\u200c\u0647\u0627\u06cc \u0628\u0627\u0644\u0627 \u0627\u0639\u0637\u0627 \u06a9\u0631\u062f\u0646\u062f\u060c \u062f\u0631 \u062d\u0627\u0644\u06cc \u06a9\u0647 \u0627\u06cc\u0646 \u0627\u0648\u0631\u0627\u0642 \u062f\u0631 \u0648\u0627\u0642\u0639 \u062e\u0637\u0631\u0627\u062a \u0632\u06cc\u0627\u062f\u06cc \u062f\u0627\u0634\u062a\u0646\u062f. \u0627\u06cc\u0646 \u0631\u062a\u0628\u0647\u200c\u0628\u0646\u062f\u06cc\u200c\u0647\u0627 \u0628\u0627\u0639\u062b \u0634\u062f\u0646\u062f \u06a9\u0647 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646 \u0627\u06cc\u0646 \u0627\u0648\u0631\u0627\u0642 \u0631\u0627 \u0627\u06cc\u0645\u0646 \u0648 \u06a9\u0645\u200c\u062e\u0637\u0631 \u0628\u062f\u0627\u0646\u0646\u062f. \u0648\u0642\u062a\u06cc \u0627\u06cc\u0646 \u0627\u0648\u0631\u0627\u0642 \u0628\u06cc\u200c\u0627\u0631\u0632\u0634 \u0634\u062f\u0646\u062f\u060c \u0627\u0639\u062a\u0645\u0627\u062f \u0628\u0647 \u0633\u06cc\u0633\u062a\u0645 \u0645\u0627\u0644\u06cc \u06a9\u0627\u0647\u0634 \u06cc\u0627\u0641\u062a \u0648 \u0628\u062d\u0631\u0627\u0646 \u06af\u0633\u062a\u0631\u0634 \u067e\u06cc\u062f\u0627 \u06a9\u0631\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2a20654 elementor-widget elementor-widget-text-editor\" data-id=\"2a20654\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><b>\u0627\u0632 \u0628\u062d\u0631\u0627\u0646 \u0645\u0633\u06a9\u0646 \u062a\u0627 \u0628\u062d\u0631\u0627\u0646 \u0628\u0627\u0646\u06a9\u06cc\u061b \u0632\u0646\u062c\u06cc\u0631\u0647\u200c\u0627\u06cc \u0627\u0632 \u0633\u0642\u0648\u0637\u200c\u0647\u0627<\/b><\/h2><p><span style=\"font-weight: 400;\">\u0628\u062d\u0631\u0627\u0646 \u0645\u0633\u06a9\u0646 \u0622\u0645\u0631\u06cc\u06a9\u0627 \u0627\u0628\u062a\u062f\u0627 \u0628\u0627\u0639\u062b \u0634\u062f \u06a9\u0647 \u0642\u06cc\u0645\u062a \u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u0628\u0647 \u0634\u062f\u062a \u06a9\u0627\u0647\u0634 \u06cc\u0627\u0628\u062f \u0648 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0645\u0631\u062f\u0645 \u0642\u0627\u062f\u0631 \u0628\u0647 \u0628\u0627\u0632\u067e\u0631\u062f\u0627\u062e\u062a \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u062e\u0648\u062f \u0646\u0628\u0627\u0634\u0646\u062f. \u0627\u06cc\u0646 \u0648\u0636\u0639\u06cc\u062a \u0645\u0646\u062c\u0631 \u0628\u0647 \u0645\u0634\u06a9\u0644\u0627\u062a \u0628\u0632\u0631\u06af \u0628\u0631\u0627\u06cc \u0628\u0627\u0646\u06a9\u200c\u0647\u0627 \u0634\u062f \u0648 \u062f\u0631 \u0646\u0647\u0627\u06cc\u062a \u0628\u062d\u0631\u0627\u0646 \u0628\u0647 \u0646\u0638\u0627\u0645 \u0628\u0627\u0646\u06a9\u06cc \u06af\u0633\u062a\u0631\u0634 \u06cc\u0627\u0641\u062a. \u0633\u067e\u0633 \u0627\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646 \u0627\u0632 \u0645\u0631\u0632\u0647\u0627\u06cc \u0622\u0645\u0631\u06cc\u06a9\u0627 \u0641\u0631\u0627\u062a\u0631 \u0631\u0641\u062a \u0648 \u0628\u0647 \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc \u062c\u0647\u0627\u0646\u06cc \u0631\u0633\u06cc\u062f\u060c \u0628\u0627\u0639\u062b \u0627\u06cc\u062c\u0627\u062f \u0631\u06a9\u0648\u062f \u0628\u0632\u0631\u06af \u06f2\u06f0\u06f0\u06f8 \u0648 \u0628\u062d\u0631\u0627\u0646 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u062f\u0631 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u06a9\u0634\u0648\u0631\u0647\u0627 \u0634\u062f.<\/span><\/p><h3><b>\u0622\u063a\u0627\u0632 \u0646\u06a9\u0648\u0644 \u0648\u0627\u0645\u200c\u0647\u0627 \u0648 \u06a9\u0627\u0647\u0634 \u0634\u062f\u06cc\u062f \u0642\u06cc\u0645\u062a \u062e\u0627\u0646\u0647\u200c\u0647\u0627<\/b><\/h3><p><span style=\"font-weight: 400;\">\u0632\u0645\u0627\u0646\u06cc \u06a9\u0647 \u0642\u06cc\u0645\u062a \u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u0634\u0631\u0648\u0639 \u0628\u0647 \u06a9\u0627\u0647\u0634 \u06a9\u0631\u062f\u060c \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0627\u0641\u0631\u0627\u062f\u06cc \u06a9\u0647 \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u0631\u0647\u0646\u06cc \u0633\u0627\u0628\u200c\u067e\u0631\u0627\u06cc\u0645 (\u0628\u0627 \u0646\u0631\u062e \u0628\u0647\u0631\u0647 \u0628\u0627\u0644\u0627) \u06af\u0631\u0641\u062a\u0647 \u0628\u0648\u062f\u0646\u062f\u060c \u0642\u0627\u062f\u0631 \u0628\u0647 \u067e\u0631\u062f\u0627\u062e\u062a \u0627\u0642\u0633\u0627\u0637 \u062e\u0648\u062f \u0646\u0634\u062f\u0646\u062f \u0648 \u0634\u0631\u0648\u0639 \u0628\u0647 \u0646\u06a9\u0648\u0644 \u0648\u0627\u0645\u200c\u0647\u0627 \u06a9\u0631\u062f\u0646\u062f. \u0627\u06cc\u0646 \u0646\u06a9\u0648\u0644\u200c\u0647\u0627 \u0628\u0647 \u0633\u0631\u0639\u062a \u0628\u0647 \u0628\u062d\u0631\u0627\u0646 \u0628\u0632\u0631\u06af\u200c\u062a\u0631\u06cc \u062a\u0628\u062f\u06cc\u0644 \u0634\u062f \u0648 \u0628\u0627\u0639\u062b \u0634\u062f \u0628\u0627\u0646\u06a9\u200c\u0647\u0627 \u0648 \u0645\u0624\u0633\u0633\u0627\u062a \u0645\u0627\u0644\u06cc \u062f\u0631 \u0622\u0645\u0631\u06cc\u06a9\u0627 \u0645\u062a\u0636\u0631\u0631 \u0634\u0648\u0646\u062f. \u06a9\u0627\u0647\u0634 \u0627\u0631\u0632\u0634 \u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u0628\u0647 \u0634\u062f\u062a \u0628\u0647 \u0628\u062d\u0631\u0627\u0646 \u0645\u0633\u06a9\u0646 \u0622\u0645\u0631\u06cc\u06a9\u0627 \u062f\u0627\u0645\u0646 \u0632\u062f.<\/span><\/p><h3><b>\u0628\u062d\u0631\u0627\u0646 \u0646\u0642\u062f\u06cc\u0646\u06af\u06cc \u062f\u0631 \u0628\u0627\u0646\u06a9\u200c\u0647\u0627 \u0648 \u0633\u0642\u0648\u0637 \u0644\u0645\u0627\u0646 \u0628\u0631\u0627\u062f\u0631\u0632<\/b><\/h3><p><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u0646\u06a9\u0648\u0644\u200c\u0647\u0627 \u0648 \u06a9\u0627\u0647\u0634 \u0642\u06cc\u0645\u062a\u200c\u0647\u0627 \u0628\u0627\u0639\u062b \u0628\u062d\u0631\u0627\u0646 \u0646\u0642\u062f\u06cc\u0646\u06af\u06cc \u062f\u0631 \u0628\u0627\u0646\u06a9\u200c\u0647\u0627 \u0634\u062f. \u0628\u0627\u0646\u06a9\u200c\u0647\u0627 \u0646\u062a\u0648\u0627\u0646\u0633\u062a\u0646\u062f \u0628\u0647 \u0631\u0627\u062d\u062a\u06cc \u0648\u0627\u0645 \u062f\u0647\u0646\u062f \u06cc\u0627 \u062f\u0627\u0631\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc \u062e\u0648\u062f \u0631\u0627 \u0628\u0641\u0631\u0648\u0634\u0646\u062f\u060c \u0632\u06cc\u0631\u0627 \u0627\u0631\u0632\u0634 \u0627\u0648\u0631\u0627\u0642 \u0628\u0647\u0627\u062f\u0627\u0631 \u0645\u0628\u062a\u0646\u06cc \u0628\u0631 \u0648\u0627\u0645\u200c\u0647\u0627 \u06a9\u0627\u0647\u0634 \u06cc\u0627\u0641\u062a\u0647 \u0628\u0648\u062f. \u0633\u0642\u0648\u0637 \u0644\u0645\u0627\u0646 \u0628\u0631\u0627\u062f\u0631\u0632 (Lehman Brothers) \u062f\u0631 \u0633\u067e\u062a\u0627\u0645\u0628\u0631 \u06f2\u06f0\u06f0\u06f8 \u0646\u0642\u0637\u0647 \u0639\u0637\u0641 \u0627\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646 \u0628\u0648\u062f. \u0627\u06cc\u0646 \u0627\u062a\u0641\u0627\u0642 \u0628\u0647 \u0627\u0639\u062a\u0645\u0627\u062f \u0639\u0645\u0648\u0645\u06cc \u0628\u0647 \u0633\u06cc\u0633\u062a\u0645 \u0645\u0627\u0644\u06cc \u0636\u0631\u0628\u0647 \u0628\u0632\u0631\u06af\u06cc \u0632\u062f \u0648 \u0628\u062d\u0631\u0627\u0646 \u0628\u0627\u0646\u06a9\u06cc \u0628\u0647 \u0637\u0648\u0631 \u06a9\u0627\u0645\u0644 \u062f\u0631 \u0633\u06cc\u0633\u062a\u0645 \u0645\u0627\u0644\u06cc \u062c\u0647\u0627\u0646\u06cc \u06af\u0633\u062a\u0631\u0634 \u06cc\u0627\u0641\u062a.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-144e3a2 elementor-widget elementor-widget-text-editor\" data-id=\"144e3a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><b>\u0633\u0631\u0627\u06cc\u062a \u0628\u062d\u0631\u0627\u0646 \u0628\u0647 \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc<\/b><\/h3><p><span style=\"font-weight: 400;\">\u067e\u0633 \u0627\u0632 \u0628\u062d\u0631\u0627\u0646 \u062f\u0631 \u0622\u0645\u0631\u06cc\u06a9\u0627\u060c \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc \u0627\u0631\u0648\u067e\u0627 \u0648 \u0633\u0627\u06cc\u0631 \u0646\u0642\u0627\u0637 \u062c\u0647\u0627\u0646 \u062a\u062d\u062a \u062a\u0627\u062b\u06cc\u0631 \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0646\u062f. \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0628\u0627\u0646\u06a9\u200c\u0647\u0627 \u0648 \u0645\u0624\u0633\u0633\u0627\u062a \u0645\u0627\u0644\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u06a9\u0647 \u062f\u0631 \u0627\u0648\u0631\u0627\u0642 \u0628\u0647\u0627\u062f\u0627\u0631 \u0645\u0628\u062a\u0646\u06cc \u0628\u0631 \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u0645\u0633\u06a9\u0646 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u06a9\u0631\u062f\u0647 \u0628\u0648\u062f\u0646\u062f \u0628\u0627 \u0645\u0634\u06a9\u0644\u0627\u062a \u0645\u0627\u0644\u06cc \u062c\u062f\u06cc \u0645\u0648\u0627\u062c\u0647 \u0634\u062f\u0646\u062f. \u062f\u0631 \u0646\u062a\u06cc\u062c\u0647\u060c \u0627\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646 \u0628\u0647 \u06cc\u06a9 \u0628\u062d\u0631\u0627\u0646 \u062c\u0647\u0627\u0646\u06cc \u062a\u0628\u062f\u06cc\u0644 \u0634\u062f \u06a9\u0647 \u062a\u0623\u062b\u06cc\u0631\u0627\u062a \u0622\u0646 \u062f\u0631 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u06a9\u0634\u0648\u0631\u0647\u0627 \u062f\u06cc\u062f\u0647 \u0634\u062f \u0648 \u0627\u0642\u062a\u0635\u0627\u062f \u062c\u0647\u0627\u0646\u06cc \u0648\u0627\u0631\u062f \u0631\u06a9\u0648\u062f \u0628\u0632\u0631\u06af \u06f2\u06f0\u06f0\u06f8 \u0634\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c006f3f elementor-widget elementor-widget-image\" data-id=\"c006f3f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"780\" height=\"438\" src=\"https:\/\/newwp.aronsos.co\/wp-content\/uploads\/2025\/11\/2008-financial-crisis-1.jpg\" class=\"attachment-large size-large wp-image-175165\" alt=\"\" srcset=\"https:\/\/newwp.aronsos.co\/wp-content\/uploads\/2025\/11\/2008-financial-crisis-1.jpg 780w, https:\/\/newwp.aronsos.co\/wp-content\/uploads\/2025\/11\/2008-financial-crisis-1-300x168.jpg 300w, https:\/\/newwp.aronsos.co\/wp-content\/uploads\/2025\/11\/2008-financial-crisis-1-768x431.jpg 768w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd38c95 elementor-widget elementor-widget-text-editor\" data-id=\"fd38c95\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><b>\u062f\u0644\u0627\u06cc\u0644 \u0639\u0645\u06cc\u0642 \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8<\/b><\/h2><p><span style=\"font-weight: 400;\">\u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0644\u0627\u06cc\u0647\u200c\u0647\u0627\u06cc \u0628\u06cc\u0631\u0648\u0646\u06cc \u0639\u0646\u0648\u0627\u0646 \u0634\u062f\u0647 \u062f\u0631 \u0628\u062e\u0634\u200c\u0647\u0627\u06cc \u0642\u0628\u0644\u06cc\u060c \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8 \u0631\u06cc\u0634\u0647\u200c\u0647\u0627\u06cc \u0639\u0645\u06cc\u0642\u200c\u062a\u0631\u00a0 \u0648 \u067e\u06cc\u0686\u06cc\u062f\u0647\u200c\u0627\u06cc \u062f\u0627\u0634\u062a. \u0639\u0648\u0627\u0645\u0644\u06cc \u0645\u0627\u0646\u0646\u062f \u0633\u0627\u062e\u062a\u0627\u0631 \u0646\u0627\u0633\u0627\u0644\u0645 \u0628\u0627\u0632\u0627\u0631 \u0627\u0639\u062a\u0628\u0627\u0631\u06cc\u060c \u0646\u0638\u0627\u0631\u062a \u0636\u0639\u06cc\u0641 \u0648 \u0631\u0641\u062a\u0627\u0631\u0647\u0627\u06cc \u0647\u06cc\u062c\u0627\u0646\u06cc \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646 \u0628\u0627\u0639\u062b \u0634\u062f\u0646\u062f \u06a9\u0647 \u0627\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646 \u0628\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0628\u0632\u0631\u06af\u200c\u062a\u0631\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u062a\u0627\u0631\u06cc\u062e \u062a\u0628\u062f\u06cc\u0644 \u0634\u0648\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0628\u062e\u0634\u060c \u0628\u0647 \u0628\u0631\u0631\u0633\u06cc \u0627\u06cc\u0646 \u062f\u0644\u0627\u06cc\u0644 \u0645\u06cc\u200c\u067e\u0631\u062f\u0627\u0632\u06cc\u0645.<\/span><\/p><h3><b>\u0633\u0627\u062e\u062a\u0627\u0631 \u0645\u0639\u06cc\u0648\u0628 \u0628\u0627\u0632\u0627\u0631 \u0627\u0639\u062a\u0628\u0627\u0631\u06cc \u0648 \u0627\u0628\u0632\u0627\u0631\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc \u0645\u0634\u062a\u0642\u0647<\/b><\/h3><p><span style=\"font-weight: 400;\">\u06cc\u06a9\u06cc \u0627\u0632 \u062f\u0644\u0627\u06cc\u0644 \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8\u060c \u0633\u0627\u062e\u062a\u0627\u0631 \u0645\u0639\u06cc\u0648\u0628 \u0628\u0627\u0632\u0627\u0631 \u0627\u0639\u062a\u0628\u0627\u0631\u06cc \u0628\u0648\u062f. \u0628\u0627\u0646\u06a9\u200c\u0647\u0627 \u0648 \u0645\u0648\u0633\u0633\u0627\u062a \u0645\u0627\u0644\u06cc \u0628\u0627 \u0627\u0633\u062a\u0641\u0627\u062f\u0647 \u0627\u0632 \u0627\u0647\u0631\u0645 \u0628\u0627\u0644\u0627 \u0648 \u0627\u0628\u0632\u0627\u0631\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc \u067e\u06cc\u0686\u06cc\u062f\u0647 \u0645\u0627\u0646\u0646\u062f \u0645\u0634\u062a\u0642\u0647\u200c\u0647\u0627\u060c \u0631\u06cc\u0633\u06a9\u200c\u0647\u0627 \u0631\u0627 \u062f\u0631 \u0633\u0631\u0627\u0633\u0631 \u0633\u06cc\u0633\u062a\u0645 \u0645\u0627\u0644\u06cc \u067e\u062e\u0634 \u06a9\u0631\u062f\u0646\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u06cc \u063a\u06cc\u0631\u0631\u0633\u0645\u06cc \u0648 \u0645\u0648\u0633\u0633\u0627\u062a \u063a\u06cc\u0631 \u0628\u0627\u0646\u06a9\u06cc (\u0628\u0627\u0646\u06a9\u200c\u0647\u0627\u06cc \u0633\u0627\u06cc\u0647) \u06a9\u0647 \u062a\u062d\u062a \u0646\u0638\u0627\u0631\u062a \u06a9\u0645\u062a\u0631\u06cc \u0628\u0648\u062f\u0646\u062f\u060c \u0628\u0647 \u0627\u06cc\u0646 \u0645\u0634\u06a9\u0644 \u062f\u0627\u0645\u0646 \u0632\u062f\u0646\u062f. \u0627\u06cc\u0646 \u0633\u0627\u062e\u062a\u0627\u0631 \u0646\u0627\u0633\u0627\u0644\u0645 \u0628\u0627\u0639\u062b \u0634\u062f \u06a9\u0647 \u0648\u0642\u062a\u06cc \u0628\u062d\u0631\u0627\u0646 \u062f\u0631 \u0628\u062e\u0634 \u0645\u0633\u06a9\u0646 \u0634\u0631\u0648\u0639 \u0634\u062f\u060c \u0631\u06cc\u0633\u06a9\u200c\u0647\u0627 \u0628\u0647 \u0634\u062f\u062a \u06af\u0633\u062a\u0631\u0634 \u06cc\u0627\u0628\u0646\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6321cd elementor-widget elementor-widget-text-editor\" data-id=\"c6321cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><b>\u0646\u0628\u0648\u062f \u0634\u0641\u0627\u0641\u06cc\u062a\u060c \u0646\u0638\u0627\u0631\u062a \u0646\u0627\u06a9\u0627\u0631\u0622\u0645\u062f \u0648 \u062a\u0636\u0627\u062f \u0645\u0646\u0627\u0641\u0639 \u062f\u0631 \u0633\u06cc\u0633\u062a\u0645 \u0645\u0627\u0644\u06cc<\/b><\/h3><p><span style=\"font-weight: 400;\">\u06cc\u06a9\u06cc \u062f\u06cc\u06af\u0631 \u0627\u0632 \u062f\u0644\u0627\u06cc\u0644 \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8\u060c \u0646\u0628\u0648\u062f \u0634\u0641\u0627\u0641\u06cc\u062a \u06a9\u0627\u0641\u06cc \u062f\u0631 \u0628\u0627\u0632\u0627\u0631\u0647\u0627 \u0648 \u0646\u0638\u0627\u0631\u062a \u0646\u0627\u06a9\u0627\u0631\u0622\u0645\u062f \u0628\u0631 \u0645\u0648\u0633\u0633\u0627\u062a \u0645\u0627\u0644\u06cc \u0628\u0648\u062f. \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0645\u0648\u0633\u0633\u0627\u062a \u0645\u0627\u0644\u06cc \u0631\u06cc\u0633\u06a9\u200c\u0647\u0627\u06cc \u0632\u06cc\u0627\u062f\u06cc \u0631\u0627 \u067e\u0646\u0647\u0627\u0646 \u06a9\u0631\u062f\u0646\u062f \u0648 \u0646\u0647\u0627\u062f\u0647\u0627\u06cc \u0646\u0638\u0627\u0631\u062a\u06cc \u0646\u062a\u0648\u0627\u0646\u0633\u062a\u0646\u062f \u0628\u0647\u200c \u062f\u0631\u0633\u062a\u06cc \u0627\u06cc\u0646 \u062e\u0637\u0631\u0627\u062a \u0631\u0627 \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u06a9\u0646\u0646\u062f. \u0639\u0644\u0627\u0648\u0647 \u0628\u0631 \u0627\u06cc\u0646\u060c \u062a\u0636\u0627\u062f \u0645\u0646\u0627\u0641\u0639 \u0645\u06cc\u0627\u0646 \u0634\u0631\u06a9\u062a\u200c\u0647\u0627\u06cc \u0631\u062a\u0628\u0647\u200c\u0628\u0646\u062f\u06cc\u060c \u0628\u0627\u0646\u06a9\u200c\u0647\u0627 \u0648 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646 \u0628\u0627\u0639\u062b \u0634\u062f \u06a9\u0647 \u062e\u0637\u0631\u0627\u062a \u0628\u0647\u200c\u0637\u0648\u0631 \u0646\u0627\u062f\u0631\u0633\u062a \u0627\u0631\u0632\u06cc\u0627\u0628\u06cc \u0634\u0648\u0646\u062f \u0648 \u0627\u06cc\u0646 \u0645\u0648\u0636\u0648\u0639 \u0628\u0647 \u0628\u062d\u0631\u0627\u0646 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u062f\u0627\u0645\u0646 \u0632\u062f.<\/span><\/p><h3><b>\u0631\u0641\u062a\u0627\u0631\u0647\u0627\u06cc \u0647\u06cc\u062c\u0627\u0646\u06cc \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646 \u0648 \u0627\u0639\u062a\u0645\u0627\u062f \u06a9\u0648\u0631 \u0628\u0647 \u0628\u0627\u0632\u0627\u0631<\/b><\/h3><p><span style=\"font-weight: 400;\">\u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646 \u0648 \u0645\u0648\u0633\u0633\u0627\u062a \u0645\u0627\u0644\u06cc \u0628\u0627 \u0627\u0639\u062a\u0645\u0627\u062f \u06a9\u0648\u0631 \u0628\u0647 \u0631\u0634\u062f \u0628\u06cc\u200c\u0648\u0642\u0641\u0647 \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u060c \u0631\u06cc\u0633\u06a9\u200c\u0647\u0627\u06cc \u0632\u06cc\u0627\u062f\u06cc \u0631\u0627 \u0646\u0627\u062f\u06cc\u062f\u0647 \u06af\u0631\u0641\u062a\u0646\u062f. \u0627\u06cc\u0646 \u0627\u0639\u062a\u0645\u0627\u062f \u0628\u06cc\u0634 \u0627\u0632 \u062d\u062f \u0628\u0627\u0639\u062b \u0634\u062f \u06a9\u0647 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u0622\u0646\u200c\u0647\u0627 \u0648\u0627\u0631\u062f \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u06cc\u06cc \u0634\u0648\u0646\u062f \u06a9\u0647 \u062f\u0631 \u0648\u0627\u0642\u0639 \u067e\u0631 \u0627\u0632 \u0631\u06cc\u0633\u06a9 \u0628\u0648\u062f\u0646\u062f. \u0627\u06cc\u0646 \u0646\u0648\u0639 \u0631\u0641\u062a\u0627\u0631 \u0647\u06cc\u062c\u0627\u0646\u06cc\u060c \u0628\u062e\u0634\u06cc \u0627\u0632 \u062d\u0628\u0627\u0628 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0631\u0627 \u0627\u06cc\u062c\u0627\u062f \u06a9\u0631\u062f \u06a9\u0647 \u062f\u0631 \u0646\u0647\u0627\u06cc\u062a \u062a\u0631\u06a9\u06cc\u062f \u0648 \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u0631\u0627 \u062a\u0634\u062f\u06cc\u062f \u06a9\u0631\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8433062 elementor-widget elementor-widget-text-editor\" data-id=\"8433062\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><b>\u0648\u0627\u06a9\u0646\u0634 \u062f\u0648\u0644\u062a \u0622\u0645\u0631\u06cc\u06a9\u0627 \u0648 \u0628\u0627\u0646\u06a9\u200c\u0647\u0627\u06cc \u0645\u0631\u06a9\u0632\u06cc \u062c\u0647\u0627\u0646 \u0628\u0647 \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8<\/b><\/h2><p><span style=\"font-weight: 400;\">\u062f\u0648\u0644\u062a \u0622\u0645\u0631\u06cc\u06a9\u0627 \u0648 \u0628\u0627\u0646\u06a9\u200c\u0647\u0627\u06cc \u0645\u0631\u06a9\u0632\u06cc \u062c\u0647\u0627\u0646 \u067e\u0633 \u0627\u0632 \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8\u060c \u0627\u0642\u062f\u0627\u0645\u0627\u062a \u06af\u0633\u062a\u0631\u062f\u0647\u200c\u0627\u06cc \u0628\u0631\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0641\u0631\u0648\u067e\u0627\u0634\u06cc \u0633\u06cc\u0633\u062a\u0645 \u0645\u0627\u0644\u06cc \u0648 \u062d\u0645\u0627\u06cc\u062a \u0627\u0632 \u0627\u0642\u062a\u0635\u0627\u062f \u0627\u0646\u062c\u0627\u0645 \u062f\u0627\u062f\u0646\u062f. \u0627\u06cc\u0646 \u0627\u0642\u062f\u0627\u0645\u0627\u062a \u0634\u0627\u0645\u0644 \u0628\u0633\u062a\u0647\u200c\u0647\u0627\u06cc \u0646\u062c\u0627\u062a \u0645\u0627\u0644\u06cc\u060c \u0633\u06cc\u0627\u0633\u062a\u200c\u0647\u0627\u06cc \u067e\u0648\u0644\u06cc \u0627\u0646\u0628\u0633\u0627\u0637\u06cc \u0648 \u0627\u0635\u0644\u0627\u062d\u0627\u062a \u0633\u0627\u062e\u062a\u0627\u0631\u06cc \u0628\u0648\u062f \u06a9\u0647 \u0628\u0647 \u0637\u0648\u0631 \u06a9\u0644\u06cc \u0628\u0647 \u0645\u062f\u06cc\u0631\u06cc\u062a \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8 \u06a9\u0645\u06a9 \u06a9\u0631\u062f\u0646\u062f.<\/span><\/p><h3><b>\u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0647\u0627\u06cc \u0646\u062c\u0627\u062a \u0645\u0627\u0644\u06cc (Bailout) \u0648 \u062a\u0632\u0631\u06cc\u0642 \u0633\u0631\u0645\u0627\u06cc\u0647 \u0628\u0647 \u0628\u0627\u0646\u06a9\u200c\u0647\u0627<\/b><\/h3><p><span style=\"font-weight: 400;\">\u0628\u0631\u0627\u06cc \u0645\u0642\u0627\u0628\u0644\u0647 \u0628\u0627 \u0628\u062d\u0631\u0627\u0646\u060c \u062f\u0648\u0644\u062a \u0622\u0645\u0631\u06cc\u06a9\u0627 \u0637\u0631\u062d\u06cc \u0628\u0647 \u0646\u0627\u0645 Troubled Asset Relief Program \u06cc\u0627 \u0628\u0647 \u0627\u062e\u062a\u0635\u0627\u0631 TARP\u00a0 \u0631\u0627 \u0627\u062c\u0631\u0627 \u06a9\u0631\u062f \u06a9\u0647 \u062f\u0631 \u0622\u0646 \u062d\u062f\u0648\u062f \u06f7\u06f0\u06f0 \u0645\u06cc\u0644\u06cc\u0627\u0631\u062f \u062f\u0644\u0627\u0631 \u0628\u0631\u0627\u06cc \u062e\u0631\u06cc\u062f \u062f\u0627\u0631\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc \u0645\u0634\u06a9\u0644\u200c\u062f\u0627\u0631 \u0648 \u062a\u0632\u0631\u06cc\u0642 \u0633\u0631\u0645\u0627\u06cc\u0647 \u0628\u0647 \u0628\u0627\u0646\u06a9\u200c\u0647\u0627 \u0627\u062e\u062a\u0635\u0627\u0635 \u06cc\u0627\u0641\u062a. \u0627\u06cc\u0646 \u0627\u0642\u062f\u0627\u0645 \u0628\u0647 \u0628\u0627\u0646\u06a9\u200c\u0647\u0627 \u06a9\u0645\u06a9 \u06a9\u0631\u062f \u062a\u0627 \u0627\u0632 \u0628\u062d\u0631\u0627\u0646 \u0646\u0642\u062f\u06cc\u0646\u06af\u06cc \u0639\u0628\u0648\u0631 \u06a9\u0646\u0646\u062f \u0648 \u0627\u0639\u062a\u0645\u0627\u062f \u0628\u0647 \u0633\u06cc\u0633\u062a\u0645 \u0645\u0627\u0644\u06cc \u062f\u0648\u0628\u0627\u0631\u0647 \u0628\u0631\u0642\u0631\u0627\u0631 \u0634\u0648\u062f. \u0627\u06cc\u0646 \u0628\u0631\u0646\u0627\u0645\u0647 \u06cc\u06a9\u06cc \u0627\u0632 \u0627\u0635\u0644\u06cc\u200c\u062a\u0631\u06cc\u0646 \u0648\u0627\u06a9\u0646\u0634\u200c\u0647\u0627\u06cc \u062f\u0648\u0644\u062a \u0628\u0631\u0627\u06cc \u0645\u0642\u0627\u0628\u0644\u0647 \u0628\u0627 \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8 \u0628\u0648\u062f.<\/span><\/p><h3><b>\u0633\u06cc\u0627\u0633\u062a\u200c\u0647\u0627\u06cc \u0627\u0646\u0628\u0633\u0627\u0637\u06cc \u0641\u062f\u0631\u0627\u0644 \u0631\u0632\u0631\u0648 \u0648 \u06a9\u0627\u0647\u0634 \u0646\u0631\u062e \u0628\u0647\u0631\u0647<\/b><\/h3><p><span style=\"font-weight: 400;\">\u0641\u062f\u0631\u0627\u0644 \u0631\u0632\u0631\u0648 \u062f\u0631 \u0648\u0627\u06a9\u0646\u0634 \u0628\u0647 \u0628\u062d\u0631\u0627\u0646\u060c \u0646\u0631\u062e \u0628\u0647\u0631\u0647 \u0631\u0627 \u0628\u0647 \u0634\u062f\u062a \u06a9\u0627\u0647\u0634 \u062f\u0627\u062f \u0648 \u0628\u0631\u0646\u0627\u0645\u0647\u200c\u0647\u0627\u06cc <\/span><a href=\"https:\/\/arongroups.co\/fa\/glossary\/quantitative-easing-qe\/\"><span style=\"font-weight: 400;\">\u062a\u0633\u0647\u06cc\u0644 \u06a9\u0645\u06cc<\/span><\/a><span style=\"font-weight: 400;\"> \u0631\u0627 \u0628\u0631\u0627\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u0646\u0642\u062f\u06cc\u0646\u06af\u06cc \u0628\u0647 \u0628\u0627\u0632\u0627\u0631\u0647\u0627 \u0628\u0647 \u06a9\u0627\u0631 \u06af\u0631\u0641\u062a. \u0627\u06cc\u0646 \u0633\u06cc\u0627\u0633\u062a\u200c\u0647\u0627 \u0628\u0627\u0639\u062b \u0634\u062f \u06a9\u0647 \u0647\u0632\u06cc\u0646\u0647 \u0627\u0633\u062a\u0642\u0631\u0627\u0636 \u067e\u0627\u06cc\u06cc\u0646 \u0628\u06cc\u0627\u06cc\u062f \u0648 \u0628\u0627\u0646\u06a9\u200c\u0647\u0627 \u0628\u062a\u0648\u0627\u0646\u0646\u062f \u0631\u0627\u062d\u062a\u200c\u062a\u0631 \u0648\u0627\u0645 \u062f\u0647\u0646\u062f. \u0627\u06cc\u0646 \u0627\u0642\u062f\u0627\u0645\u0627\u062a \u0628\u0647 \u06a9\u0627\u0647\u0634 \u0634\u062f\u062a<\/span><a href=\"https:\/\/arongroups.co\/fa\/forex\/recognizing-economic-recession\/\"> <span style=\"font-weight: 400;\">\u0631\u06a9\u0648\u062f \u0627\u0642\u062a\u0635\u0627\u062f\u06cc<\/span><\/a><span style=\"font-weight: 400;\"> \u0648 \u0627\u062d\u06cc\u0627\u06cc \u0633\u0631\u06cc\u0639\u200c\u062a\u0631 \u0627\u0642\u062a\u0635\u0627\u062f \u06a9\u0645\u06a9 \u06a9\u0631\u062f\u0646\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d365fd2 elementor-widget elementor-widget-text-editor\" data-id=\"d365fd2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><b>\u0627\u0635\u0644\u0627\u062d\u0627\u062a \u0633\u0627\u062e\u062a\u0627\u0631\u06cc \u0648 \u0627\u06cc\u062c\u0627\u062f \u0642\u0648\u0627\u0646\u06cc\u0646 \u062c\u062f\u06cc\u062f \u0628\u0631\u0627\u06cc \u0646\u0638\u0627\u0631\u062a \u0645\u0627\u0644\u06cc<\/b><\/h3><p><span style=\"font-weight: 400;\">\u067e\u0633 \u0627\u0632 \u0628\u062d\u0631\u0627\u0646 2008\u060c \u0642\u0648\u0627\u0646\u06cc\u0646 \u062c\u062f\u06cc\u062f\u06cc \u0628\u0631\u0627\u06cc \u0646\u0638\u0627\u0631\u062a \u0628\u0631 \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc \u0648\u0636\u0639 \u0634\u062f. \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u0627\u06cc\u0646 \u0627\u0635\u0644\u0627\u062d\u0627\u062a\u060c \u0642\u0627\u0646\u0648\u0646 Dodd-Frank \u0628\u0648\u062f \u06a9\u0647 \u0647\u062f\u0641 \u0622\u0646 \u062a\u0642\u0648\u06cc\u062a \u0646\u0638\u0627\u0631\u062a \u0648 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u062a\u06a9\u0631\u0627\u0631 \u0628\u062d\u0631\u0627\u0646\u200c\u0647\u0627\u06cc \u0645\u0634\u0627\u0628\u0647 \u062f\u0631 \u0622\u06cc\u0646\u062f\u0647 \u0628\u0648\u062f. \u0627\u06cc\u0646 \u0627\u0635\u0644\u0627\u062d\u0627\u062a \u0628\u0647 \u0628\u0647\u0628\u0648\u062f \u0634\u0641\u0627\u0641\u06cc\u062a \u062f\u0631 \u0633\u06cc\u0633\u062a\u0645 \u0645\u0627\u0644\u06cc \u0648 \u06a9\u0627\u0647\u0634 \u0631\u06cc\u0633\u06a9\u200c\u0647\u0627\u06cc \u0646\u0638\u0627\u0645 \u0628\u0627\u0646\u06a9\u06cc \u06a9\u0645\u06a9 \u06a9\u0631\u062f\u0646\u062f \u0648 \u0628\u0631\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0628\u062d\u0631\u0627\u0646 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc\u200c\u0647\u0627\u06cc \u0645\u0634\u0627\u0628\u0647 \u062f\u0631 \u0622\u06cc\u0646\u062f\u0647 \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0646\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d302f3 elementor-widget elementor-widget-text-editor\" data-id=\"8d302f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><b>\u0631\u06a9\u0648\u062f \u0628\u0632\u0631\u06af \u06f2\u06f0\u06f0\u06f8 \u0648 \u0627\u062b\u0631\u0627\u062a \u0622\u0646 \u0628\u0631 \u0627\u0642\u062a\u0635\u0627\u062f \u062c\u0647\u0627\u0646\u06cc<\/b><\/h2><p><span style=\"font-weight: 400;\">\u0631\u06a9\u0648\u062f \u0628\u0632\u0631\u06af \u06f2\u06f0\u06f0\u06f8 \u06cc\u06a9\u06cc \u0627\u0632 \u0634\u062f\u06cc\u062f\u062a\u0631\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0628\u0648\u062f \u06a9\u0647 \u062a\u0623\u062b\u06cc\u0631\u0627\u062a \u0622\u0646 \u062f\u0631 \u0633\u0637\u062d \u062c\u0647\u0627\u0646\u06cc \u0645\u062d\u0633\u0648\u0633 \u0628\u0648\u062f. \u0627\u06cc\u0646 \u0631\u06a9\u0648\u062f \u0646\u0647 \u062a\u0646\u0647\u0627 \u062f\u0631 \u0627\u0642\u062a\u0635\u0627\u062f \u06a9\u0634\u0648\u0631\u0647\u0627\u06cc \u067e\u06cc\u0634\u0631\u0641\u062a\u0647 \u0627\u062b\u0631 \u06af\u0630\u0627\u0634\u062a \u0628\u0644\u06a9\u0647 \u06a9\u0634\u0648\u0631\u0647\u0627\u06cc \u062f\u0631 \u062d\u0627\u0644 \u062a\u0648\u0633\u0639\u0647 \u0646\u06cc\u0632 \u062a\u062d\u062a \u062a\u0623\u062b\u06cc\u0631 \u0622\u0646 \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a\u0646\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0628\u062e\u0634\u060c \u0628\u0647 \u0628\u0631\u0631\u0633\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u0628\u06cc\u06a9\u0627\u0631\u06cc\u060c \u06a9\u0627\u0647\u0634 \u062a\u0648\u0644\u06cc\u062f \u0648 \u062a\u0623\u062b\u06cc\u0631 \u0628\u062d\u0631\u0627\u0646 \u0628\u0631 \u06a9\u0634\u0648\u0631\u0647\u0627\u06cc \u062f\u0631 \u062d\u0627\u0644 \u062a\u0648\u0633\u0639\u0647 \u0648 \u0627\u0642\u062a\u0635\u0627\u062f \u0627\u06cc\u0631\u0627\u0646 \u0645\u06cc\u200c\u067e\u0631\u062f\u0627\u0632\u06cc\u0645.<\/span><\/p><h3><b>\u0627\u0641\u0632\u0627\u06cc\u0634 \u0628\u06cc\u06a9\u0627\u0631\u06cc \u0648 \u0633\u0642\u0648\u0637 \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u06cc \u0633\u0647\u0627\u0645<\/b><\/h3><p><span style=\"font-weight: 400;\">\u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8 \u0628\u0627\u0639\u062b \u0634\u062f \u06a9\u0647 \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u06cc \u0633\u0647\u0627\u0645 \u0628\u0647 \u0634\u062f\u062a \u0633\u0642\u0648\u0637 \u06a9\u0646\u0646\u062f \u0648 \u0646\u0631\u062e \u0628\u06cc\u06a9\u0627\u0631\u06cc \u062f\u0631 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u06a9\u0634\u0648\u0631\u0647\u0627 \u0628\u0627\u0644\u0627 \u0631\u0648\u062f. \u062f\u0631 \u0622\u0645\u0631\u06cc\u06a9\u0627\u060c \u0628\u06cc\u06a9\u0627\u0631\u06cc \u0628\u0647 \u06f1\u06f0 \u062f\u0631\u0635\u062f \u0631\u0633\u06cc\u062f \u0648 \u0645\u06cc\u0644\u06cc\u0648\u0646\u200c\u0647\u0627 \u0634\u063a\u0644 \u0627\u0632 \u062f\u0633\u062a \u0631\u0641\u062a. \u0627\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646 \u0647\u0645\u0686\u0646\u06cc\u0646 \u0628\u0627\u0639\u062b \u0634\u062f \u06a9\u0647 \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u06cc \u0633\u0647\u0627\u0645 \u062c\u0647\u0627\u0646\u06cc \u062f\u0686\u0627\u0631 \u0627\u0641\u062a \u0634\u062f\u06cc\u062f \u0634\u0648\u0646\u062f. \u0633\u0642\u0648\u0637 \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u060c \u06a9\u0627\u0647\u0634 \u0627\u0639\u062a\u0645\u0627\u062f \u0645\u0631\u062f\u0645 \u0628\u0647 \u0627\u0642\u062a\u0635\u0627\u062f \u0648 \u0645\u062d\u062f\u0648\u062f \u0634\u062f\u0646 \u0641\u0631\u0635\u062a\u200c\u0647\u0627\u06cc \u0634\u063a\u0644\u06cc \u0645\u0646\u062c\u0631 \u0628\u0647 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0628\u06cc\u06a9\u0627\u0631\u06cc \u0648 \u0628\u062d\u0631\u0627\u0646 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u062f\u0631 \u06a9\u0634\u0648\u0631\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0634\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e4943a elementor-widget elementor-widget-text-editor\" data-id=\"9e4943a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><b>\u06a9\u0627\u0647\u0634 \u062a\u0648\u0644\u06cc\u062f \u0648 \u062a\u0642\u0627\u0636\u0627\u06cc \u062c\u0647\u0627\u0646\u06cc \u062f\u0631 \u0633\u0627\u0644\u200c\u0647\u0627\u06cc \u06f2\u06f0\u06f0\u06f8 \u062a\u0627 \u06f2\u06f0\u06f1\u06f0<\/b><\/h3><p><span style=\"font-weight: 400;\">\u0631\u06a9\u0648\u062f \u0628\u0632\u0631\u06af \u06f2\u06f0\u06f0\u06f8 \u0628\u0627\u0639\u062b \u0634\u062f \u06a9\u0647 \u062a\u0648\u0644\u06cc\u062f \u0635\u0646\u0639\u062a\u06cc \u062f\u0631 \u06a9\u0634\u0648\u0631\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u06a9\u0627\u0647\u0634 \u06cc\u0627\u0628\u062f \u0648 \u062a\u0642\u0627\u0636\u0627\u06cc \u062c\u0647\u0627\u0646\u06cc \u0628\u0631\u0627\u06cc \u06a9\u0627\u0644\u0627 \u0648 \u062e\u062f\u0645\u0627\u062a \u0628\u0647 \u0634\u062f\u062a \u067e\u0627\u06cc\u06cc\u0646 \u0628\u06cc\u0627\u06cc\u062f. \u0627\u06cc\u0646 \u0631\u06a9\u0648\u062f \u0645\u0648\u062c\u0628 \u0634\u062f \u06a9\u0647 \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u06a9\u0627\u0631\u062e\u0627\u0646\u0647\u200c\u0647\u0627 \u062a\u0648\u0644\u06cc\u062f\u0627\u062a \u062e\u0648\u062f \u0631\u0627 \u06a9\u0627\u0647\u0634 \u062f\u0647\u0646\u062f \u0648 \u062a\u062c\u0627\u0631\u062a \u062c\u0647\u0627\u0646\u06cc \u0646\u06cc\u0632 \u0628\u0647 \u0634\u062f\u062a \u0627\u0641\u062a \u06a9\u0646\u062f. \u06a9\u0627\u0647\u0634 \u062a\u0642\u0627\u0636\u0627\u060c \u06a9\u0627\u0647\u0634 \u0635\u0627\u062f\u0631\u0627\u062a \u0648 \u062a\u0648\u0644\u06cc\u062f \u062f\u0631 \u0633\u0637\u062d \u062c\u0647\u0627\u0646\u06cc \u0628\u0647 \u0645\u0634\u06a9\u0644\u0627\u062a \u062c\u062f\u06cc \u062f\u0631 \u0627\u0642\u062a\u0635\u0627\u062f\u0647\u0627\u06cc \u0628\u0632\u0631\u06af \u0648 \u06a9\u0648\u0686\u06a9 \u062f\u0627\u0645\u0646 \u0632\u062f.<\/span><\/p><h3><b>\u062a\u0623\u062b\u06cc\u0631 \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc 2008 \u0628\u0631 \u06a9\u0634\u0648\u0631\u0647\u0627\u06cc \u062f\u0631 \u062d\u0627\u0644 \u062a\u0648\u0633\u0639\u0647 \u0648 \u0627\u0642\u062a\u0635\u0627\u062f \u0627\u06cc\u0631\u0627\u0646<\/b><\/h3><p><span style=\"font-weight: 400;\">\u0628\u062d\u0631\u0627\u0646 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0628\u0631 \u06a9\u0634\u0648\u0631\u0647\u0627\u06cc \u062f\u0631 \u062d\u0627\u0644 \u062a\u0648\u0633\u0639\u0647 \u0646\u06cc\u0632 \u062a\u0627\u062b\u06cc\u0631 \u0632\u06cc\u0627\u062f\u06cc \u062f\u0627\u0634\u062a. \u06a9\u0627\u0647\u0634 \u0635\u0627\u062f\u0631\u0627\u062a\u060c \u06a9\u0627\u0647\u0634 \u0648\u0631\u0648\u062f \u0633\u0631\u0645\u0627\u06cc\u0647 \u0648 \u0645\u0634\u06a9\u0644\u0627\u062a \u0646\u0642\u062f\u06cc\u0646\u06af\u06cc \u0628\u0627\u0639\u062b \u0634\u062f \u06a9\u0647 \u0627\u0642\u062a\u0635\u0627\u062f\u0647\u0627\u06cc \u0627\u06cc\u0646 \u06a9\u0634\u0648\u0631\u0647\u0627 \u062f\u0686\u0627\u0631 \u0645\u0634\u06a9\u0644 \u0634\u0648\u0646\u062f. \u0628\u0631\u0627\u06cc \u0645\u062b\u0627\u0644\u060c \u0627\u06cc\u0631\u0627\u0646 \u06a9\u0647 \u0628\u0647 \u0634\u062f\u062a \u0648\u0627\u0628\u0633\u062a\u0647 \u0628\u0647 \u0635\u0627\u062f\u0631\u0627\u062a \u0646\u0641\u062a \u0627\u0633\u062a\u060c \u062a\u062d\u062a \u062a\u0627\u062b\u06cc\u0631 \u0627\u0641\u062a \u0642\u06cc\u0645\u062a \u0646\u0641\u062a \u0648 \u06a9\u0627\u0647\u0634 \u062a\u0642\u0627\u0636\u0627 \u0642\u0631\u0627\u0631 \u06af\u0631\u0641\u062a. \u0641\u0634\u0627\u0631 \u0628\u0631 \u0646\u0631\u062e \u0627\u0631\u0632 \u0648 \u06a9\u0627\u0647\u0634 \u0627\u0631\u0632\u0634 \u0631\u06cc\u0627\u0644\u060c \u06cc\u06a9\u06cc \u0627\u0632 \u0622\u062b\u0627\u0631 \u0645\u0647\u0645 \u0628\u062d\u0631\u0627\u0646 \u0628\u0631 \u0627\u0642\u062a\u0635\u0627\u062f \u0627\u06cc\u0631\u0627\u0646 \u0628\u0648\u062f \u06a9\u0647 \u0647\u0645\u0686\u0646\u0627\u0646 \u062a\u0623\u062b\u06cc\u0631\u0627\u062a \u0622\u0646 \u0627\u062d\u0633\u0627\u0633 \u0645\u06cc\u200c\u0634\u0648\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f3494d elementor-widget elementor-widget-text-editor\" data-id=\"0f3494d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><b>\u0628\u0627\u0632\u06cc\u0627\u0628\u06cc \u062a\u062f\u0631\u06cc\u062c\u06cc \u0627\u0642\u062a\u0635\u0627\u062f \u062c\u0647\u0627\u0646\u06cc \u067e\u0633 \u0627\u0632 \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc\u202f\u06f2\u06f0\u06f0\u06f8<\/b><\/h2><p><span style=\"font-weight: 400;\">\u067e\u0633 \u0627\u0632 \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8\u060c \u0627\u0642\u062a\u0635\u0627\u062f \u062c\u0647\u0627\u0646\u06cc \u0648\u0627\u0631\u062f \u0641\u0627\u0632 \u0628\u0627\u0632\u06cc\u0627\u0628\u06cc \u0634\u062f. \u062f\u0648\u0644\u062a\u200c\u0647\u0627 \u0648 \u0628\u0627\u0646\u06a9\u200c\u0647\u0627\u06cc \u0645\u0631\u06a9\u0632\u06cc \u0627\u0642\u062f\u0627\u0645\u0627\u062a \u0645\u062e\u062a\u0644\u0641\u06cc \u0627\u0646\u062c\u0627\u0645 \u062f\u0627\u062f\u0646\u062f \u062a\u0627 \u0628\u0647 \u0627\u0642\u062a\u0635\u0627\u062f\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u06a9\u0645\u06a9 \u06a9\u0646\u0646\u062f \u06a9\u0647 \u0627\u0632 \u0631\u06a9\u0648\u062f \u0639\u0645\u06cc\u0642 \u062e\u0627\u0631\u062c \u0634\u0648\u0646\u062f. \u0627\u06cc\u0646 \u0627\u0642\u062f\u0627\u0645\u0627\u062a \u0634\u0627\u0645\u0644:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0628\u0633\u062a\u0647\u200c\u0647\u0627\u06cc \u0645\u062d\u0631\u06a9 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc\u061b<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0627\u0635\u0644\u0627\u062d\u0627\u062a \u0645\u0627\u0644\u06cc\u061b<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0648 \u062a\u063a\u06cc\u06cc\u0631 \u0631\u0641\u062a\u0627\u0631 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646 \u0628\u0648\u062f \u06a9\u0647 \u0628\u0647 \u062a\u062f\u0631\u06cc\u062c \u0628\u0627\u0639\u062b \u0628\u0627\u0632\u0633\u0627\u0632\u06cc \u0627\u0642\u062a\u0635\u0627\u062f \u062c\u0647\u0627\u0646\u06cc \u0634\u062f\u0646\u062f.<\/span><\/li><\/ul><h3><b>\u0646\u0642\u0634 \u0628\u0633\u062a\u0647\u200c\u0647\u0627\u06cc \u0645\u062d\u0631\u06a9 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u062f\u0631 \u062e\u0631\u0648\u062c \u0627\u0632 \u0631\u06a9\u0648\u062f<\/b><\/h3><p><span style=\"font-weight: 400;\">\u0628\u0631\u0627\u06cc \u0645\u0642\u0627\u0628\u0644\u0647 \u0628\u0627 \u0631\u06a9\u0648\u062f \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0646\u0627\u0634\u06cc \u0627\u0632 \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8\u060c \u062f\u0648\u0644\u062a\u200c\u0647\u0627 \u0628\u0633\u062a\u0647\u200c\u0647\u0627\u06cc \u0645\u062d\u0631\u06a9 \u0645\u0627\u0644\u06cc \u0628\u0632\u0631\u06af\u06cc \u0628\u0647 \u0628\u0627\u0632\u0627\u0631 \u0648\u0627\u0631\u062f \u06a9\u0631\u062f\u0646\u062f. \u0627\u06cc\u0646 \u0628\u0633\u062a\u0647\u200c\u0647\u0627 \u0634\u0627\u0645\u0644 \u062a\u0632\u0631\u06cc\u0642 \u067e\u0648\u0644 \u0628\u0647 \u0633\u06cc\u0633\u062a\u0645 \u0645\u0627\u0644\u06cc\u060c \u06a9\u0627\u0647\u0634 \u0645\u0627\u0644\u06cc\u0627\u062a\u200c\u0647\u0627 \u0648 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u062f\u0631 \u067e\u0631\u0648\u0698\u0647\u200c\u0647\u0627\u06cc \u0632\u06cc\u0631\u0633\u0627\u062e\u062a\u06cc \u0628\u0648\u062f\u0646\u062f. \u0647\u062f\u0641 \u0627\u06cc\u0646 \u0627\u0642\u062f\u0627\u0645\u0627\u062a \u062a\u0642\u0648\u06cc\u062a \u062a\u0642\u0627\u0636\u0627 \u0648 \u0631\u0634\u062f \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0628\u0648\u062f \u062a\u0627 \u0627\u0642\u062a\u0635\u0627\u062f\u0647\u0627\u06cc \u0645\u062e\u062a\u0644\u0641 \u0627\u0632 \u0631\u06a9\u0648\u062f \u062e\u0627\u0631\u062c \u0634\u0648\u0646\u062f. \u0627\u06cc\u0646 \u0628\u0633\u062a\u0647\u200c\u0647\u0627\u06cc \u0645\u062d\u0631\u06a9 \u0628\u0647 \u0627\u06cc\u062c\u0627\u062f \u0634\u063a\u0644 \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0645\u0635\u0631\u0641 \u06a9\u0645\u06a9 \u06a9\u0631\u062f\u0646\u062f \u0648 \u0628\u062e\u0634 \u0632\u06cc\u0627\u062f\u06cc \u0627\u0632 \u0627\u062b\u0631\u0627\u062a \u0645\u0646\u0641\u06cc \u0628\u062d\u0631\u0627\u0646 \u0631\u0627 \u06a9\u0627\u0647\u0634 \u062f\u0627\u062f\u0646\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-998b12d elementor-widget elementor-widget-text-editor\" data-id=\"998b12d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><b>\u0638\u0647\u0648\u0631 \u0627\u0635\u0644\u0627\u062d\u0627\u062a \u0645\u0627\u0644\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u0648 \u0646\u0638\u0627\u0631\u062a \u0628\u0631 \u0628\u0627\u0646\u06a9\u200c\u0647\u0627<\/b><\/h3><p><span style=\"font-weight: 400;\">\u067e\u0633 \u0627\u0632 \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8\u060c \u0646\u0638\u0627\u0645 \u0645\u0627\u0644\u06cc \u062c\u0647\u0627\u0646\u06cc \u0648\u0627\u0631\u062f \u0645\u0631\u062d\u0644\u0647\u200c\u0627\u06cc \u0627\u0632 \u0628\u0627\u0632\u0646\u06af\u0631\u06cc \u0639\u0645\u06cc\u0642 \u0634\u062f \u0648 \u0645\u062c\u0645\u0648\u0639\u0647\u200c\u0627\u06cc \u0627\u0632 \u0627\u0635\u0644\u0627\u062d\u0627\u062a \u0645\u0627\u0644\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u0628\u0627 \u0647\u062f\u0641 \u06a9\u0627\u0647\u0634 <\/span><a href=\"https:\/\/arongroups.co\/fa\/forex\/%D8%B1%DB%8C%D8%B3%DA%A9-%D8%AE%D8%A7%D8%B5-%DA%86%DB%8C%D8%B3%D8%AA%D8%9F-%D8%B1%D8%A7%D9%87%D9%86%D9%85%D8%A7%DB%8C-%D9%85%D8%A8%D8%AA%D8%AF%DB%8C%D8%A7%D9%86\/\"><span style=\"font-weight: 400;\">\u0631\u06cc\u0633\u06a9 \u0633\u06cc\u0633\u062a\u0645\u0627\u062a\u06cc\u06a9<\/span><\/a><span style=\"font-weight: 400;\"> \u0648 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u062a\u06a9\u0631\u0627\u0631 \u0634\u0648\u06a9\u200c\u0647\u0627\u06cc \u0645\u0634\u0627\u0628\u0647 \u062a\u062f\u0648\u06cc\u0646 \u06af\u0631\u062f\u06cc\u062f. \u0645\u062d\u0648\u0631 \u0627\u0635\u0644\u06cc \u0627\u06cc\u0646 \u0627\u0635\u0644\u0627\u062d\u0627\u062a\u060c \u062a\u0642\u0648\u06cc\u062a \u0646\u0638\u0627\u0631\u062a \u0628\u0631 \u0628\u0627\u0646\u06a9\u200c\u0647\u0627\u060c \u0627\u0644\u0632\u0627\u0645 \u0646\u0647\u0627\u062f\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc \u0628\u0647 \u0634\u0641\u0627\u0641\u06cc\u062a \u0628\u06cc\u0634\u062a\u0631 \u0648 \u0628\u0647\u0628\u0648\u062f \u0633\u0627\u062e\u062a\u0627\u0631 \u0633\u0631\u0645\u0627\u06cc\u0647 \u0628\u0648\u062f.<\/span><\/p><p><span style=\"font-weight: 400;\">\u062f\u0631 \u0627\u06cc\u0646 \u062f\u0648\u0631\u0647\u060c \u06a9\u0645\u06cc\u062a\u0647 \u0628\u0627\u0632\u0644 \u0645\u0642\u0631\u0631\u0627\u062a Basel III \u0631\u0627 \u0645\u0639\u0631\u0641\u06cc \u06a9\u0631\u062f \u06a9\u0647 \u0645\u062c\u0645\u0648\u0639\u0647\u200c\u0627\u06cc \u0627\u0632 \u0627\u0633\u062a\u0627\u0646\u062f\u0627\u0631\u062f\u0647\u0627\u06cc \u0627\u0644\u0632\u0627\u0645\u200c\u0622\u0648\u0631 \u0634\u0627\u0645\u0644 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062d\u062f\u0627\u0642\u0644 \u06a9\u0641\u0627\u06cc\u062a \u0633\u0631\u0645\u0627\u06cc\u0647\u060c \u062a\u0639\u0631\u06cc\u0641 \u0628\u0627\u0641\u0631\u0647\u0627\u06cc \u062d\u0641\u0627\u0638\u062a\u06cc (Capital Buffers)\u060c \u0627\u0644\u0632\u0627\u0645\u0627\u062a \u0633\u062e\u062a\u200c\u06af\u06cc\u0631\u0627\u0646\u0647\u200c\u062a\u0631 \u0646\u0642\u062f\u06cc\u0646\u06af\u06cc (LCR \u0648 NSFR) \u0648 \u0645\u062d\u062f\u0648\u062f\u06cc\u062a\u200c\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f \u0628\u0631\u0627\u06cc \u0627\u0647\u0631\u0645 \u0645\u0627\u0644\u06cc (Leverage Ratio) \u0628\u0648\u062f. \u0627\u06cc\u0646 \u0645\u0642\u0631\u0631\u0627\u062a \u0637\u0631\u0627\u062d\u06cc \u0634\u062f\u0646\u062f \u062a\u0627 \u0628\u0627\u0646\u06a9\u200c\u0647\u0627 \u062f\u0631 \u0628\u0631\u0627\u0628\u0631 \u0628\u062d\u0631\u0627\u0646\u200c\u0647\u0627 \u0645\u0642\u0627\u0648\u0645\u200c\u062a\u0631 \u0634\u0648\u0646\u062f \u0648 \u062a\u0648\u0627\u0646 \u062a\u062d\u0645\u0644 \u0632\u06cc\u0627\u0646\u200c\u0647\u0627\u06cc \u0646\u0627\u06af\u0647\u0627\u0646\u06cc \u0631\u0627 \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f.<\/span><\/p><p><span style=\"font-weight: 400;\">\u0647\u0645\u200c \u0632\u0645\u0627\u0646\u060c \u0628\u0633\u06cc\u0627\u0631\u06cc \u0627\u0632 \u06a9\u0634\u0648\u0631\u0647\u0627 \u0642\u0648\u0627\u0646\u06cc\u0646 \u062f\u0627\u062e\u0644\u06cc \u062e\u0648\u062f \u0631\u0627 \u0627\u0635\u0644\u0627\u062d \u06a9\u0631\u062f\u0646\u062f. \u0628\u0631\u0627\u06cc \u0645\u062b\u0627\u0644\u060c \u0642\u0627\u0646\u0648\u0646 Dodd\u2013Frank \u062f\u0631 \u0622\u0645\u0631\u06cc\u06a9\u0627 \u0645\u062d\u062f\u0648\u062f\u06cc\u062a\u200c\u0647\u0627\u06cc \u06af\u0633\u062a\u0631\u062f\u0647\u200c\u062a\u0631\u06cc \u0628\u0631\u0627\u06cc \u0628\u0627\u0646\u06a9\u200c\u0647\u0627\u06cc \u0628\u0632\u0631\u06af \u0648\u0636\u0639 \u06a9\u0631\u062f \u0648 \u0646\u0638\u0627\u0631\u062a \u0628\u0631 \u062f\u0627\u0631\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc \u067e\u0631\u0631\u06cc\u0633\u06a9 \u0648 \u0645\u0639\u0627\u0645\u0644\u0627\u062a \u0645\u0634\u062a\u0642\u0647 \u0631\u0627 \u0627\u0641\u0632\u0627\u06cc\u0634 \u062f\u0627\u062f. \u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0634\u0648\u0631\u0627\u0647\u0627\u06cc \u0646\u0627\u0638\u0631 \u0645\u0646\u0637\u0642\u0647\u200c\u0627\u06cc \u0648 \u062c\u0647\u0627\u0646\u06cc \u0645\u0627\u0646\u0646\u062f FSB (\u0647\u06cc\u0626\u062a \u062b\u0628\u0627\u062a \u0645\u0627\u0644\u06cc) \u0645\u0633\u0626\u0648\u0644\u06cc\u062a \u0647\u0645\u0627\u0647\u0646\u06af\u06cc \u0645\u06cc\u0627\u0646 \u0646\u0647\u0627\u062f\u0647\u0627\u06cc \u0646\u0638\u0627\u0631\u062a\u06cc \u0631\u0627 \u0628\u0631 \u0639\u0647\u062f\u0647 \u06af\u0631\u0641\u062a\u0646\u062f.<\/span><\/p><p><span style=\"font-weight: 400;\">\u0627\u06cc\u0646 \u0627\u0635\u0644\u0627\u062d\u0627\u062a\u060c \u0645\u062c\u0645\u0648\u0639\u0647\u200c\u0627\u06cc \u06cc\u06a9\u067e\u0627\u0631\u0686\u0647 \u0627\u0632 \u0645\u0642\u0631\u0631\u0627\u062a \u0631\u0627 \u0634\u06a9\u0644 \u062f\u0627\u062f\u0646\u062f \u06a9\u0647 \u0647\u062f\u0641 \u0622\u0646\u200c\u0647\u0627 \u062a\u0642\u0648\u06cc\u062a \u0633\u0644\u0627\u0645\u062a \u0628\u0627\u0646\u06a9\u200c\u0647\u0627\u060c \u06a9\u0627\u0647\u0634 \u0648\u0627\u0628\u0633\u062a\u06af\u06cc \u0628\u0647 \u0628\u062f\u0647\u06cc\u060c \u0645\u062f\u06cc\u0631\u06cc\u062a \u0628\u0647\u062a\u0631 \u0631\u06cc\u0633\u06a9 \u0646\u0642\u062f\u06cc\u0646\u06af\u06cc \u0648 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0641\u0631\u0648\u067e\u0627\u0634\u06cc \u0632\u0646\u062c\u06cc\u0631\u0647\u200c\u0627\u06cc \u0645\u0624\u0633\u0633\u0627\u062a \u0645\u0627\u0644\u06cc \u0628\u0648\u062f. \u0628\u0647\u200c \u0627\u06cc\u0646\u200c \u062a\u0631\u062a\u06cc\u0628\u060c \u0646\u0638\u0627\u0631\u062a \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u0628\u0631 \u0628\u0627\u0646\u06a9\u200c\u0647\u0627 \u0648\u0627\u0631\u062f \u0645\u0631\u062d\u0644\u0647\u200c\u0627\u06cc \u062c\u062f\u06cc\u062f\u060c \u0645\u0646\u0633\u062c\u0645 \u0648 \u0633\u062e\u062a\u200c\u06af\u06cc\u0631\u0627\u0646\u0647 \u0634\u062f \u06a9\u0647 \u062a\u0627 \u0627\u0645\u0631\u0648\u0632 \u0646\u06cc\u0632 \u0686\u0627\u0631\u0686\u0648\u0628 \u0627\u0635\u0644\u06cc \u0646\u0638\u0627\u0645 \u0645\u0627\u0644\u06cc \u062c\u0647\u0627\u0646 \u0631\u0627 \u062a\u0634\u06a9\u06cc\u0644 \u0645\u06cc\u200c\u062f\u0647\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3f0d6b5 elementor-widget elementor-widget-text-editor\" data-id=\"3f0d6b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><b>\u062a\u063a\u06cc\u06cc\u0631 \u0631\u0641\u062a\u0627\u0631 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646 \u0648 \u0627\u062d\u062a\u06cc\u0627\u0637 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u06cc \u0631\u06cc\u0633\u06a9\u06cc<\/b><\/h3><p><span style=\"font-weight: 400;\">\u067e\u0633 \u0627\u0632 \u0628\u062d\u0631\u0627\u0646 \u06f2\u06f0\u06f0\u06f8\u060c \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646 \u0646\u0633\u0628\u062a \u0628\u0647 \u0631\u06cc\u0633\u06a9\u200c\u0647\u0627 \u0628\u0633\u06cc\u0627\u0631 \u0645\u062d\u062a\u0627\u0637\u200c\u062a\u0631 \u0634\u062f\u0646\u062f. \u0627\u0639\u062a\u0645\u0627\u062f \u0628\u0647 \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc \u06a9\u0627\u0647\u0634 \u06cc\u0627\u0641\u062a \u0648 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u0627\u0628\u0632\u0627\u0631\u0647\u0627\u06cc\u06cc \u0628\u0627 \u0631\u06cc\u0633\u06a9 \u06a9\u0645\u062a\u0631 \u0631\u0641\u062a\u0646\u062f. \u062f\u0631 \u0627\u06cc\u0646 \u0628\u06cc\u0646\u060c \u0628\u0631\u062e\u06cc \u0627\u0632 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646 \u0628\u0647 \u062f\u0646\u0628\u0627\u0644 \u062f\u0627\u0631\u0627\u06cc\u06cc\u200c\u0647\u0627\u06cc \u062c\u062f\u06cc\u062f\u062a\u0631 \u0648 \u06a9\u0645\u200c\u0631\u06cc\u0633\u06a9\u200c\u062a\u0631\u06cc \u0645\u0627\u0646\u0646\u062f \u0628\u06cc\u062a\u200c \u06a9\u0648\u06cc\u0646 \u0631\u0641\u062a\u0646\u062f. \u0627\u06cc\u0646 \u062a\u063a\u06cc\u06cc\u0631 \u062f\u0631 \u0631\u0641\u062a\u0627\u0631 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646 \u0628\u0647 \u0645\u0639\u0646\u0627\u06cc \u0627\u0631\u0632\u06cc\u0627\u0628\u06cc \u062f\u0642\u06cc\u0642\u200c\u062a\u0631 \u0631\u06cc\u0633\u06a9\u200c\u0647\u0627 \u0648 \u0645\u062f\u06cc\u0631\u06cc\u062a \u0628\u0647\u062a\u0631 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u0647\u0627 \u0628\u0648\u062f \u06a9\u0647 \u0628\u0647 \u062a\u0642\u0648\u06cc\u062a \u062b\u0628\u0627\u062a \u0628\u0627\u0632\u0627\u0631 \u06a9\u0645\u06a9 \u06a9\u0631\u062f.<\/span><\/p><h2><b>\u062f\u0631\u0633\u200c\u0647\u0627\u06cc\u06cc \u0627\u0632 \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8 \u0628\u0631\u0627\u06cc \u0622\u06cc\u0646\u062f\u0647 \u0627\u0642\u062a\u0635\u0627\u062f<\/b><\/h2><p><span style=\"font-weight: 400;\">\u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8\u060c \u0627\u06af\u0631\u0686\u0647 \u06cc\u06a9 \u0634\u0648\u06a9 \u0639\u0638\u06cc\u0645 \u0628\u0631\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f \u062c\u0647\u0627\u0646\u06cc \u0628\u0648\u062f\u060c \u0627\u0645\u0627 \u062f\u0631\u0633\u200c\u0647\u0627\u06cc \u0645\u0647\u0645\u06cc \u0628\u0631\u0627\u06cc \u0622\u06cc\u0646\u062f\u0647 \u062f\u0627\u0634\u062a. \u0627\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646 \u0646\u0634\u0627\u0646 \u062f\u0627\u062f \u06a9\u0647 \u0633\u06cc\u0633\u062a\u0645\u200c\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc \u0628\u0627\u06cc\u062f \u0634\u0641\u0627\u0641 \u0648 \u067e\u0627\u0633\u062e\u06af\u0648 \u0628\u0627\u0634\u0646\u062f\u060c \u0645\u0631\u062f\u0645 \u0628\u0627\u06cc\u062f \u062f\u0627\u0646\u0634 \u0645\u0627\u0644\u06cc \u0648 \u0622\u06af\u0627\u0647\u06cc \u0627\u0632 \u0631\u06cc\u0633\u06a9\u200c\u0647\u0627\u06cc \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f \u0648 \u0628\u0647\u0628\u0648\u062f \u0646\u0638\u0627\u0631\u062a \u0648 \u0633\u06cc\u0627\u0633\u062a\u200c\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc \u0628\u0631\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u062a\u06a9\u0631\u0627\u0631 \u0628\u062d\u0631\u0627\u0646\u200c\u0647\u0627\u06cc \u0645\u0634\u0627\u0628\u0647 \u0636\u0631\u0648\u0631\u06cc \u0627\u0633\u062a.<\/span><\/p><h3><b>\u0627\u0647\u0645\u06cc\u062a \u0634\u0641\u0627\u0641\u06cc\u062a \u0648 \u067e\u0627\u0633\u062e\u200c\u06af\u0648\u06cc\u06cc \u062f\u0631 \u0633\u06cc\u0633\u062a\u0645 \u0645\u0627\u0644\u06cc<\/b><\/h3><p><span style=\"font-weight: 400;\">\u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u062f\u0631\u0633\u200c\u0647\u0627\u06cc \u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8 \u0627\u06cc\u0646 \u0627\u0633\u062a \u06a9\u0647 \u0646\u0638\u0627\u0645 \u0645\u0627\u0644\u06cc \u0628\u0627\u06cc\u062f \u0634\u0641\u0627\u0641 \u0648 \u067e\u0627\u0633\u062e\u06af\u0648 \u0628\u0627\u0634\u062f. \u0645\u0648\u0633\u0633\u0627\u062a \u0645\u0627\u0644\u06cc \u0628\u0627\u06cc\u062f \u0627\u0637\u0644\u0627\u0639\u0627\u062a \u062f\u0642\u06cc\u0642 \u0648 \u0628\u0647\u200c \u0645\u0648\u0642\u0639 \u062f\u0631\u0628\u0627\u0631\u0647 \u0648\u0636\u0639\u06cc\u062a \u0645\u0627\u0644\u06cc \u062e\u0648\u062f \u0628\u0647 \u0639\u0645\u0648\u0645 \u0645\u0631\u062f\u0645 \u0648 \u0646\u0647\u0627\u062f\u0647\u0627\u06cc \u0646\u0638\u0627\u0631\u062a\u06cc \u0627\u0631\u0627\u0626\u0647 \u062f\u0647\u0646\u062f. \u0634\u0641\u0627\u0641\u06cc\u062a \u0628\u0627\u0639\u062b \u0645\u06cc\u200c\u0634\u0648\u062f \u06a9\u0647 \u0631\u06cc\u0633\u06a9\u200c\u0647\u0627 \u0632\u0648\u062f\u062a\u0631 \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u0634\u0648\u0646\u062f \u0648 \u062a\u0635\u0645\u06cc\u0645\u200c\u06af\u06cc\u0631\u06cc\u200c\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc \u0628\u0647\u062a\u0631 \u0648 \u0622\u06af\u0627\u0647\u0627\u0646\u0647\u200c\u062a\u0631 \u0627\u0646\u062c\u0627\u0645 \u0634\u0648\u062f. \u0646\u0638\u0627\u0631\u062a \u062f\u0642\u06cc\u0642 \u0648 \u0645\u0624\u062b\u0631 \u0628\u0631 \u0641\u0639\u0627\u0644\u06cc\u062a\u200c\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0627\u0632 \u0628\u0631\u0648\u0632 \u0628\u062d\u0631\u0627\u0646\u200c\u0647\u0627\u06cc \u0645\u0634\u0627\u0628\u0647 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u06a9\u0646\u062f \u0648 \u0627\u0632 \u0627\u06cc\u0646\u200c\u0631\u0648 \u0627\u0647\u0645\u06cc\u062a \u0632\u06cc\u0627\u062f\u06cc \u062f\u0627\u0631\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1993717 elementor-widget elementor-widget-text-editor\" data-id=\"1993717\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h3><b>\u0644\u0632\u0648\u0645 \u0622\u0645\u0648\u0632\u0634 \u0645\u0627\u0644\u06cc \u0639\u0645\u0648\u0645\u06cc \u0648 \u0645\u062f\u06cc\u0631\u06cc\u062a \u0631\u06cc\u0633\u06a9 \u062f\u0631 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc<\/b><\/h3><p><span style=\"font-weight: 400;\">\u0628\u062d\u0631\u0627\u0646 \u0645\u0633\u06a9\u0646 \u0622\u0645\u0631\u06cc\u06a9\u0627 \u0648 \u0628\u0647 \u062a\u0628\u0639 \u0622\u0646 \u0628\u062d\u0631\u0627\u0646 \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0646\u0634\u0627\u0646 \u062f\u0627\u062f \u06a9\u0647 \u0645\u0631\u062f\u0645 \u0648 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u0627\u0646 \u0646\u06cc\u0627\u0632 \u062f\u0627\u0631\u0646\u062f \u062a\u0627 \u0627\u0632 \u0646\u0638\u0631 \u0645\u0627\u0644\u06cc \u0622\u06af\u0627\u0647\u200c\u062a\u0631 \u0634\u0648\u0646\u062f. \u0622\u06af\u0627\u0647\u06cc \u0627\u0632 \u0627\u0635\u0648\u0644 <\/span><a href=\"https:\/\/arongroups.co\/fa\/forex\/risk-management\/\"><span style=\"font-weight: 400;\">\u0645\u062f\u06cc\u0631\u06cc\u062a \u0631\u06cc\u0633\u06a9<\/span><\/a><span style=\"font-weight: 400;\">\u060c \u0634\u0646\u0627\u062e\u062a \u062f\u0642\u06cc\u0642 \u0627\u0632 \u0627\u0646\u0648\u0627\u0639 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc\u200c\u0647\u0627 \u0648 \u062a\u0648\u0627\u0646\u0627\u06cc\u06cc \u0627\u0631\u0632\u06cc\u0627\u0628\u06cc \u0631\u06cc\u0633\u06a9\u200c\u0647\u0627 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0627\u0632 \u0648\u0642\u0648\u0639 \u062d\u0628\u0627\u0628\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0648 \u0645\u0634\u06a9\u0644\u0627\u062a \u0645\u0634\u0627\u0628\u0647 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u06a9\u0646\u062f. \u0622\u0645\u0648\u0632\u0634 \u0645\u0627\u0644\u06cc \u0639\u0645\u0648\u0645\u06cc \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u06a9\u0645\u06a9 \u06a9\u0646\u062f \u062a\u0627 \u0627\u0641\u0631\u0627\u062f \u062a\u0635\u0645\u06cc\u0645\u0627\u062a \u0628\u0647\u062a\u0631\u06cc \u062f\u0631 \u0645\u0648\u0631\u062f \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc \u0628\u06af\u06cc\u0631\u0646\u062f \u0648 \u062e\u0637\u0631\u0627\u062a \u0631\u0627 \u0628\u0647\u062a\u0631 \u062f\u0631\u06a9 \u06a9\u0646\u0646\u062f.<\/span><\/p><h3><b>\u067e\u06cc\u0634\u200c\u0628\u06cc\u0646\u06cc \u0628\u062d\u0631\u0627\u0646\u200c\u0647\u0627\u06cc \u0622\u06cc\u0646\u062f\u0647 \u0648 \u0631\u0627\u0647\u06a9\u0627\u0631\u0647\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u062a\u06a9\u0631\u0627\u0631 \u0622\u0646<\/b><\/h3><p><span style=\"font-weight: 400;\">\u0628\u0631\u0627\u06cc \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0627\u0632 \u0628\u062d\u0631\u0627\u0646\u200c\u0647\u0627\u06cc\u06cc \u0645\u0627\u0646\u0646\u062f \u0631\u06a9\u0648\u062f \u0628\u0632\u0631\u06af \u06f2\u06f0\u06f0\u06f8\u060c \u067e\u06cc\u0634\u0646\u0647\u0627\u062f \u0645\u06cc\u200c\u0634\u0648\u062f:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0646\u0638\u0627\u0631\u062a\u200c\u0647\u0627\u06cc \u0628\u06cc\u0646\u200c\u0627\u0644\u0645\u0644\u0644\u06cc \u062a\u0642\u0648\u06cc\u062a \u0634\u0648\u0646\u062f\u061b<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u0627\u0628\u0632\u0627\u0631\u0647\u0627\u06cc \u0646\u0638\u0627\u0631\u062a\u06cc \u062f\u0642\u06cc\u0642\u200c\u062a\u0631 \u0648 \u06a9\u0627\u0631\u0622\u0645\u062f\u062a\u0631\u06cc \u0628\u0631\u0627\u06cc \u0634\u0646\u0627\u0633\u0627\u06cc\u06cc \u0631\u06cc\u0633\u06a9\u200c\u0647\u0627 \u0627\u06cc\u062c\u0627\u062f \u0634\u0648\u0646\u062f\u061b<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u06a9\u0646\u062a\u0631\u0644 \u0628\u0631 \u0627\u0647\u0631\u0645 \u0645\u0627\u0644\u06cc \u0627\u0641\u0632\u0627\u06cc\u0634 \u06cc\u0627\u0628\u062f.\u00a0<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">\u0647\u0645\u0686\u0646\u06cc\u0646\u060c \u0631\u0641\u062a\u0627\u0631 \u0627\u062e\u0644\u0627\u0642\u06cc \u062f\u0631 \u0628\u0627\u0646\u06a9\u200c\u0647\u0627 \u0648 \u0645\u0624\u0633\u0633\u0627\u062a \u0645\u0627\u0644\u06cc \u0628\u0627\u06cc\u062f \u062a\u0642\u0648\u06cc\u062a \u0634\u0648\u062f \u062a\u0627 \u0627\u0632 \u062a\u0635\u0645\u06cc\u0645\u0627\u062a \u0646\u0627\u062f\u0631\u0633\u062a \u0648 \u067e\u0631\u0631\u06cc\u0633\u06a9 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u06af\u0631\u062f\u062f. \u062a\u0646\u0648\u0639 \u062f\u0631 \u062f\u0627\u0631\u0627\u06cc\u06cc\u200c\u0647\u0627 \u0646\u06cc\u0632 \u0645\u06cc\u200c\u062a\u0648\u0627\u0646\u062f \u0627\u0632 \u0631\u06cc\u0633\u06a9\u200c\u0647\u0627\u06cc \u0628\u0627\u0644\u0627 \u062f\u0631 \u0633\u0631\u0645\u0627\u06cc\u0647\u200c\u06af\u0630\u0627\u0631\u06cc\u200c\u0647\u0627 \u0628\u06a9\u0627\u0647\u062f \u0648 \u06a9\u0645\u06a9 \u06a9\u0646\u062f \u062a\u0627 \u062f\u0631 \u0628\u062d\u0631\u0627\u0646\u200c\u0647\u0627\u06cc \u0645\u0634\u0627\u0628\u0647\u060c \u0628\u0627\u0632\u0627\u0631\u0647\u0627 \u0645\u0642\u0627\u0648\u0645\u062a \u0628\u06cc\u0634\u062a\u0631\u06cc \u062f\u0627\u0634\u062a\u0647 \u0628\u0627\u0634\u0646\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8fe83d elementor-widget elementor-widget-image\" data-id=\"c8fe83d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/newwp.aronsos.co\/wp-content\/uploads\/2025\/11\/2008-financial-crisis-2-1024x640.jpg\" class=\"attachment-large size-large wp-image-175168\" alt=\"\u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc 2008\" srcset=\"https:\/\/newwp.aronsos.co\/wp-content\/uploads\/2025\/11\/2008-financial-crisis-2-1024x640.jpg 1024w, https:\/\/newwp.aronsos.co\/wp-content\/uploads\/2025\/11\/2008-financial-crisis-2-300x188.jpg 300w, https:\/\/newwp.aronsos.co\/wp-content\/uploads\/2025\/11\/2008-financial-crisis-2-768x480.jpg 768w, https:\/\/newwp.aronsos.co\/wp-content\/uploads\/2025\/11\/2008-financial-crisis-2-1536x960.jpg 1536w, https:\/\/newwp.aronsos.co\/wp-content\/uploads\/2025\/11\/2008-financial-crisis-2.jpg 1999w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f38bda elementor-widget elementor-widget-text-editor\" data-id=\"0f38bda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<h2><b>\u0646\u062a\u06cc\u062c\u0647\u200c\u06af\u06cc\u0631\u06cc<\/b><\/h2><p><span style=\"font-weight: 400;\">\u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8 \u0628\u0647 \u062f\u0644\u06cc\u0644 \u062a\u0631\u06a9\u06cc\u0628 \u0639\u0648\u0627\u0645\u0644\u06cc \u0647\u0645\u0686\u0648\u0646 \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u067e\u0631\u0631\u06cc\u0633\u06a9\u060c \u0636\u0639\u0641 \u062f\u0631 \u0646\u0638\u0627\u0631\u062a \u0648 \u0633\u06cc\u0627\u0633\u062a\u200c\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc \u0646\u0627\u0645\u0646\u0627\u0633\u0628 \u0628\u0647 \u0648\u0642\u0648\u0639 \u067e\u06cc\u0648\u0633\u062a \u0648 \u062a\u0623\u062b\u06cc\u0631\u0627\u062a \u0622\u0646 \u0628\u0647 \u0633\u0631\u0639\u062a \u0628\u0647 \u0633\u0631\u0627\u0633\u0631 \u062c\u0647\u0627\u0646 \u06af\u0633\u062a\u0631\u0634 \u06cc\u0627\u0641\u062a. \u0627\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646 \u0628\u0627\u0639\u062b \u0627\u06cc\u062c\u0627\u062f \u0631\u06a9\u0648\u062f \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u0639\u0645\u06cc\u0642 \u0634\u062f \u06a9\u0647 \u0628\u0627\u0632\u0627\u0631\u0647\u0627\u06cc \u0645\u0627\u0644\u06cc\u060c \u062a\u0648\u0644\u06cc\u062f \u0648 \u0627\u0634\u062a\u063a\u0627\u0644 \u0631\u0627 \u062a\u062d\u062a \u062a\u0623\u062b\u06cc\u0631 \u0642\u0631\u0627\u0631 \u062f\u0627\u062f. \u0628\u0627 \u0648\u062c\u0648\u062f \u0622\u0633\u06cc\u0628\u200c\u0647\u0627\u06cc \u0634\u062f\u06cc\u062f\u060c \u0627\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646 \u0628\u0647 \u0627\u0635\u0644\u0627\u062d\u0627\u062a \u0645\u0627\u0644\u06cc \u0648 \u062a\u0642\u0648\u06cc\u062a \u0646\u0638\u0627\u0631\u062a\u200c\u0647\u0627 \u0645\u0646\u062c\u0631 \u0634\u062f \u062a\u0627 \u0627\u0632 \u0648\u0642\u0648\u0639 \u0628\u062d\u0631\u0627\u0646\u200c\u0647\u0627\u06cc \u0645\u0634\u0627\u0628\u0647 \u062c\u0644\u0648\u06af\u06cc\u0631\u06cc \u0634\u0648\u062f. \u062f\u0631\u0633\u200c\u0647\u0627\u06cc \u0622\u0645\u0648\u062e\u062a\u0647\u200c \u0634\u062f\u0647 \u0627\u0632 \u0627\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646\u060c \u0636\u0631\u0648\u0631\u062a \u0634\u0641\u0627\u0641\u06cc\u062a \u0628\u06cc\u0634\u062a\u0631\u060c \u0646\u0638\u0627\u0631\u062a \u0642\u0648\u06cc\u200c\u062a\u0631 \u0648 \u0645\u062f\u06cc\u0631\u06cc\u062a \u0628\u0647\u062a\u0631 \u0631\u06cc\u0633\u06a9\u200c\u0647\u0627 \u0631\u0627 \u0628\u0631\u0627\u06cc \u0622\u06cc\u0646\u062f\u0647 \u0627\u0642\u062a\u0635\u0627\u062f \u062c\u0647\u0627\u0646\u06cc \u0628\u0631\u062c\u0633\u062a\u0647 \u06a9\u0631\u062f.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>\u0628\u062d\u0631\u0627\u0646 \u0645\u0627\u0644\u06cc \u06f2\u06f0\u06f0\u06f8 \u06cc\u06a9\u06cc \u0627\u0632 \u0645\u0647\u0645\u200c\u062a\u0631\u06cc\u0646 \u0648 \u067e\u06cc\u0686\u06cc\u062f\u0647\u200c\u062a\u0631\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646\u200c\u0647\u0627\u06cc \u0627\u0642\u062a\u0635\u0627\u062f\u06cc \u062a\u0627\u0631\u06cc\u062e \u0628\u0648\u062f \u06a9\u0647 \u062a\u0623\u062b\u06cc\u0631\u0627\u062a \u0622\u0646 \u062a\u0627 \u0633\u0627\u0644\u200c\u0647\u0627 \u0627\u062d\u0633\u0627\u0633 \u0634\u062f. \u0627\u06cc\u0646 \u0628\u062d\u0631\u0627\u0646 \u0646\u0627\u0634\u06cc \u0627\u0632 \u06cc\u06a9 \u0633\u0631\u06cc \u0627\u0634\u062a\u0628\u0627\u0647\u0627\u062a \u0633\u06cc\u0633\u062a\u0645\u0627\u062a\u06cc\u06a9 \u062f\u0631 \u0628\u0627\u0632\u0627\u0631 \u0645\u0633\u06a9\u0646 \u0622\u0645\u0631\u06cc\u06a9\u0627 \u0628\u0648\u062f. \u0632\u06cc\u0631\u0627\u00a0 \u0648\u0627\u0645\u200c\u0647\u0627\u06cc \u0631\u0647\u0646\u06cc \u067e\u0631\u0631\u06cc\u0633\u06a9 \u0648 \u0627\u0641\u0632\u0627\u06cc\u0634 \u0628\u06cc\u200c\u0631\u0648\u06cc\u0647 \u0642\u06cc\u0645\u062a \u062e\u0627\u0646\u0647\u200c\u0647\u0627\u060c \u062d\u0628\u0627\u0628\u06cc \u0628\u0632\u0631\u06af \u0627\u06cc\u062c\u0627\u062f \u06a9\u0631\u062f\u0646\u062f. \u00a0\u0628\u0627 \u0622\u063a\u0627\u0632 \u0633\u0642\u0648\u0637 \u0642\u06cc\u0645\u062a \u0645\u0633\u06a9\u0646\u060c \u0633\u06cc\u0633\u062a\u0645 \u0645\u0627\u0644\u06cc \u062f\u0631 \u0645\u0639\u0631\u0636 \u0628\u062d\u0631\u0627\u0646\u200c\u0647\u0627\u06cc [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":175155,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[74],"tags":[63,66],"class_list":["post-175154","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forex-articles","tag-forex-market","tag-economic-concepts"],"_links":{"self":[{"href":"https:\/\/newwp.aronsos.co\/fa\/wp-json\/wp\/v2\/posts\/175154","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/newwp.aronsos.co\/fa\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/newwp.aronsos.co\/fa\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/newwp.aronsos.co\/fa\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/newwp.aronsos.co\/fa\/wp-json\/wp\/v2\/comments?post=175154"}],"version-history":[{"count":1,"href":"https:\/\/newwp.aronsos.co\/fa\/wp-json\/wp\/v2\/posts\/175154\/revisions"}],"predecessor-version":[{"id":193416,"href":"https:\/\/newwp.aronsos.co\/fa\/wp-json\/wp\/v2\/posts\/175154\/revisions\/193416"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/newwp.aronsos.co\/fa\/wp-json\/wp\/v2\/media\/175155"}],"wp:attachment":[{"href":"https:\/\/newwp.aronsos.co\/fa\/wp-json\/wp\/v2\/media?parent=175154"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/newwp.aronsos.co\/fa\/wp-json\/wp\/v2\/categories?post=175154"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/newwp.aronsos.co\/fa\/wp-json\/wp\/v2\/tags?post=175154"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}